{"id":100220,"date":"2020-03-06T07:26:10","date_gmt":"2020-03-06T10:26:10","guid":{"rendered":"http:\/\/argentinamunicipal.com.ar\/argentina\/?p=100220"},"modified":"2020-03-06T07:26:10","modified_gmt":"2020-03-06T10:26:10","slug":"una-cientifica-del-conicet-y-su-paso-a-la-gestion-publica","status":"publish","type":"post","link":"http:\/\/argentinamunicipal.com.ar\/argentina\/una-cientifica-del-conicet-y-su-paso-a-la-gestion-publica\/","title":{"rendered":"Una cient\u00edfica del Conicet y su paso a la gesti\u00f3n p\u00fablica"},"content":{"rendered":"<p>En el Ministerio de Seguridad de Naci\u00f3n somos varios quienes llegamos tras solicitar licencia en nuestros trabajos como investigadores del Conicet. Pasar el Rubic\u00f3n, en este caso, es cruzar una l\u00ednea cada vez m\u00e1s difusa entre \u201cacademia\u201d y \u201cgesti\u00f3n p\u00fablica\u201d, sobre todo porque el campo de intervenci\u00f3n y estudio de las fuerzas de seguridad ha crecido desde mediados de los \u201980.<\/p>\n<p>En 2010, cuando se cre\u00f3 este ministerio, muchos de quienes desarrollamos esas investigaciones nos sumamos al mismo. Es decir, la sinergia entre investigaci\u00f3n cient\u00edfica y campo securitario tiene su tradici\u00f3n formal y emp\u00edrica desde hace m\u00e1s de una d\u00e9cada. Si bien en una de sus dimensiones el mundo acad\u00e9mico y el de la gesti\u00f3n son diferentes, cuando un proyecto pol\u00edtico resulta convocante y es af\u00edn a determinado modo de mirar al mundo, ambos espacios quedan disponibles para tender puentes que redunden en la transformaci\u00f3n y mejora de la mirada, as\u00ed como en el dise\u00f1o de pol\u00edticas p\u00fablicas, en este caso, de seguridad.<\/p>\n<p>En los grupos acad\u00e9micos donde trabajo, el conocimiento sobre y con las fuerzas es construido en base a trabajo de campo. Esto significa que quien investiga se interesa por la vida cotidiana de quienes pertenecen a las fuerzas de seguridad. Por eso, observamos pr\u00e1cticas discursivas y extra-discursivas, miramos espacios, analizamos temporalidades e indagamos la construcci\u00f3n de cuerpos, ret\u00f3ricas, instituciones y subjetividades. Producimos saberes hablando con los jefes -m\u00e1s apegados a las reglas de la instituci\u00f3n-, as\u00ed como con los trabajadores de las fuerzas. Se trata de conocer m\u00e1s personas, m\u00e1s espacios, m\u00e1s tiempos y m\u00e1s vivencias.<\/p>\n<p>Ese trabajo de campo se traduce en textos.\u00a0Vamos y volvemos de las notas de campo a la teor\u00eda y de la teor\u00eda a nuestras reflexiones. Ese derrotero, esas traducciones, permiten comprender diferentes l\u00f3gicas de funcionamiento, de disputas y de construcciones de autoridad y subalternidad. En definitiva, posibilitan interpretar y analizar las formas de las instituciones. Ese bagaje nos brinda herramientas valiosas \u2013si no cruciales- para la gesti\u00f3n p\u00fablica. Aporta espesor a nuestros trabajos en y con los miembros de las fuerzas.\u00a0La gesti\u00f3n \u2013atravesada por estos conocimientos- act\u00faa en la urgencia de las respuestas del Estado, as\u00ed como tambi\u00e9n en la planificaci\u00f3n polif\u00f3nica a largo plazo.<\/p>\n<p>La gesti\u00f3n posee ritmos y l\u00f3gicas diferentes a las de la producci\u00f3n cient\u00edfica. Sin embargo, la extrema velocidad, muchas veces da\u00f1a aquello en lo que procura incidir. Del mismo modo, la temporalidad cient\u00edfica, muchas veces, aporta saberes que demoran.<\/p>\n<p>La presunta extranjer\u00eda de los investigadores que apostamos a la gesti\u00f3n p\u00fablica tiene la ventaja de buscar el equilibrio exacto entre ambas l\u00f3gicas (no s\u00f3lo) temporales. Para quienes venimos del campo acad\u00e9mico, el desaf\u00edo inherente a la gesti\u00f3n p\u00fablica constituye un pilar para poder hacer aqu\u00ed y ahora aquello que investigamos desde lejos y desde hace mucho tiempo.<\/p>\n<p>Por\u00a0Karina Mouzo<\/p>\n<h6>Fuente: P\u00e1gina 12<\/h6>\n","protected":false},"excerpt":{"rendered":"<p>En el Ministerio de Seguridad de Naci\u00f3n somos varios quienes llegamos tras solicitar licencia en nuestros trabajos como investigadores del Conicet.<\/p>\n","protected":false},"author":2,"featured_media":100221,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6],"tags":[21],"class_list":["post-100220","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-opiniones","tag-argentina"],"_links":{"self":[{"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/posts\/100220","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/comments?post=100220"}],"version-history":[{"count":0,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/posts\/100220\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/media\/100221"}],"wp:attachment":[{"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/media?parent=100220"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/categories?post=100220"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/tags?post=100220"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}