{"id":100251,"date":"2020-03-09T06:28:06","date_gmt":"2020-03-09T09:28:06","guid":{"rendered":"http:\/\/argentinamunicipal.com.ar\/argentina\/?p=100251"},"modified":"2020-03-09T06:28:06","modified_gmt":"2020-03-09T09:28:06","slug":"el-ejecutivo-de-gualeguaychu-abrira-la-paritaria-pero-con-un-solo-gremio","status":"publish","type":"post","link":"http:\/\/argentinamunicipal.com.ar\/argentina\/el-ejecutivo-de-gualeguaychu-abrira-la-paritaria-pero-con-un-solo-gremio\/","title":{"rendered":"El Ejecutivo de Gualeguaych\u00fa abrir\u00e1 la paritaria pero con un solo gremio"},"content":{"rendered":"<p>Este lunes a las 8.30, el piaggismo cit\u00f3 al Sindicato de Municipales pero excluy\u00f3 de la discusi\u00f3n salarial a la Asociaci\u00f3n de Trabajadores.<\/p>\n<p>En el sal\u00f3n de la Memoria del palacio Municipal se producir\u00e1, desde las 8.30, el primer encuentro de debate paritario entre el Poder Ejecutivo y uno de los gremios que representan a los trabajadores.<\/p>\n<p>Seg\u00fan confirm\u00f3\u00a0R2820, los convocados son los representantes del Sindicato de Trabajadores Municipales de Gualeguaych\u00fa [SITRAMG]pero no se invit\u00f3 al segundo gremio que cuenta con afiliados en la Comuna: la Asociaci\u00f3n de Trabajadores Municipales [ATM].<\/p>\n<p>Si bien existe un \u201ccompromiso p\u00fablico de trabajar temas puntuales en conjunto con la secretar\u00eda de Gobierno, Delfina Herlax, y su equipo como tambi\u00e9n con la Direcci\u00f3n de Personal, eso no se refleja en la paritaria\u201d, puntualiz\u00f3 Nelson Volker, secretario adjunto de ATM.<\/p>\n<p>Ante\u00a0R2820, Volker reafirm\u00f3 que \u201cel director de Personal Renzo Peruzzo posterg\u00f3 indefinidamente y a \u00faltimo momento, la reuni\u00f3n que ten\u00edamos el viernes con Cristian Vera y N\u00e9stor G\u00f3mez, el secretario general y el gremial\u201d.<\/p>\n<p>Consultado sobre el encuentro paritario de este lunes, Nelson Volker, admiti\u00f3 que \u201cno fuimos convocados formalmente\u201d, sin embargo si fue invitado el SITRAMG seg\u00fan le confirm\u00f3 a este medio Horacio Reyes, secretario de Finanzas.<\/p>\n<p>Volker asegur\u00f3 que \u201cATM hace 20 a\u00f1os que tiene presencia en la municipalidad con su respectiva personer\u00eda jur\u00eddica y, desde 2015, cuenta con inscripci\u00f3n gremial para representar a los trabajadores en las asambleas. Entonces, cuando era candidato, Mart\u00edn Piaggio estuvo cuatro veces con nosotros y estaba de acuerdo con los planteos de libertad sindical. Sin embargo, cuando fue electo nunca m\u00e1s nos llam\u00f3 para ser parte de la mesa de discusi\u00f3n paritaria y cuando solicitamos por nota nuestra concurrencia nunca fue respondida\u201d.<\/p>\n<p>\u201cGualeguaych\u00fa es un lugar especial en la provincia. Somos el \u00fanico municipio con un unicato, no se nos permite participar de las discusiones que van m\u00e1s all\u00e1 de lo salarial sino m\u00e1s bien a temas cotidianos y derechos de los agentes\u201d.<\/p>\n<p>El secretario adjunto de la Asociaci\u00f3n de Trabajadores Municipales anticip\u00f3 que se reunir\u00e1n el mi\u00e9rcoles 11 a las 19, en Asamblea, en la sede de Clavarino 852, casi Segu\u00ed. \u201cInvitamos a los afiliados o no afiliados a debatir la propuesta de porcentaje de aumento y definir los dos representantes paritarios\u201d. Si bien el n\u00famero de pedido como aumento al Poder Ejecutivo saldr\u00e1 por consenso, Volker anticip\u00f3 que \u201cno alcanzamos la inflaci\u00f3n del a\u00f1o pasado con los aumentos, o sea que la intensi\u00f3n es no perder poder adquisitivo\u201d.CARTA ORG\u00c1NICA<br \/>\nNelson Volker asegur\u00f3 que se est\u00e1 trabajando tambi\u00e9n de cara a la futura Carta Org\u00e1nica para incorporar la \u201cposibilidad de democratizar la participaci\u00f3n gremial. Es una oportunidad hist\u00f3rica y apoyamos la Carta Org\u00e1nica desde un primer momento\u201d.<\/p>\n<p>\u201cLa representaci\u00f3n gremial \u00fanica en el Municipio de Gualeguaych\u00fa es un tema que tiene que reverse y considero que es una cuesti\u00f3n importante a incluir. Estamos dispuestos a llevar adelante este debate junto con toda la comunidad\u201d, reafirm\u00f3 en di\u00e1logo con\u00a0R2820.<\/p>\n<h6>Fuente: r2820.com<\/h6>\n","protected":false},"excerpt":{"rendered":"<p>Este lunes a las 8.30, el piaggismo cit\u00f3 al Sindicato de Municipales pero excluy\u00f3 de la discusi\u00f3n salarial a la Asociaci\u00f3n de Trabajadores.<\/p>\n","protected":false},"author":2,"featured_media":100252,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[17],"class_list":["post-100251","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-informe-sindical","tag-entre-rios"],"_links":{"self":[{"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/posts\/100251","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/comments?post=100251"}],"version-history":[{"count":0,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/posts\/100251\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/media\/100252"}],"wp:attachment":[{"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/media?parent=100251"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/categories?post=100251"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/tags?post=100251"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}