{"id":100326,"date":"2020-03-10T07:02:22","date_gmt":"2020-03-10T10:02:22","guid":{"rendered":"http:\/\/argentinamunicipal.com.ar\/argentina\/?p=100326"},"modified":"2020-03-10T07:02:22","modified_gmt":"2020-03-10T10:02:22","slug":"mas-mujeres-en-los-cargos-jerarquicos-del-gobierno-nacional","status":"publish","type":"post","link":"http:\/\/argentinamunicipal.com.ar\/argentina\/mas-mujeres-en-los-cargos-jerarquicos-del-gobierno-nacional\/","title":{"rendered":"M\u00e1s mujeres en los cargos jer\u00e1rquicos del gobierno nacional"},"content":{"rendered":"<p>Un relevamiento del Centro Atenea muestra c\u00f3mo mejor\u00f3 la participaci\u00f3n femenina en los ministerios con el cambio de gobierno. Las carteras con m\u00e1s y con menos mujeres en espacios de decisi\u00f3n. Lo que falta para lograr la paridad.<br \/>\nPor\u00a0Luc\u00eda Beatriz Blotta Cavalli e Ileana Bel\u00e9n Fern\u00e1ndez Escobar<\/p>\n<p>El marco del 8M nos invita a reflexionar acerca de los l\u00edmites que el \u201ctecho de cristal\u201d ejerce a la participaci\u00f3n pol\u00edtica femenina, y c\u00f3mo se manifiesta en n\u00fameros cuando hablamos de acceso a los lugares jer\u00e1rquicos de toma de decisi\u00f3n y poder en el espacio p\u00fablico de las mujeres. El \u201ctecho de cristal\u201d es una construcci\u00f3n sociocultural que est\u00e1 invisibilizada, raz\u00f3n por la que se le dice de cristal, y ejerce fuerte presi\u00f3n sobre las trayectorias laborales de las mujeres.<\/p>\n<p>El movimiento Ni Una Menos surgi\u00f3 en Argentina en junio de 2015 y puso en primera plana de la agenda medi\u00e1tica los reclamos contra la violencia machista en los distintos \u00e1mbitos de la sociedad, evidenciando las desigualdades de g\u00e9nero tambi\u00e9n existentes en la arena pol\u00edtica.<\/p>\n<p>\u00bfC\u00f3mo canalizar las demandas del colectivo feminista si las mujeres son apartadas de los lugares en donde se toman las decisiones?<\/p>\n<p>El feminismo recogi\u00f3 sus frutos, a nivel institucional, en las leyes de Paridad. \u00c9stas se sancionaron en varias provincias y a nivel nacional, generando mayores y mejores mecanismos de inclusi\u00f3n y participaci\u00f3n pol\u00edtica. Sin embargo, en el Poder Ejecutivo no existe un mecanismo similar que invite a los dirigentes a compartir esos espacios con las dirigentas del g\u00e9nero femenino, lo que presenta carteras en donde no hay ni una sola mujer en el organigrama. Tal es el caso del Ministerio de Transporte, el Ministerio de Trabajo, Empleo y Seguridad Social, y el Ministerio de Obras P\u00fablicas.<\/p>\n<p>Un informe del Centro de Estudios Atenea realizado a partir de la publicaci\u00f3n del Mapa del Estado a nivel nacional nos revela que\u00a0de 2019 a 2020, con el cambio de la gesti\u00f3n de Maurio Macri (Cambiemos) a la de Alberto Fern\u00e1ndez (Frente de Todos), se ha ampliado la presencia de mujeres en los lugares de poder. Como ilustra el cuadro, en el 2019 no se llegaba al 30 por ciento de participaci\u00f3n femenina en ninguno de los tres niveles jer\u00e1rquicos relevados: ministros 18 por ciento, secretar\u00edas ministeriales 23 por ciento y subsecretar\u00edas ministeriales 20 por ciento. En cambio, esos n\u00fameros tienden a crecer hacia el 2020, donde encontramos que las mujeres ocupan el 39 por ciento de las secretar\u00edas ministeriales, el 37 por ciento de las subsecretar\u00edas y el 19 por ciento de los ministerios.<\/p>\n<p>Cuando analizamos el comparativo ministerio por ministerio, encontramos que en el 2020,\u00a0tanto el Ministerio de Cultura como el Ministerio de Turismo y Deportes cumplen con el ideal de una participaci\u00f3n pol\u00edtica equitativa de g\u00e9nero. Tambi\u00e9n este a\u00f1o hay algunas carteras que superan el 50 por ciento. Por ejemplo,\u00a0el Ministerio de Seguridad encabezado por Sabina Andrea Frederic hoy muestra un 62 por ciento de mujeres, cuando en 2019 con Patricia Bullrich s\u00f3lo presentaba el 17 por ciento. A su vez,\u00a0el Ministerio de Desarrollo Territorial y H\u00e1bitat, cuya ministra es Mar\u00eda Eugenia Bielsa, hoy cuenta con un 57 por ciento de sus cargos jer\u00e1rquicos ejercidos por mujeres. Mientras que en el 2019 esta funci\u00f3n estaba dentro del Ministerio del Interior, Obras P\u00fablicas y Vivienda, solo el 8 por ciento era presencia femenina. Por \u00faltimo, el Ministerio de Educaci\u00f3n, comandado por Nicol\u00e1s Trotta en la actualidad llega al 54 por ciento, y en el 2019 el Ministerio de Educaci\u00f3n, Cultura, Ciencia y Tecnolog\u00eda s\u00f3lo era del 18 por ciento.<\/p>\n<p>Los l\u00edmites a la representaci\u00f3n paritaria al interior de los ministerios, se encuentran en el hecho de que la representaci\u00f3n femenina se acrecienta en tem\u00e1ticas que se vinculan a las pol\u00edticas de cuidado reproduciendo los estereotipos de g\u00e9nero, y disminuye en reparticiones cuyas tem\u00e1ticas se vinculan a lo econ\u00f3mico y productivo.<\/p>\n<p>El techo de cristal que impide el acceso de las mujeres a los lugares de toma de decisi\u00f3n, se hace a\u00fan m\u00e1s evidente cuando vemos la formaci\u00f3n acad\u00e9mica de aquellos que cumplen funciones en el Estado. Las mujeres que no tienen certificaci\u00f3n acad\u00e9mica son menos del 8 por ciento, cuando los hombres en la misma condici\u00f3n casi duplican ese n\u00famero. La brecha se achica a medida que subimos en el nivel de formaci\u00f3n, aproximadamente el 60 por ciento de las mujeres que acceden tienen t\u00edtulo de grado, cuando en los varones es el 50 por ciento, y por \u00faltimo, con posgrados ambos g\u00e9neros se encuentran alrededor del 33 por ciento.<\/p>\n<p>Es v\u00e1lido destacar tambi\u00e9n que el aumento de la participaci\u00f3n de las mujeres en los espacios de toma de decisi\u00f3n a nivel nacional se hizo efectivo en organismos descentralizados de la Administraci\u00f3n P\u00fablica de suma trascendencia, tanto en la definici\u00f3n de ejes de desarrollo como la construcci\u00f3n de pol\u00edticas p\u00fablicas de nuestro pa\u00eds.\u00a0Actualmente, las m\u00e1ximas autoridades del Conicet, AFIP, PAMI, INTA y AySA son mujeres. En \u00e9stas dos \u00faltimas instituciones es la primera vez en la historia que una mujer se encuentra al frente.<\/p>\n<p>Asimismo, el Inadi y el recientemente creado Instituto Nacional de la Juventud son liderados por mujeres cuya presencia propiciar\u00e1 la ampliaci\u00f3n, reconocimiento y ejercicio de derechos de las mujeres y diversidades en los \u00e1mbitos de desarrollo personal y laboral.<\/p>\n<p>Por \u00faltimo, es preciso destacar la creaci\u00f3n del Ministerio de las Mujeres, G\u00e9neros y Diversidad de la Naci\u00f3n. La jerarquizaci\u00f3n de la tem\u00e1tica en la agenda nacional tiene su correlato en los niveles provinciales y municipales, en los cuales se crearon \u00e1reas espec\u00edficas que trabajar\u00e1n articuladamente en la sensibilizaci\u00f3n y visibilizaci\u00f3n de las desigualdades sexo-gen\u00e9ricas, as\u00ed como tambi\u00e9n en la creaci\u00f3n e implementaci\u00f3n de pol\u00edticas p\u00fablicas trasversales con perspectiva de g\u00e9nero. La creaci\u00f3n de las \u00e1reas tiene como principales objetivos la ampliaci\u00f3n de derechos, propiciar mayor participaci\u00f3n de las mujeres en las espacios de toma de decisi\u00f3n, la visibilizaci\u00f3n del trabajo no remunerado y remunerado de las mujeres y las diversidades, considerando el abordaje integral que necesitan las tareas de cuidado.<\/p>\n<p>La ampliaci\u00f3n de derechos en general y de participaci\u00f3n pol\u00edtica en particular de las mujeres y diversidades es una responsabilidad que debe asumirse desde el Estado y trabajar de manera articulada con las instituciones de la sociedad civil para poder hacerla efectiva.<\/p>\n<p>Somos conscientes de que se ha logrado un aumento en la participaci\u00f3n de las mujeres en espacios de toma de decisi\u00f3n. Tambi\u00e9n de que la normativa vigente ha propiciado mayor igualdad pero queda mucho por hacer para lograr real paridad de los g\u00e9neros en los lugares donde se piensa, crea y busca construir un pa\u00eds que incluya todas las personas.<\/p>\n<p>*\u00a0Luc\u00eda Beatriz Blotta Cavalli e Ileana Bel\u00e9n Fern\u00e1ndez Escobar son polit\u00f3logas e investigadoras del Centro de Estudios para el Desarrollo Nacional Atenea.<\/p>\n<h6>Fuente: P\u00e1gina 12<\/h6>\n","protected":false},"excerpt":{"rendered":"<p>Un relevamiento del Centro Atenea muestra c\u00f3mo mejor\u00f3 la participaci\u00f3n femenina en los ministerios con el cambio de gobierno. Las carteras con m\u00e1s y con menos mujeres en espacios de decisi\u00f3n. Lo que falta para lograr la paridad.<\/p>\n","protected":false},"author":2,"featured_media":100327,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[8],"tags":[21],"class_list":["post-100326","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-informe-nacional","tag-argentina"],"_links":{"self":[{"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/posts\/100326","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/comments?post=100326"}],"version-history":[{"count":0,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/posts\/100326\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/media\/100327"}],"wp:attachment":[{"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/media?parent=100326"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/categories?post=100326"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/tags?post=100326"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}