{"id":100391,"date":"2020-03-11T07:45:41","date_gmt":"2020-03-11T10:45:41","guid":{"rendered":"http:\/\/argentinamunicipal.com.ar\/argentina\/?p=100391"},"modified":"2020-03-11T07:45:41","modified_gmt":"2020-03-11T10:45:41","slug":"marchas-barricadas-y-fogatas-contra-pinera","status":"publish","type":"post","link":"http:\/\/argentinamunicipal.com.ar\/argentina\/marchas-barricadas-y-fogatas-contra-pinera\/","title":{"rendered":"Marchas, barricadas y fogatas contra Pi\u00f1era"},"content":{"rendered":"<p>Este 11 de marzo se cumplen dos a\u00f1os desde que asumi\u00f3 la presidencia Sebasti\u00e1n Pi\u00f1era y las protestas se acentuar\u00e1n en la calle. Marchas, actos, barricadas y fogatas volver\u00e1n a darle a esta capital una din\u00e1mica que no ha perdido desde octubre pasado. En ese marco se desarrollar\u00e1 un paro de 11 minutos, a las 11 de la ma\u00f1ana y que para este d\u00eda 11 convocaron el Bloque Sindical de la Mesa de Unidad Social y la CUT (Central Unitaria de Trabajadores). Los sectores m\u00e1s combativos que siguen movilizados por todo el pa\u00eds cuestionan esta medida testimonial. La tildaron de \u201cvergonzosa\u201d.<\/p>\n<p>Los gremialistas llamaron a la \u201cparalizaci\u00f3n de actividades laborales, escolares y de transporte; acompa\u00f1adas de bocinazos y todo tipo de ruido\u201d bajo la consigna: \u201c\u00a1que el Poder escuche la protesta!\u201d. Para este sector que no ha tenido una presencia activa en las movilizaciones que se producen desde octubre, la jornada se cerrar\u00e1 con un cacerolazo nacional a las 20.30.<\/p>\n<p>El Bloque Sindical difundi\u00f3 un documento donde dice que \u201clas chilenas y chilenos claman por una sociedad diferente que recupere las libertades y derechos fundamentales, que son los que le hacen sentido a la mujer y al hombre sencillo de nuestro pueblo que aspiran a una vida buena, justa y acogedora\u201d. Lo que pase estar\u00e1 m\u00e1s determinado por lo ocurra en la calle antes que en los despachos de los dirigentes gremiales. Es as\u00ed hace cinco meses.<\/p>\n<h6>Fuente: P\u00e1gina 12<\/h6>\n","protected":false},"excerpt":{"rendered":"<p>Este 11 de marzo se cumplen dos a\u00f1os desde que asumi\u00f3 la presidencia Sebasti\u00e1n Pi\u00f1era y las protestas se acentuar\u00e1n en la calle.<\/p>\n","protected":false},"author":2,"featured_media":100392,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[22],"tags":[57],"class_list":["post-100391","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-el-mundo","tag-el-mundo"],"_links":{"self":[{"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/posts\/100391","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/comments?post=100391"}],"version-history":[{"count":0,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/posts\/100391\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/media\/100392"}],"wp:attachment":[{"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/media?parent=100391"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/categories?post=100391"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/tags?post=100391"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}