{"id":100663,"date":"2020-03-25T06:06:54","date_gmt":"2020-03-25T09:06:54","guid":{"rendered":"http:\/\/argentinamunicipal.com.ar\/argentina\/?p=100663"},"modified":"2020-03-25T15:13:53","modified_gmt":"2020-03-25T18:13:53","slug":"santa-fe-asoma-el-consenso-entre-oficialismo-y-oposicion-por-la-ley-de-necesidad-publica","status":"publish","type":"post","link":"http:\/\/argentinamunicipal.com.ar\/argentina\/santa-fe-asoma-el-consenso-entre-oficialismo-y-oposicion-por-la-ley-de-necesidad-publica\/","title":{"rendered":"Santa Fe: Asoma el consenso entre oficialismo y oposici\u00f3n por la ley de necesidad p\u00fablica"},"content":{"rendered":"<p>El gobernador Perotti se reuni\u00f3 con diputados y senadores. Todo indica que hoy habr\u00e1 sesi\u00f3n en Diputados y aprobar\u00e1n las leyes de emergencia.<\/p>\n<p>\u00abSeguimos conversando, estamos cerca de lograr un consenso y esperamos darle un corte ma\u00f1ana (por hoy) en las dos C\u00e1maras legislativas\u00bb. El que habla con moderado pero a la vez marcado optimismo es el ministro de Econom\u00eda de la provincia Walter Agosto y se refiere al proyecto de ley de necesidad p\u00fablica que cuenta con media sanci\u00f3n del Senado y hoy ser\u00e1 tratado en la sesi\u00f3n especial convocada por Miguel Lifschitz en la C\u00e1mara baja santafesina.<\/p>\n<p>Mientras el titular de Hacienda se sinceraba ante LaCapital, adentro del Sal\u00f3n Blanco de la Casa de Gobierno en Santa Fe, ya entrada la noche y al cierre de esta edici\u00f3n, la reuni\u00f3n presidida por el gobernador Omar Perotti con los titulares del Senado, Alejandra Rodenas, de Diputados el propio Lifschitz y los jefes de bloque ya llevaba consumidas casi tres horas.<\/p>\n<p>\u00abEl gobernador hizo un crudo diagn\u00f3stico del estado de situaci\u00f3n de la provincia derivada de la emergencia sanitaria, hubo intercambios de opiniones, consultas, todo en un marco muy riguroso pero distendido\u00bb, desliz\u00f3 por Watsapp uno de los participantes del c\u00f3nclave que se inici\u00f3 minutos despu\u00e9s de las 18 bajo estrictas medidas profil\u00e1cticas que incluyeron hasta la toma del estado febril de los conspicuos participantes.<\/p>\n<p>Desde el mandatario provincial para abajo todos debieron atravesar un celoso cedazo sanitario que incluy\u00f3 hasta la desinfecci\u00f3n de zapatos e indumentaria con un rociador de alcohol l\u00edquido.<\/p>\n<p>\u00abMe la tengo que tomar de nuevo\u00bb, interrog\u00f3 en tono jocoso el gobernador cuando una de las asistentes ataviada con mamelucos blancos y barbijos le acerc\u00f3 a Perotti el term\u00f3metro digital a la frente, dando a entender el propio mandatario que se controla la temperatura varias veces al d\u00eda durante sus intensas rutinas en la Casa Gris y recorridas para supervisar personalmente el desarrollo de la cuarentena en la bota.<\/p>\n<p>Adentro ya lo aguardaban a Perotti, que ingres\u00f3 acompa\u00f1ado por Rodenas y el ministro de Salud Carlos Parola senadores y diputados de todo el abanico legislativo. Al primero que salud\u00f3, con el caracter\u00edstico roce de codos que instaur\u00f3 la pandemia, fue a su antecesor Miguel Lifschitz.<\/p>\n<p>Se trat\u00f3 de un postergado reencuentro de las dos m\u00e1ximas figuras pol\u00edticas santafesinas luego de un semestre de tensas pulseadas pol\u00edticas, s\u00f3lo mitigadas por intercambios de mensajes y llamadas telef\u00f3nicas en los \u00faltimos d\u00edas, cuando el Coronavirus mut\u00f3 la realidad pol\u00edtica impensadamente y sin dar aviso.<\/p>\n<p>En el oficialismo conf\u00edan que el c\u00f3nclave desarrollado anoche sea el preludio de una jornada legislativa en la cual hoy pueda darse ese \u00abcorte definitivo\u00bb al que se refiri\u00f3 el ministro de Hacienda respecto a una eventual sanci\u00f3n definitiva de la ley de necesidad p\u00fablica que, antes bajo el formato de las nonatas leyes de emergencia, la Casa Gris viene demandando antes de la irrupci\u00f3n del Coronavirus para manejar las finanzas provinciales.<\/p>\n<p>\u00abCreemos que podemos acercar posiciones entre el proyecto que aprob\u00f3 el Senado y el dictamen de minor\u00eda que suscribieron los legisladores del Frente, y de esa manera pueda ser votada ma\u00f1ana (por hoy) en ambas C\u00e1maras\u00bb, repet\u00edan esperanzados como una letan\u00eda los habitantes de la Casa Gris. Afuera se consum\u00eda la noche en una capital santafesina que ofrec\u00eda un panorama desolador en las calles adyacentes a la Plaza de Mayo que s\u00f3lo reflejaban las luces encendidas del Sal\u00f3n Blanco.<\/p>\n<h6>Fuente: La Capital<\/h6>\n","protected":false},"excerpt":{"rendered":"<p>El gobernador Perotti se reuni\u00f3 con diputados y senadores. Todo indica que hoy habr\u00e1 sesi\u00f3n en Diputados y aprobar\u00e1n las leyes de emergencia.<\/p>\n","protected":false},"author":2,"featured_media":100664,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"tags":[10],"class_list":["post-100663","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-informe-politico","tag-santa-fe"],"_links":{"self":[{"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/posts\/100663","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/comments?post=100663"}],"version-history":[{"count":0,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/posts\/100663\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/media\/100664"}],"wp:attachment":[{"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/media?parent=100663"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/categories?post=100663"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/tags?post=100663"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}