{"id":100725,"date":"2020-03-26T08:08:32","date_gmt":"2020-03-26T11:08:32","guid":{"rendered":"http:\/\/argentinamunicipal.com.ar\/argentina\/?p=100725"},"modified":"2020-03-26T08:08:32","modified_gmt":"2020-03-26T11:08:32","slug":"hay-13-municipios-de-mendoza-que-adelantaron-el-pago-de-sueldos","status":"publish","type":"post","link":"http:\/\/argentinamunicipal.com.ar\/argentina\/hay-13-municipios-de-mendoza-que-adelantaron-el-pago-de-sueldos\/","title":{"rendered":"Hay 13 municipios de Mendoza que adelantaron el pago de sueldos"},"content":{"rendered":"<p>Casi todas las que depositan el \u00faltimo d\u00eda h\u00e1bil del mes lo har\u00e1n ma\u00f1ana. Debieron modificar el esquema luego del cambio en los feriados.<\/p>\n<p>El decreto 297\/2020, que lleva la firma del presidente Alberto Fern\u00e1ndez, establece las normativas que deben acatarse durante el per\u00edodo de cuarentena total. Una de las decisiones oblig\u00f3 a diagramar nuevamente el calendario de feriados para que el 2 de abril, cuando se homenajea a los Veteranos y Ca\u00eddos en la Guerra de las Malvinas, se adelante dos d\u00edas y pase al martes 31 de marzo; adem\u00e1s, fija que el lunes 30 ser\u00e1 feriado puente.<\/p>\n<p>Con este nuevo almanaque, el \u00faltimo d\u00eda h\u00e1bil de marzo ser\u00e1 entonces el viernes 27, cuatro d\u00edas antes del original 31.\u00a0Ante este escenario, la reingenier\u00eda financiera de las municipalidades pis\u00f3 el acelerador para adelantar los dep\u00f3sitos de haberes para empleados y empleadassu personal.<\/p>\n<p>El Gobierno provincial, por su parte, inform\u00f3 que mantendr\u00e1 el pr\u00f3ximo martes 31 como el d\u00eda en el que estar\u00e1n depositados los sueldos de los estatales correspondientes al mes de marzo.<\/p>\n<p>Ante la consulta de Los Andes a los 18 municipios de la provincia, la respuesta mayoritaria fue que los sueldos estar\u00e1n depositados a m\u00e1s tardar ma\u00f1ana.\u00a0S\u00f3lo la Ciudad de Mendoza, General Alvear y San Rafael confirmaron que ser\u00e1 el 31. Desde Tunuy\u00e1n no respondieron al pedido de este medio y Guaymall\u00e9n no dio detalles de cu\u00e1ndo estar\u00e1n disponibles los haberes. Ser\u00e1n depositados \u201coportunamente\u201d, indicaron.<\/p>\n<p>Quienes sacaron algunas horas de ventaja al resto fueron los municipios de San Carlos y Lavalle. En el Valle de Uco las cuentas tienen fondos desde el s\u00e1bado 21 de marzo, seg\u00fan confirm\u00f3 el intendente Rolando Scanio. Mientras que Roberto Righi asegur\u00f3 que el dinero ingres\u00f3 a las entidades bancarias en donde \u201cqui\u00e9nes cobran por el Banco Credicoop desde hoy -por ayer- ya cuentan con el dinero y los que cobran por el Naci\u00f3n, lo tendr\u00e1n entre ma\u00f1ana y pasado \u2013hoy o ma\u00f1ana-\u201c.<\/p>\n<p>En el Gran Mendoza los dep\u00f3sitos estar\u00e1n disponibles, al menos para la mayor\u00eda de las plantillas de personal municipal, a m\u00e1s tardar el \u00faltimo d\u00eda h\u00e1bil de marzo. Godoy Cruz y Las Heras abonan unos d\u00edas antes de fin de mes. Por lo tanto, los sueldos se pagar\u00e1n a m\u00e1s tardar ma\u00f1ana, pero es posible que hoy ya se vean los ingresos mensuales, dependiendo de la entidad bancaria por la que se reciba la remuneraci\u00f3n.<\/p>\n<p>En Maip\u00fa y Luj\u00e1n de Cuyo se cobra el \u00faltimo d\u00eda h\u00e1bil del mes y para esta ocasi\u00f3n confirmaron que ma\u00f1ana estar\u00e1n los haberes disponibles para el retiro a trav\u00e9s de cajeros autom\u00e1ticos. La Ciudad de Mendoza lo har\u00e1 el martes 31, al igual que la Provincia. Guaymall\u00e9n, por su parte, asegur\u00f3 que \u201clos sueldos se depositar\u00e1n en tiempo y forma\u201d, pero no dieron detalles sobre la fecha.<\/p>\n<p>En el Este provincial, tambi\u00e9n habr\u00e1 adelanto de pagos. Jun\u00edn, al igual que la comuna godoicruce\u00f1a y la lasherina tambi\u00e9n deposita con anticipaci\u00f3n, por lo que hoy estar\u00e1n los haberes en las cuentas bancarias. Desde La Paz est\u00e1n esperando la confirmaci\u00f3n del Banco Naci\u00f3n para que los sueldos se acrediten hoy.\u00a0\u201cSiempre se deposita un d\u00eda antes que la Provincia para que no se abarroten los cajeros\u201d,\u00a0indicaron.<\/p>\n<p>En San Mart\u00edn recibir\u00e1n las remuneraciones ma\u00f1ana, al igual que en Rivadavia. Santa Rosa har\u00e1 lo propio para que el s\u00e1bado haya dinero para su planta de personal.<\/p>\n<p>Volviendo al Valle de Uco, en Tupungato\u00a0\u201cest\u00e1n trabajando para pagar los sueldos el viernes\u201d dado que en esa comuna tambi\u00e9n se cobra el \u00faltimo d\u00eda h\u00e1bil de cada mes.\u00a0Tunuy\u00e1n por su parte, no respondi\u00f3 a la consulta de este medio.<\/p>\n<p>En el Sur provincial, el \u00fanico que adelant\u00f3 los pagos fue el municipio de Malarg\u00fce para ma\u00f1ana. Tanto General Alvear como San Rafael har\u00e1n efectivos sus dep\u00f3sitos para que los sueldos est\u00e9n a disposici\u00f3n de sus empleados y empleadas el martes pr\u00f3ximo.<\/p>\n<h6>Fuente: Los Andes<\/h6>\n","protected":false},"excerpt":{"rendered":"<p>Casi todas las que depositan el \u00faltimo d\u00eda h\u00e1bil del mes lo har\u00e1n ma\u00f1ana. Debieron modificar el esquema luego del cambio en los feriados.<\/p>\n","protected":false},"author":2,"featured_media":100726,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5],"tags":[31],"class_list":["post-100725","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-informe-economico","tag-mendoza"],"_links":{"self":[{"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/posts\/100725","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/comments?post=100725"}],"version-history":[{"count":0,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/posts\/100725\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/media\/100726"}],"wp:attachment":[{"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/media?parent=100725"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/categories?post=100725"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/tags?post=100725"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}