{"id":100793,"date":"2020-03-27T05:54:04","date_gmt":"2020-03-27T08:54:04","guid":{"rendered":"http:\/\/argentinamunicipal.com.ar\/argentina\/?p=100793"},"modified":"2020-03-27T08:03:59","modified_gmt":"2020-03-27T11:03:59","slug":"medidas-para-los-sectores-mas-golpeados-en-san-juan","status":"publish","type":"post","link":"http:\/\/argentinamunicipal.com.ar\/argentina\/medidas-para-los-sectores-mas-golpeados-en-san-juan\/","title":{"rendered":"Medidas para los sectores m\u00e1s golpeados en San Juan"},"content":{"rendered":"<p>El gobernador de San Juan, Sergio U\u00f1ac, anunci\u00f3 un paquete de medidas econ\u00f3micas y sociales destinadas a contener la situaci\u00f3n de los sectores m\u00e1s vulnerables ante la pandemia. El mandatario anunci\u00f3 una asistencia alimentaria de emergencia, la descentralizaci\u00f3n del control de precios en los gobiernos municipales y rebajas impositivas para peque\u00f1as y medianas empresas.<\/p>\n<p>U\u00f1ac destac\u00f3 que, por el momento, no hay casos positivos de coronavirus en San Juan. \u00abLos efectos de esta pandemia son sanitarios en primer t\u00e9rmino pero no podemos soslayar los efectos que va a generar la paralizaci\u00f3n econ\u00f3mica que est\u00e1n teniendo el mundo, el pa\u00eds y tambi\u00e9n la provincia de San Juan\u00bb, indic\u00f3.<\/p>\n<p>El gobernador anunci\u00f3 \u00abla implementaci\u00f3n de la asistencia alimentaria de emergencia para todos los sectores que est\u00e1n sufriendo esta crisis, que no solamente son quienes no ten\u00edan trabajo al momento de la declaraci\u00f3n de la pandemia, sino tambi\u00e9n aquellos que aun teniendo trabajo y producto de la paralizaci\u00f3n econ\u00f3mica est\u00e1n empezando a tener problemas de subsistencia a la fecha\u201d. A\u00f1adi\u00f3 que se est\u00e1n entregando \u201cm\u00f3dulos alimentarios que incluyen kits sanitarios. Hemos articulado la compra de 200 mil kits que ser\u00e1n adicionados a la entrega de los m\u00f3dulos alimentarios\u201d.<\/p>\n<p>Adem\u00e1s, cont\u00f3 que se est\u00e1 trabajando en la descentralizaci\u00f3n en el control de precios que llevar\u00e1n a cabo los gobiernos municipales y el lanzamiento de una canasta b\u00e1sica que estar\u00e1 disponible en comercios locales. E indic\u00f3 que est\u00e1 vigente una l\u00ednea de financiamiento del Banco de San Juan para alimentos, indumentaria y materiales de construcci\u00f3n.<\/p>\n<p>Por otra parte, se\u00f1al\u00f3 que habr\u00e1 medidas para peque\u00f1as empresas:\u00a0 \u201cHemos trabajado en la rebaja al 50 por ciento del monto que pagan los contribuyentes incluidos en las categor\u00edas A y B del monotributo teniendo en cuenta el R\u00e9gimen Simplificado Provincial. En cuanto a l\u00edneas para capital de trabajo, anunciamos 500 millones de pesos para descuento de cheques, para que el sector empresario pueda seguir con el trabajo normal y habitual, teniendo en cuenta la disminuci\u00f3n de las actividades\u00bb, precis\u00f3.<\/p>\n<p>Sobre el sector publico, U\u00f1ac se\u00f1al\u00f3:\u00a0 \u201cHay tres iniciativas que podemos mencionar: la entrega de 25 millones de pesos del Fondo de Emergencia Municipal para los 19 departamentos en los porcentajes estipulados en la Coparticipaci\u00f3n Municipal; la reasignaci\u00f3n de partidas que por un monto global de 4 mil millones de pesos vamos a ir liberando en la medida en que vayamos necesit\u00e1ndolo; y tambi\u00e9n un aporte del CFI por 25 millones de pesos para San Juan en t\u00e9rminos generales para de alguna manera contener los embates del Covid-19 que desde lo sanitario y lo econ\u00f3mico afectan a la provincia\u201d.<\/p>\n<h6>Fuente: P\u00e1gina 12<\/h6>\n","protected":false},"excerpt":{"rendered":"<p>El gobernador de San Juan, Sergio U\u00f1ac, anunci\u00f3 un paquete de medidas econ\u00f3micas y sociales destinadas a contener la situaci\u00f3n de los sectores m\u00e1s vulnerables ante la pandemia.<\/p>\n","protected":false},"author":2,"featured_media":100794,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[65],"tags":[32],"class_list":["post-100793","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-provincias","tag-san-juan"],"_links":{"self":[{"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/posts\/100793","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/comments?post=100793"}],"version-history":[{"count":0,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/posts\/100793\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/media\/100794"}],"wp:attachment":[{"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/media?parent=100793"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/categories?post=100793"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/tags?post=100793"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}