{"id":100875,"date":"2020-03-30T07:48:00","date_gmt":"2020-03-30T10:48:00","guid":{"rendered":"http:\/\/argentinamunicipal.com.ar\/argentina\/?p=100875"},"modified":"2020-03-31T07:51:19","modified_gmt":"2020-03-31T10:51:19","slug":"el-ministro-de-salud-chileno-descarto-la-cuarentena-general-en-el-pais","status":"publish","type":"post","link":"http:\/\/argentinamunicipal.com.ar\/argentina\/el-ministro-de-salud-chileno-descarto-la-cuarentena-general-en-el-pais\/","title":{"rendered":"El ministro de salud chileno descart\u00f3 la cuarentena general en el pa\u00eds"},"content":{"rendered":"<p>La criticada gesti\u00f3n de la emergencia sanitaria encabezada por el ministro de Salud chileno, Jaime Ma\u00f1alich, sum\u00f3 un nuevo cap\u00edtulo luego de que \u00e9ste descartara la posibilidad de establecer una cuarentena general en el pa\u00eds. Luego de informar las nuevas cifras referentes al coronavirus en Chile (ocho muertos, 2449 contagios), Ma\u00f1alich dijo que ve \u00abpr\u00e1cticamente imposible\u00bb que en Chile se aplique la medida, ya que fracas\u00f3 en pa\u00edses como Italia y Argentina.<\/p>\n<p>Ma\u00f1alich expres\u00f3 que la cuarentena \u00abest\u00e1 fracasando abiertamente\u00bb en otros pa\u00edses. El titular de la cartera de Salud puso como ejemplo \u00abel sur de Italia, donde ya hay llamados muy fuertes a no seguir respetando estas medidas de aislamiento, porque las cuarentenas totales generan un efecto adverso muy importante, y es que la gente no puede comer\u00bb.<\/p>\n<p>Ma\u00f1alich cit\u00f3 adem\u00e1s el caso de Argentina, \u00abdonde se ha decretado una medida de este tipo, est\u00e1 ocurriendo exactamente lo mismo, y el respeto a la cuarentena total es bastante bajo\u00bb. Sin embargo, el propio presidente Alberto Fern\u00e1ndez remarc\u00f3 que el \u00abaislamiento social\u00bb tiene un acatamiento del 90 por ciento en todo el pa\u00eds.<\/p>\n<p>Hace algunos d\u00edas y en una entrevista televisiva, Ma\u00f1alich hab\u00eda presentado sus argumentos para oponerse a una cuarentena total con una pregunta que fue motivo de burla entre los chilenos: \u00ab\u00bfQu\u00e9 pasa si el virus muta y se pone buena persona?\u00bb.<\/p>\n<h6>Fuente: P\u00e1gina 12<\/h6>\n","protected":false},"excerpt":{"rendered":"<p>La criticada gesti\u00f3n de la emergencia sanitaria encabezada por el ministro de Salud chileno, Jaime Ma\u00f1alich, sum\u00f3 un nuevo cap\u00edtulo luego de que \u00e9ste descartara la posibilidad de establecer una cuarentena general en el pa\u00eds.<\/p>\n","protected":false},"author":2,"featured_media":100876,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[22],"tags":[57],"class_list":["post-100875","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-el-mundo","tag-el-mundo"],"_links":{"self":[{"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/posts\/100875","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/comments?post=100875"}],"version-history":[{"count":0,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/posts\/100875\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/media\/100876"}],"wp:attachment":[{"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/media?parent=100875"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/categories?post=100875"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/tags?post=100875"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}