{"id":100890,"date":"2020-03-31T08:23:26","date_gmt":"2020-03-31T11:23:26","guid":{"rendered":"http:\/\/argentinamunicipal.com.ar\/argentina\/?p=100890"},"modified":"2020-03-31T08:23:26","modified_gmt":"2020-03-31T11:23:26","slug":"vidal-elude-la-polemica-por-los-hospitales-que-no-inauguro","status":"publish","type":"post","link":"http:\/\/argentinamunicipal.com.ar\/argentina\/vidal-elude-la-polemica-por-los-hospitales-que-no-inauguro\/","title":{"rendered":"Vidal elude la pol\u00e9mica por los hospitales que no inaugur\u00f3"},"content":{"rendered":"<p>As\u00ed se diferenci\u00f3 de la l\u00ednea dura del ex presidente, m\u00e1s preocupado por los argentinos en el exterior y por el parate econ\u00f3mico. Y de Patricia Bullrich, quien defendi\u00f3 los 1500 despidos en Techint.<\/p>\n<p>Quiz\u00e1s la comparaci\u00f3n de mensajes p\u00fablicos fue lo que m\u00e1s marc\u00f3 el contraste: mientras el ex presidente Mauricio Macri exig\u00eda con un comunicado del PRO que dejaran volver a los argentinos que est\u00e1n en el exterior, la ex gobernadora Mar\u00eda Eugenia Vidal publicaba un video de apoyo al presidente Alberto Fern\u00e1ndez y ped\u00eda acompa\u00f1ar las decisiones oficiales. No obstante, cuando public\u00f3 ese mensaje, muchos le recordaron sus palabras cuando dijo que no iba a inaugurar un hospital m\u00e1s en la provincia de Buenos Aires. El propio presidente hizo referencia hace algunos d\u00edas, tras una recorrida por La Matanza, sobre los dos hospitales que pasaron cuatro a\u00f1os all\u00ed sin comenzar a funcionar . Vidal eligi\u00f3 no responder. En su lugar, lo hicieron su ex ministro de Seguridad y actual jefe del bloque de Diputados del PRO, Cristian Ritondo, y su ex ministro de Salud, Andr\u00e9s Scarsi, quien argument\u00f3 que los hospitales estaban \u00abmal construidos\u00bb.<\/p>\n<p>La ex gobernadora viene manteniendo un perfil bajo en la arena pol\u00edtica, sin discursos p\u00fablicos ni reportajes con medios de comunicaci\u00f3n. No obstante, public\u00f3 un video en su cuenta de Instagram en el que dijo: \u00abEn estos momentos dif\u00edciles de incertidumbre, de preocupaci\u00f3n, y, en algunos hasta de miedo, les quiero mandar toda mi fuerza. Ese abrazo que por ahora no nos vamos a poder dar. Y decirles que si cada uno pone su parte vamos a estar menos solos y vamos a salir adelante\u00bb. \u00abPoner nuestra parte es acompa\u00f1ar y apoyar la decisiones del presidente, de los gobernadores y de cada intendente. Cada uno de ellos toma las mejores decisiones que cree posibles para ayudarnos a enfrentar algo que todav\u00eda no conocemos\u00bb, expresa all\u00ed Vidal.<\/p>\n<p>La ex gobernadora de Buenos Aires habl\u00f3 de la importancia de las y los trabajadores de la salud, que reciben un aplauso todas las noches, pero eludi\u00f3 volver a referirse a los hospitales no inaugurados durante su gesti\u00f3n. Se trata de seis hospitales que estaban pr\u00e1cticamente terminados en 2015 -seg\u00fan\u00a0un informe\u00a0de la Fundaci\u00f3n Soberan\u00eda Sanitaria- y que Vidal no puso en funcionamiento en sus cuatro a\u00f1os.\u00a0Eran dos hospitales en La Matanza, un tercero en Ca\u00f1uelas y otros tres en Ituzaing\u00f3, Esteban Echeverr\u00eda y Escobar.<\/p>\n<p>La entonces gobernadora defendi\u00f3 una y otra vez la decisi\u00f3n: \u00abConstruir un edificio es la parte m\u00e1s f\u00e1cil. Lo que vale la pena es poner equipamiento de \u00faltima generaci\u00f3n, que haya insumos, enfermeras y m\u00e9dicos. No voy a abrir hospitales nuevos porque es una estafa a la gente. Aunque no sea pol\u00edticamente correcto,\u00a0no me interesa cortar cintas\u00bb, dijo entonces. Y asegur\u00f3, en su momento, que el esfuerzo iba a ponerse en refaccionar los ochenta hospitales que ya exist\u00edan.<\/p>\n<p>El presidente Fern\u00e1ndez lo hab\u00eda recordado tras una visita a La Matanza: \u00abEstuve en el hospital Ren\u00e9 Favaloro, que qued\u00f3 hecho en 2015. Nunca nadie termin\u00f3 de poner las camas y la aparatolog\u00eda y lo dejaron ah\u00ed olvidado. Hay otro igual, que lo vandalizaron\u00bb.<\/p>\n<p>Vidal eligi\u00f3 no recoger el guante y no volvi\u00f3 sobre esa pol\u00e9mica. S\u00ed lo hizo su ex ministro Ritondo, quien tuite\u00f3: \u00bb\u00a0Al coronavirus lo enfrentamos todos juntos, pero sin mentiras. Acompa\u00f1ar y apoyar en esta emergencia no significa callar\u00bb. Y public\u00f3 una serie de discursos de hace a\u00f1os de Vidal, editados de manera que parece que le contesta a Fern\u00e1ndez. Pero la ex gobernadora no contest\u00f3.<\/p>\n<p>De hecho, el mensaje de Vidal con un abierto apoyo a las decisiones del presidente Fern\u00e1ndez contrast\u00f3 con una l\u00ednea que, de momento, no pudo imponer el ala dura del Juntos por el Cambio. Sin ir muy lejos, la presidenta del PRO,\u00a0Patricia Bullrich, el domingo\u00a0se dedic\u00f3 a defender los 1500 despidos en Techint\u00a0.<\/p>\n<p>Algo de eso se vio en una reuni\u00f3n virtual de la conducci\u00f3n del PRO del viernes pasado, donde el ex presidente Macri puso como uno de los temas la exigencia de que dejen volver a los argentinos en el exterior. Sin discutirselo -porque tampoco se oponen-\u00a0Vidal y el jefe de Gobierno, Horacio Rodr\u00edguez Larreta, intercambiaron miradas: creen que las prioridades son otras. Ella, en particular, est\u00e1 observando con preocupaci\u00f3n el conurbano, donde la demanda de comida -aseguran en su entorno- se cuatriplic\u00f3.<\/p>\n<p>Mientras tanto, Macri -quien tambi\u00e9n baj\u00f3 l\u00ednea sobre remarcar en p\u00fablico las consecuencias econ\u00f3micas de la cuarentena- compart\u00eda en su Twitter el comunicado del PRO sobre los argentinos en el exterior.<\/p>\n<p>Algunos de los que participaron de esa reuni\u00f3n dijeron a este diario que lo vieron al ex presidente \u00aben otro planeta, totalmente fuera de foco, incluso m\u00e1s que antes\u00bb, durante sus \u00faltimos a\u00f1os de gobierno. Quiz\u00e1s el tiempo que le dedica a la FIFA no lo est\u00e1 ayudando a concentrarse.<\/p>\n<h6>Fuente: P\u00e1gina 12<\/h6>\n","protected":false},"excerpt":{"rendered":"<p>As\u00ed se diferenci\u00f3 de la l\u00ednea dura del ex presidente, m\u00e1s preocupado por los argentinos en el exterior y por el parate econ\u00f3mico. Y de Patricia Bullrich, quien defendi\u00f3 los 1500 despidos en Techint.<\/p>\n","protected":false},"author":2,"featured_media":100891,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"tags":[21],"class_list":["post-100890","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-informe-politico","tag-argentina"],"_links":{"self":[{"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/posts\/100890","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/comments?post=100890"}],"version-history":[{"count":0,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/posts\/100890\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/media\/100891"}],"wp:attachment":[{"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/media?parent=100890"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/categories?post=100890"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/tags?post=100890"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}