{"id":101272,"date":"2020-04-08T06:44:56","date_gmt":"2020-04-08T09:44:56","guid":{"rendered":"http:\/\/argentinamunicipal.com.ar\/argentina\/?p=101272"},"modified":"2020-04-08T07:51:02","modified_gmt":"2020-04-08T10:51:02","slug":"coronavirus-merenderos-mendocinos-llevan-la-comida-casa-por-casa","status":"publish","type":"post","link":"http:\/\/argentinamunicipal.com.ar\/argentina\/coronavirus-merenderos-mendocinos-llevan-la-comida-casa-por-casa\/","title":{"rendered":"Coronavirus: merenderos mendocinos llevan la comida casa por casa"},"content":{"rendered":"<p>El movimiento Libres del Sur, y una de las agrupaciones que la integra, Barrios de Pie, pusieron en marcha acciones solidarias y trabajan en los barrios m\u00e1s humildes para contener a los m\u00e1s carenciados en la dif\u00edcil situaci\u00f3n que actualmente transita el pa\u00eds y Mendoza por la pandemia mundial del coronavirus, y que ha detenido a las econom\u00edas, especialmente a la nuestra, severamente resentida antes del flagelo sanitario.<\/p>\n<p>La organizaci\u00f3n social modific\u00f3 la forma de entrega de alimentos y realiza capacitaciones para prevenir el contagio. El trabajo que se est\u00e1 haciendo\u00a0se coordina en base a tres ejes: Intervenci\u00f3n en la\u00a0asistencia alimentaria bajo la modalidad ambulatoria\u00a0(entrega a domicilio para no generar situaciones de riesgo).\u00a0Asistencia social\u00a0en todas sus dimensiones, concientizaci\u00f3n; y\u00a0distribuci\u00f3n de informaci\u00f3n.<\/p>\n<p>Adri\u00e1n Bonada, coordinador provincial de Barrios de Pie explic\u00f3 que est\u00e1n articulando con los organismos del Estado la asistencia social en todas las dimensiones territoriales, ya sean municipales, provinciales o nacionales.<\/p>\n<p>\u00abEstamos colaborando y dando una mano en la intervenci\u00f3n de los sectores m\u00e1s humildes en la asistencia alimentaria.\u00a0Llevamos adelante los merenderos y los comedores, entregando por casa los alimentos en formato de vianda y fortaleciendo con m\u00f3dulos alimentarios para las familias que m\u00e1s complicada la est\u00e1n pasando. La\u00a0entrega es ambulatoria para evitar concentraciones de personas\u00a0y para promover que todos y todas se queden en casa\u00bb, explic\u00f3 Bonada.<\/p>\n<p>Desde Barrios de Pie tambi\u00e9n trabajan en la concientizaci\u00f3n, prevenci\u00f3n y la distribuci\u00f3n de informaci\u00f3n. \u00abQueremos que las familias m\u00e1s humildes tengan la informaci\u00f3n necesaria para no entrar en p\u00e1nico pero al mismo tiempo puedan tomar en serio el problema y extremar las precauciones\u00bb, ampli\u00f3 el coordinador de Barrios de Pie.<\/p>\n<p><strong>Presencia en toda la provincia<\/strong><br \/>\n\u00abHemos estado entregando la mercader\u00eda en barrios de toda la provincia, algunos son : Lihue, El Martillo, Ozaderuk, y El Sauce. En Godoy Cruz: Campo Pappa, Sol y sierra, Barrancos y Solidaridad, en Guaymall\u00e9n. En\u00a0Luj\u00e1n: Uni\u00f3n y Fuerza, Palmeras, Virgen de Lourdes, Tierras Vivas, Hogar del trabajador, Brandsen y Cuadro Estaci\u00f3n. En Tunuy\u00e1n: El algarrobo. En Capital: La Favorita, Olivares y San MartinLas Heras: Maza, Algarrobal, Santa Teresita, Democracia. Maip\u00fa: Coquimbito, 25 de Mayo, el Rosedal, 26 de julio. San Mart\u00edn: El central, Los Parrales, Divisadero, Tres porte\u00f1as, Montecaseros, Chapanay y Palmira. Estos algunos de los barrios en los que hemos estado asistiendo. Son varios m\u00e1s pero principalmente en estos\u00bb, detallo extensamente Adri\u00e1n.<\/p>\n<p>respecto a uno de los tres ejes con los que se gu\u00edan los voluntarios de Barrios de pie, Bonada explic\u00f3: \u00abTratamos de compartir y hacer viral toda la informaci\u00f3n oficial del gobierno. A trav\u00e9s de Whatsapp y Facebook sobre todo. Incentivamos no caer en noticias falsas que desinformen y causan p\u00e1nico\u00bb, explic\u00f3 el dirigente social, que agreg\u00f3: \u00abDespu\u00e9s intentamos servir de ayuda para asesorar en lo relacionado a los programas de asistencia como el ingreso \u00fanico de 10 mil pesos entre otras cuestiones que van surgiendo para asistir a este sector tan golpeado\u00bb, dijo.<\/p>\n<p>Sobre la recepci\u00f3n de la gente a esta inicitiva, Adri\u00e1n indic\u00f3 que \u00abla verdad que muy bien. La situaci\u00f3n se est\u00e1 poniendo dura y cualquier ayuda que haga m\u00e1s llevadero esto, es recibida con mucho agradecimiento. Sobre todo en lugares donde est\u00e9 freno econ\u00f3mico golpea de una manera terrible\u00bb.<\/p>\n<p>\u00abEstamos a disposici\u00f3n de todos los organismos del Estado sobre todo los que est\u00e1n involucrados con la asistencia social de los sectores m\u00e1s vulnerables\u00a0que son los que est\u00e1n empezando a sentir m\u00e1s fuertemente el impacto, ya que dependen de la econom\u00eda informal\u00bb, concluy\u00f3 el dirigente social.<\/p>\n<h6>Fuente: Uno<\/h6>\n","protected":false},"excerpt":{"rendered":"<p>El movimiento Libres del Sur, y una de las agrupaciones que la integra, Barrios de Pie, pusieron en marcha acciones solidarias y trabajan en los barrios m\u00e1s humildes para contener a los m\u00e1s carenciados<\/p>\n","protected":false},"author":2,"featured_media":101273,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[31],"class_list":["post-101272","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-informe-municipal","tag-mendoza"],"_links":{"self":[{"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/posts\/101272","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/comments?post=101272"}],"version-history":[{"count":0,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/posts\/101272\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/media\/101273"}],"wp:attachment":[{"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/media?parent=101272"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/categories?post=101272"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/tags?post=101272"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}