{"id":101424,"date":"2020-04-13T05:40:56","date_gmt":"2020-04-13T08:40:56","guid":{"rendered":"http:\/\/argentinamunicipal.com.ar\/argentina\/?p=101424"},"modified":"2020-04-13T07:43:12","modified_gmt":"2020-04-13T10:43:12","slug":"san-rafael-la-noble-labor-de-los-municipales-que-recogen-la-basura","status":"publish","type":"post","link":"http:\/\/argentinamunicipal.com.ar\/argentina\/san-rafael-la-noble-labor-de-los-municipales-que-recogen-la-basura\/","title":{"rendered":"San Rafael: La noble labor de los municipales que recogen la basura"},"content":{"rendered":"<p>Sin lugar a dudas, una corriente de simpat\u00eda con los trabajadores encargados de recolectar los residuos se extiende entre la poblaci\u00f3n. As\u00ed lo perciben cientos de mensajes que se ven en las redes, a la hora de ponderar esta y otro tipos de tareas que se requieren en este tiempo de coronavirus.<\/p>\n<p>Sergio Ram\u00f3n y Sixto Pereyra, son dos de los empleados encargados de mantener limpia de basura a nuestra ciudad, y que d\u00eda a d\u00eda se exponen de lleno su salud a este noble trabajo.<\/p>\n<p>Sergio dijo a Diario San Rafael que \u201chasta ahora nuestro trabajo sigue siendo normal. Con m\u00e1s precauci\u00f3n obviamente, sobre todo cuando volvemos a casa y nos recibe la familia. Uno siempre tiene miedo porque estamos recorriendo toda la ciudad. Sobre todo cuando uno levanta los residuos de lugares donde puede haber alguien en cuarentena, o donde uno sabe que hay extranjeros, ya que siempre te queda la duda si pueden tener algo o no, y si en los residuos hay algo que uno puede contagiarse, pero bueno hay que seguir nom\u00e1s\u201d.<\/p>\n<p>A\u00f1adi\u00f3 que \u201cyo tengo cinco hijos y el mayor temor es cuando llego a casa. Hay que higienizarse muy bien, y ser m\u00e1s cuidadoso que de costumbre, m\u00e1s nosotros que estamos tan expuestos. En lo personal, cuando llego a mi casa dejo la ropa afuera, me ba\u00f1o y reci\u00e9n ah\u00ed me acerco a la familia por temor a que uno pueda contagiar a alguien. Ese es un momento que me siento raro\u201d.<\/p>\n<p>En esta l\u00ednea, Sixto coment\u00f3 que \u201cen medio de esta cuarentena somos uno de los oficios m\u00e1s importantes para que todo siga con normalidad y la gente se est\u00e1 dando cuenta y eso es bueno. En mi casa somos cinco y siempre que llego me cambio primero que nada, me ba\u00f1o y reci\u00e9n ah\u00ed saludo. Uno anda con un poco de miedo pero trato de no pensar mucho porque sino te persegu\u00eds demasiado y no te hace bien, porque al otro d\u00eda hay que seguir\u201d.<\/p>\n<p>Previo a subirse al cami\u00f3n junto a su compa\u00f1ero para seguir con su recorrido, a\u00f1adi\u00f3 que \u201cojal\u00e1 todo el mundo haga caso y se quede en su casa, pero lamentablemente parece imposible porque uno se da cuenta tambi\u00e9n que hay gente que anda caminando o haciendo cosas que no deber\u00edan y eso puede quitarnos la tranquilidad que tenemos hasta ahora. Espero que este virus no nos llegue en nada a los sanrafaelinos y a los lugares que ya ha llegado y ha enfermado gente, ojal\u00e1 que se curen pronto, porque es una situaci\u00f3n muy mala en todo sentido\u201d.<\/p>\n<p>Ambos se mostraron agradecidos y orgullosos de la empat\u00eda que observan entre los ciudadanos hac\u00eda su oficio en estos momentos dif\u00edciles, tambi\u00e9n sus compa\u00f1eros les transmiten que perciben esa solidaridad hacia un trabajo que es esencial y necesario en estos tiempos de cuarentena.<\/p>\n<h6>Fuente: diariosanrafael.com.ar<\/h6>\n","protected":false},"excerpt":{"rendered":"<p>Sin lugar a dudas, una corriente de simpat\u00eda con los trabajadores encargados de recolectar los residuos se extiende entre la poblaci\u00f3n. As\u00ed lo perciben cientos de mensajes que se ven en las redes<\/p>\n","protected":false},"author":2,"featured_media":101425,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[31],"class_list":["post-101424","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-informe-municipal","tag-mendoza"],"_links":{"self":[{"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/posts\/101424","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/comments?post=101424"}],"version-history":[{"count":0,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/posts\/101424\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/media\/101425"}],"wp:attachment":[{"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/media?parent=101424"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/categories?post=101424"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/tags?post=101424"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}