{"id":105722,"date":"2020-08-04T07:21:02","date_gmt":"2020-08-04T10:21:02","guid":{"rendered":"http:\/\/argentinamunicipal.com.ar\/argentina\/?p=105722"},"modified":"2020-08-04T07:21:02","modified_gmt":"2020-08-04T10:21:02","slug":"en-julio-una-familia-cordobesa-necesito-casi-17-000-para-alimentos","status":"publish","type":"post","link":"http:\/\/argentinamunicipal.com.ar\/argentina\/en-julio-una-familia-cordobesa-necesito-casi-17-000-para-alimentos\/","title":{"rendered":"En julio, una familia cordobesa necesit\u00f3 casi $17.000 para alimentos"},"content":{"rendered":"<p>El dato surge de un informe del Defensor del Pueblo para un hogar con dos adultos y dos ni\u00f1os. Las familias que no superen ese monto son consideradas indigentes.<\/p>\n<p>El precio de la Canasta B\u00e1sica Alimentaria (CBA) para un hogar formado por dos adultos y dos ni\u00f1os lleg\u00f3 a $16.915,17 durante julio pasado. Las familias cuyos ingresos no superen ese nivel, son consideradas indigentes. La Canasta B\u00e1sica Total (CBT) para ese hogar, con los dem\u00e1s gastos cotidianos, fue de $41.103,86. Tener salarios que no alcancen ese monto implica encontrarse bajo la l\u00ednea de pobreza.<\/p>\n<p>La variaci\u00f3n mensual de la CBA durante julio fue del 1,42%.\u00a0Los alimentos esenciales costaron $237,27 m\u00e1s que en junio. En tanto que la variaci\u00f3n interanual (julio 2019\/2020) fue del 46,33%, es decir, $5.355,50 m\u00e1s cara que hace un a\u00f1o. En relaci\u00f3n a la CBT, en un a\u00f1o tuvo una variaci\u00f3n de $12.089,08. O sea, 41,67% m\u00e1s cara.<\/p>\n<p>Subas por rubro<br \/>\nLos cortes que se incluyen en Carnes constituyen el grupo con m\u00e1s peso dentro de la CBA. El rubro tuvo una variaci\u00f3n de\u00a04,38%. Los aumentos m\u00e1s relevantes se dieron en paleta (15,23%), carnaza (10,26%), asado (10,13%) y falda (10,12%). El \u00fanico corte que mostr\u00f3 una baja sensible fue la nalga (-9,14%).<\/p>\n<p>El rubro Harinas y Legumbres en el mes de julio registr\u00f3 una variaci\u00f3n de 2,32%. Ocho de los diez \u00edtems que integran este rubro aumentaron. Entre ellos se destacan las lentejas (16,82%), porotos (12,54%) y arroz (11,72%). Por otra parte, la polenta fue el art\u00edculo que mostr\u00f3 la mayor baja de precio dentro del (-4,45%).<\/p>\n<p>Frutas y Verduras tuvieron una variaci\u00f3n mensual del 0,26%. Los mayores aumentos se dieron en la cebolla (12,62%) y en la batata (9,92%). La papa, que es el producto que mayor gasto implica dentro del rubro, se present\u00f3 con una variaci\u00f3n en su costo del 5,85%. En tanto que se constat\u00f3 una sensible baja en el precio del tomate (-30,41%).<\/p>\n<p>Los alimentos agrupados dentro de Otros tuvieron en julio una variaci\u00f3n del -2,06%. El precio del dulce de batata fue el que m\u00e1s subi\u00f3 (6,95%), seguido por la mermelada (3,72%).\u00a0Entre las bajas se destacan el dulce de leche (-6,18%) y el aceite, un producto relevante en el rubro, que baj\u00f3 un -0,18%.<\/p>\n<p>El grupo Huevos y L\u00e1cteos present\u00f3 una baja del -3,47%. Todos los art\u00edculos que componen el rubro disminuyeron, con variaciones que oscilaron entre el -0,12% en el costo del queso fresco, hasta un -4,38% para el precio de la leche entera, que es el producto que m\u00e1s peso tiene en el costo total de este rubro.<\/p>\n<h6>Fuente: La Nueva Ma\u00f1ana<\/h6>\n","protected":false},"excerpt":{"rendered":"<p>El dato surge de un informe del Defensor del Pueblo para un hogar con dos adultos y dos ni\u00f1os. Las familias que no superen ese monto son consideradas indigentes.<\/p>\n","protected":false},"author":2,"featured_media":105723,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5],"tags":[3],"class_list":["post-105722","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-informe-economico","tag-cordoba"],"_links":{"self":[{"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/posts\/105722","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/comments?post=105722"}],"version-history":[{"count":0,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/posts\/105722\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/media\/105723"}],"wp:attachment":[{"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/media?parent=105722"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/categories?post=105722"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/tags?post=105722"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}