{"id":105795,"date":"2020-08-05T05:40:59","date_gmt":"2020-08-05T08:40:59","guid":{"rendered":"http:\/\/argentinamunicipal.com.ar\/argentina\/?p=105795"},"modified":"2020-08-05T07:42:58","modified_gmt":"2020-08-05T10:42:58","slug":"reves-para-macri-por-el-correo-la-justicia-rechaza-ultimo-recurso-a-la-corte","status":"publish","type":"post","link":"http:\/\/argentinamunicipal.com.ar\/argentina\/reves-para-macri-por-el-correo-la-justicia-rechaza-ultimo-recurso-a-la-corte\/","title":{"rendered":"Rev\u00e9s para Macri por el Correo: la Justicia rechaza \u00faltimo recurso a la Corte"},"content":{"rendered":"<p>La intenci\u00f3n de los representantes de la familia Macri era llegar a la Corte Suprema con un recurso extraordinario. En Tribunales no descartan un nuevo intento dilatorio.<\/p>\n<p>La C\u00e1mara Comercial rechaz\u00f3 un pedido de la familia\u00a0Macri\u00a0para ir a la\u00a0Corte Suprema\u00a0y as\u00ed demorar el proceso de salvataje, o \u201ccramdown\u201d del\u00a0Correo Argentino, y los pasos previos a la quiebra de la firma controlada por Socma.<\/p>\n<p>La intenci\u00f3n de los representantes de la familia Macri era llegar a la Corte Suprema con un recurso extraordinario en el que se cuestion\u00f3 la decisi\u00f3n de la Sala B de la C\u00e1mara Comercial, que orden\u00f3 en diciembre pasado el inicio del registro de cramdown, es decir la convocatoria p\u00fablica para saber si existen interesados en la compra del Correo Argentino.<\/p>\n<p>En tribunales no descartan que en un nuevo intento dilatorio, los representantes de la familia Macri interpongan una \u201cqueja\u201d directa a la Corte.<\/p>\n<p>De todas maneras, un nuevo rev\u00e9s fue asestado este martes con el fallo dictado por la C\u00e1mara Comercial que en dur\u00edsimos t\u00e9rminos, dio respuesta a ese recurso interpuesto por la deudora, seg\u00fan inform\u00f3\u00a0Ambito.com.<\/p>\n<p>En diciembre del a\u00f1o pasado,\u00a0la C\u00e1mara rechaz\u00f3 la apelaci\u00f3n y confirm\u00f3 la resoluci\u00f3n de primera instancia que desestim\u00f3 la homologaci\u00f3n del acuerdo; y orden\u00f3 la apertura del registro de \u00a8cramdown\u00a8.<\/p>\n<p>Ahora,\u00a0por defectos formales de la presentaci\u00f3n de la concursada,\u00a0rechaz\u00f3 la procedencia del recurso, y precis\u00f3 que no es aceptable el argumento de \u201carbitrariedad\u201d esgrimido por los representantes de Correo de la familia Macri.<\/p>\n<p>En ese sentido, la deudora aleg\u00f3 entre otras cosas que el Estado habr\u00eda abusado de su posici\u00f3n. Que se permite que el Estado Nacional, \u201chaga abuso de su supuesto derecho y de su posici\u00f3n dominante, y lleve a la quiebra a una empresa con el grave perjuicio de todos los sectores comprometidos, tanto proveedores, como acreedores y tambi\u00e9n el personal que se desempe\u00f1a en ella\u201d.<\/p>\n<p>La C\u00e1mara rechaz\u00f3 la procedencia del recurso intentado en ese sentido. \u201cEl discurso de la recurrente procura enjuiciar el proceder de esta Alzada, mas no hace sino trasuntar diversa interpretaci\u00f3n de los hechos analizados y de las conclusiones asumidas en el decisorio las que, m\u00e1s all\u00e1 de la disconformidad que provoquen, hallan adecuado fundamento en los antecedentes de la causa, lo cual descarta la imputaci\u00f3n de arbitrariedad\u201d, dice uno de los p\u00e1rrafos del fallo de la C\u00e1mara.<\/p>\n<p>Los jueces recordaron que a lo largo de las actuaciones se sucedieron\u00a0\u201cdiversas mejoras de la primigenia oferta no contando ninguna de ellas con la conformidad del Estado Nacional, raz\u00f3n por la cual tanto el Poder Ejecutivo como la aqu\u00ed recurrente solicitaron varias pr\u00f3rrogas de plazos\u201d.<\/p>\n<p>En la causa tambi\u00e9n consta la presentaci\u00f3n de fecha 2\/10\/2019 donde el propio Estado Nacional expresa que no presta conformidad con la \u00faltima mejora de la concursada, \u201craz\u00f3n por la cual en la actualidad en forma expl\u00edcita se puede se\u00f1alar que no se han obtenido las mayor\u00edas legales requeridas por lo que fatalmente corresponde confirmar la resoluci\u00f3n\u201d adoptada.<\/p>\n<p>De esta forma, el tribunal respald\u00f3 el dictamen de la fiscal\u00a0Gabriela Boqu\u00edn, que d\u00edas atr\u00e1s\u00a0se pronunci\u00f3 por rechazar el intento de la deudora de recurrir la apertura del procedimiento de salvataje, previsto en el art\u00edculo 48 de la Ley de Concursos y Quiebras.<\/p>\n<p>Boqu\u00edn ya lo hab\u00eda dicho:\u00a0que el pedido de los Macri deb\u00eda ser declarado inadmisible, porque no existe cuesti\u00f3n federal ni supuesto de arbitrariedad y que el recurso extraordinario para llegar a la Corte constituye \u00abun nuevo intento dilatorio de la concursada para seguir prolongando el tr\u00e1mite de los actuados, lo cual a esta altura ya no puede ser admitido\u201d.<\/p>\n<p>Ahora la C\u00e1mara, al rebatir los argumentos de la concursada, le dice que \u201csi se pretendi\u00f3 una interpretaci\u00f3n distinta, debi\u00f3 especificar con precisi\u00f3n los fundamentos de las objeciones, puesto que como es sabido, los criterios diversos, las afirmaciones gen\u00e9ricas y las impugnaciones de orden general son inid\u00f3neas para mantener un recurso\u201d.<\/p>\n<h6>Fuente: Minuto Uno<\/h6>\n","protected":false},"excerpt":{"rendered":"<p>La intenci\u00f3n de los representantes de la familia Macri era llegar a la Corte Suprema con un recurso extraordinario. En Tribunales no descartan un nuevo intento dilatorio.<\/p>\n","protected":false},"author":2,"featured_media":105796,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"tags":[21],"class_list":["post-105795","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-informe-politico","tag-argentina"],"_links":{"self":[{"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/posts\/105795","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/comments?post=105795"}],"version-history":[{"count":0,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/posts\/105795\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/media\/105796"}],"wp:attachment":[{"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/media?parent=105795"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/categories?post=105795"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/tags?post=105795"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}