{"id":106545,"date":"2020-08-26T11:04:38","date_gmt":"2020-08-26T14:04:38","guid":{"rendered":"http:\/\/argentinamunicipal.com.ar\/argentina\/?p=106545"},"modified":"2020-08-26T11:04:38","modified_gmt":"2020-08-26T14:04:38","slug":"desde-hoy-nacion-emitira-partes-diarios-sobre-los-incendios-en-el-pais","status":"publish","type":"post","link":"http:\/\/argentinamunicipal.com.ar\/argentina\/desde-hoy-nacion-emitira-partes-diarios-sobre-los-incendios-en-el-pais\/","title":{"rendered":"Desde hoy, Naci\u00f3n emitir\u00e1 partes diarios sobre los incendios en el pa\u00eds"},"content":{"rendered":"<p>En medio del desastre ecol\u00f3gico, el Gobierno indic\u00f3 que se dar\u00e1 informaci\u00f3n detallada de las acciones para combatir los incendios que se registran en diferentes provincias.<\/p>\n<p>El Gobierno nacional emitir\u00e1 a partir de este mi\u00e9rcoles partes diarios con informaci\u00f3n detallada de las acciones que se llevan adelante para combatir los incendios que se registran en diferentes provincias del pa\u00eds, en el marco de trabajos coordinados por los ministerios de Seguridad, a trav\u00e9s del Servicio Nacional de Manejo del Fuego, y el de Ambiente y Desarrollo Sostenible.<\/p>\n<p>Fuentes de Gobierno consignaron que\u00a0el informe, que se difundir\u00e1 en horario matutino, dar\u00e1 cuenta de \u00ablas provincias afectadas por el fuego y la situaci\u00f3n actualizada del trabajo que all\u00ed se efect\u00faa\u00a0con el despliegue de medios aportados\u00bb por el Poder Ejecutivo.<\/p>\n<p>Tambi\u00e9n\u00a0se adjuntar\u00e1 durante los informes \u00abun mapa ilustrativo que registrar\u00e1 los lugares donde se focalizan los incendios\u00bb.<\/p>\n<p>El presidente Alberto Fern\u00e1ndez se comunic\u00f3 en las \u00faltimas horas con el gobernador Juan Schiaretti, para ofrecerle colaboraci\u00f3n para combatir los incendios forestales que se registran desde hace m\u00e1s de una semana en las sierras y afectan a montes, pastizales y viviendas, adem\u00e1s de causar innumerables da\u00f1os a la flora y fauna.<\/p>\n<p>En su cuenta de Twitter,\u00a0el mandatario provincial agradeci\u00f3 \u00abel llamado del presidente Alberto Fern\u00e1ndez para ponerse a disposici\u00f3n en la colaboraci\u00f3n con todo lo necesario en la lucha contra los incendios que afectan a nuestra provincia\u00bb.<\/p>\n<p>\u00abEn este momento, contamos con aviones hidrantes del Plan Nacional de Manejo del Fuego y en el d\u00eda de ma\u00f1ana llegar\u00e1 un helic\u00f3ptero\u00bb,\u00a0afirm\u00f3 Schiaretti.<\/p>\n<p>Los incendios forestales que se desarrollan en la zona norte del Valle de Punilla continuaban activos, con dos focos que complican la visibilidad en la Ruta Nacional 38, entre Capilla del Monte y Cruz del Eje, mientras\u00a0bomberos voluntarios trabajan combatiendo las llamas y aviones hidrantes realizan el soporte a\u00e9reo.<\/p>\n<p>Tambi\u00e9n se registran incendios en las islas del Paran\u00e1 cercanas a la ciudad de Rosario, en Chaco y Corrientes.<\/p>\n<h6>Fuente: La Nueva Ma\u00f1ana<\/h6>\n","protected":false},"excerpt":{"rendered":"<p>En medio del desastre ecol\u00f3gico, el Gobierno indic\u00f3 que se dar\u00e1 informaci\u00f3n detallada de las acciones para combatir los incendios que se registran en diferentes provincias.<\/p>\n","protected":false},"author":2,"featured_media":106546,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[21],"class_list":["post-106545","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-informe-municipal","tag-argentina"],"_links":{"self":[{"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/posts\/106545","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/comments?post=106545"}],"version-history":[{"count":0,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/posts\/106545\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/media\/106546"}],"wp:attachment":[{"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/media?parent=106545"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/categories?post=106545"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/tags?post=106545"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}