{"id":106591,"date":"2020-08-28T07:26:20","date_gmt":"2020-08-28T10:26:20","guid":{"rendered":"http:\/\/argentinamunicipal.com.ar\/argentina\/?p=106591"},"modified":"2020-08-28T07:26:20","modified_gmt":"2020-08-28T10:26:20","slug":"bariloche-mantiene-su-acuerdo-con-ops-y-no-para-de-acumular-deuda","status":"publish","type":"post","link":"http:\/\/argentinamunicipal.com.ar\/argentina\/bariloche-mantiene-su-acuerdo-con-ops-y-no-para-de-acumular-deuda\/","title":{"rendered":"Bariloche mantiene su acuerdo con OPS y no para de acumular deuda"},"content":{"rendered":"<p>La municipalidad contin\u00faa utilizando la maquinaria de la firma cipole\u00f1a. La empresa se\u00f1ala que est\u00e1 pr\u00f3xima a levantar la quiebra y estima el pasivo de la ciudad andina en unos 250 millones de pesos.<\/p>\n<p>Apremiado por la necesidad de mantener en estado decoroso las calles, pluviales y espacios p\u00fablicos, el municipio de Bariloche fue en busca, hace casi dos a\u00f1os, de la empresa OPS, que ten\u00eda maquinaria ociosa disponible para ese fin.<\/p>\n<p>El v\u00ednculo comenz\u00f3 en el mayor de los sigilos, con menos protocolos y burocracia que de costumbre, y al d\u00eda de hoy los equipos viales de la firma con base en Cipolletti siguen al servicio del municipio, pero la relaci\u00f3n est\u00e1 lejos de ser arm\u00f3nica.<\/p>\n<p>El alquiler gener\u00f3 en favor de OPS una acreencia millonaria, con un aditamento clave: la empresa fue declarada en quiebra en 2019 y hoy su propietario original no puede disponer de los bienes, que est\u00e1n bajo la tutela de un s\u00edndico judicial.<\/p>\n<p>El intendente Gustavo Gennuso dijo que la operaci\u00f3n \u201ces muy beneficiosa\u201d y el municipio jam\u00e1s podr\u00eda haber atendido la demanda de servicios en un territorio tan amplio sin las m\u00e1quinas de OPS. Admiti\u00f3 que hay una deuda que saldar y que no hay acuerdo por el monto.<\/p>\n<p>Tambi\u00e9n se\u00f1al\u00f3 que los intentos de llevar claridad a ese punto estaban encaminados antes de la pandemia, pero la feria judicial paraliz\u00f3 todo. \u201cTen\u00edamos pedida una audiencia a la jueza de la quiebra, que estaba fijada para el 26 de marzo, pero no se hizo porque pocos d\u00edas antes entramos en cuarentena\u00a0-record\u00f3 el intendente-. Despu\u00e9s pedimos una nueva fecha en junio y todav\u00eda no tuvimos respuesta\u201d.<\/p>\n<p>La asesora letrada del municipio, Mercedes Lasmartres, dijo tambi\u00e9n que no hab\u00eda novedades, que\u00a0el expediente de quiebra tramita en Buenos Aires y que \u201ctodo est\u00e1 frenado por la pandemia\u201d. Adem\u00e1s, el caso OPS no est\u00e1 a su cargo en forma directa porque el municipio contrat\u00f3 con ese fin al abogado Dar\u00edo Tropeano.<\/p>\n<p>El desperezamiento de la actividad judicial podr\u00eda contribuir por fin a llevar claridad al conflicto de partes que permanece irresuelto y que, seg\u00fan algunos observadores, podr\u00eda terminar en una demanda contra el municipio por cientos de millones de pesos.<\/p>\n<p>Otro punto a resolver, que est\u00e1 llamado a alterar el escenario, es el posible levantamiento de la quiebra, reclamada por los propietarios de OPS. El representante comercial de la firma, Jonathan Mart\u00ednez, le asegur\u00f3 a este diario que esa decisi\u00f3n judicial ya es \u201ccasi un hecho\u201d y le puso plazo: \u201cva a ser en los primeros d\u00edas de septiembre\u201d.<\/p>\n<p>De esa forma, retomar\u00eda el control de\u00a0OPS el grupo empresario liderado por Mario Cifuentes,\u00a0quien gan\u00f3 notoriedad entre 2010 y 2015 como proveedor privilegiado de YPF y arrastra denuncias por evasi\u00f3n y lavado de dinero.<\/p>\n<p>Gennuso dijo que no ten\u00eda m\u00e1s precisiones pero tambi\u00e9n asegur\u00f3 que estar\u00eda cerca el levantamiento de la quiebra. Estim\u00f3 que -en ese sentido- la posici\u00f3n de la empresa mejor\u00f3 \u201ccon la cl\u00e1usula de la \u00faltima moratoria\u201d dispuesta por Naci\u00f3n, que otorga facilidades a las empresas fallidas que mantienen abultadas deudas con el fisco.<\/p>\n<p><strong>M\u00e1quinas salvadoras<\/strong><\/p>\n<p>El v\u00ednculo del gobierno de Gennuso con OPS comenz\u00f3 a finales de 2018,\u00a0cuando ya estaba a la vista la crucial elecci\u00f3n del a\u00f1o pasado (en la que logr\u00f3 renovar su mandato) y ya ten\u00eda sobradamente probado que el mantenimiento de calles era un factor de alta sensibilidad en la opini\u00f3n p\u00fablica.<\/p>\n<p>La flota de propiedad municipal ten\u00eda (y tiene hoy) una capacidad apenas simb\u00f3lica y la opci\u00f3n OPS le calz\u00f3 como un guante, porque pod\u00eda disponer de m\u00e1quinas de buena calidad, en un n\u00famero imposible de conseguir de otro modo y disponibles para el alquiler \u201csin chofer\u201d que -seg\u00fan el propio Gennuso- ninguna otra firma del rubro estaba dispuesta a conceder.<\/p>\n<p>El camino elegido fue entonces la\u00a0contrataci\u00f3n directa, y en el verano de 2019 los barrios de Bariloche ya empezaron a familiarizarse con las motoniveladoras \u201cCaterpillar\u201d, cuya eficiencia era muy superior a las \u201cPawly\u201d, de propiedad municipal. Tambi\u00e9n\u00a0una topadora de OPS comenz\u00f3 a operar en el basurero y contribuy\u00f3 a mejorar ese servicio, que el municipio deb\u00eda atender sin demora, urgido por un amparo judicial.<\/p>\n<p>Hoy el municipio tiene en resguardo 19 m\u00e1quinas y camiones de OPS, aunque no todos est\u00e1n en uso. El secretario de Obras y Servicios P\u00fablicos, Eduardo Garza, dijo que actualmente est\u00e1n operativas cuatro motoniveladoras, dos retroexcavadoras, dos palas cargadoras y dos camiones con batea. Otra motoniveladora est\u00e1 \u201cguardada\u201d en la delegaci\u00f3n Cerro Otto y no funciona por \u201cun problema de inyecci\u00f3n\u201d que es de compleja reparaci\u00f3n.<\/p>\n<p>El resto de las m\u00e1quinas reciben mantenimiento, con repuestos y horas de mec\u00e1nicos de los que se hacer cargo el municipio.<\/p>\n<p>Ese costo, que la gesti\u00f3n Gennuso pretende restar de lo devengado en los alquileres, es el principal punto de controversia a la hora de determinar la deuda.<\/p>\n<p>El detalle deber\u00eda tenerlo el secretario de Hacienda, Diego Quintana, un funcionario de origen neuquino quien desde el Centro C\u00edvico fue se\u00f1alado como el verdadero gestor del acuerdo con OPS. Pero Quintana no atendi\u00f3 los llamados de este diario.<\/p>\n<p>Seg\u00fan indic\u00f3 Garza,\u00a0la municipalidad tiene hoy otras cinco motoniveladoras de su propiedad\u00a0\u201cm\u00e1s una sexta que est\u00e1 parada, porque hay que hacerle el motor\u201d. De modo que los equipos arrendados a OPS representan la mitad de la capacidad operativa total.<\/p>\n<p><strong>Un reclamo de 250 millones<\/strong><\/p>\n<p>La relaci\u00f3n del municipio con OPS est\u00e1 llena de interrogantes y el dinero en juego sea tal vez el punto m\u00e1s oscuro.<\/p>\n<p>El\u00a0municipio efectu\u00f3 un primer pago de 3.121.800 pesos a comienzos de 2019.\u00a0En julio de ese a\u00f1o la sindicatura de OPS present\u00f3 una factura por 21,2 millones y ya en marzo de este a\u00f1o los representantes de\u00a0la firma hablaban de una deuda 130 millones. En mayo habr\u00edan emitido otra factura por 200 millones.<\/p>\n<p>Aunque la cifra pueda parecer inabarcable, las m\u00e1quinas nunca dejaron de trabajar.<\/p>\n<p>Jonathan Mart\u00ednez, vocero de la empresa, dijo esta semana que no contaba con un c\u00e1lculo actualizado de la deuda. S\u00f3lo se\u00f1al\u00f3 que\u00a0\u201centre mayo y junio\u201d, la cifra rondaba \u201clos 250 millones de pesos\u201d.<\/p>\n<p>Dijo que los titulares de OPS esperan el levantamiento de la quiebra para ir por ese dinero y minimiz\u00f3 los eventuales descuentos que puedan realizarse en funci\u00f3n de las reparaciones y el mantenimiento de m\u00e1quinas que tenga documentado el municipio.<\/p>\n<p>En febrero pasado Quintana dijo que el reclamo de compensaci\u00f3n a esa fecha era por 40 millones.<\/p>\n<p>Mart\u00ednez no dijo c\u00f3mo llegaron a redondear una factura por esos valores. Solo se\u00f1al\u00f3 a modo de referencia que el alquiler mensual de una motoniveladora \u201ccon 250 horas de uso garantizado\u201d est\u00e1 cotizado en 180 mil pesos. No fue posible confirmar si el municipio valida esa tarifa y sobre cu\u00e1ntas m\u00e1quinas se debe contabilizar el impago.<\/p>\n<p>A sabiendas de que la deuda corre,\u00a0Gennuso confirm\u00f3 que hicieron en junio pasado un dep\u00f3sito en sede judicial de 2 millones de pesos como pago \u201ca cuenta\u201d.<\/p>\n<p>El intendente confirm\u00f3 que no todos los veh\u00edculos de OPS que recibi\u00f3 el municipio est\u00e1n operativos. Se\u00f1al\u00f3 que el trato entre las partes podr\u00eda cambiar con el inminente levantamiento de la quiebra, pero no se atrevi\u00f3 a decir si el municipio se ver\u00e1 favorecido o perjudicado.<\/p>\n<p>La contrataci\u00f3n directa con OPS tambi\u00e9n entr\u00f3 en el radar del Tribunal de Contralor municipal, que ya en la gesti\u00f3n anterior hab\u00eda pedido informes sobre el tema, sin tomar ninguna definici\u00f3n. El actual presidente de ese \u00f3rgano, Oscar Cannizzaro, reconoci\u00f3 que tienen \u201cdocumentaci\u00f3n para evaluar\u201d, pero dijo que no hubo hasta ahora ning\u00fan avance en ese expediente.<\/p>\n<p><strong>\u00abUn beneficio indiscutible\u00bb<\/strong><\/p>\n<p>Al margen de las sospechas generadas por la contrataci\u00f3n directa, por los antecedentes de\u00a0OPS\u00a0y por los vol\u00famenes de dinero en juego, el intendente Gustavo Gennuso dijo que la puesta en servicio de esas m\u00e1quinas en el ejido municipal trajo \u201cun beneficio indiscutible\u201d y subray\u00f3 que no hab\u00eda otra forma de resolver esa demanda.<\/p>\n<p>\u201cFue una soluci\u00f3n porque las m\u00e1quinas son de buena calidad y duplicaron el parque automotor que ten\u00edamos\u201d, asegur\u00f3.\u00a0El secretario de Obras y Servicios P\u00fablicos, Eduardo Garza, tambi\u00e9n ponder\u00f3 el aporte de las \u201cmoto\u201d y las \u201cretro\u201d de la empresa cipole\u00f1a.<\/p>\n<p>Dijo que \u201cson fundamentales, aun pagando alquiler, porque con lo gastado no se podr\u00eda haber comprado ni siquiera una m\u00e1quina nueva, que anda en los 100 millones de pesos\u201d.<\/p>\n<p>Dijo que con los equipos arrendados y los propios el municipio \u201cse arregla bien en una \u00e9poca normal\u201d, pero en un invierno duro, con sucesi\u00f3n de tormentas de nieve, como ocurri\u00f3 este a\u00f1o \u201cno hay nada que alcance\u201d.<\/p>\n<p>Garza asegur\u00f3 que al principio ven\u00eda a Bariloche personal t\u00e9cnico de\u00a0OPS\u00a0para realizar reparaciones peri\u00f3dicas, pero dejaron de hacerlo cuando \u201cse public\u00f3 todo y se gener\u00f3 la pol\u00e9mica\u201d.<\/p>\n<p>Dijo que desde entonces, cada tanto, la firma env\u00eda empleados a controlar sus bienes y \u201cest\u00e1n conformes, encuentran todo muy bien. Ellos mismos cuentan que en otros lugares donde tienen m\u00e1quinas en alquiler est\u00e1n todas desmanteladas\u201d.<\/p>\n<p>Se\u00f1al\u00f3 tambi\u00e9n que contar con m\u00e1s motoniveladoras y retroexcavadoras podr\u00eda ayudar a brindar mejor servicio pero el municipio carece de la cantidad de maquinistas necesarios. Sobre la exigencia de usar solo choferes locales, otro exdelegado municipal dijo que \u201ces muy importante, porque conocen todo, d\u00f3nde est\u00e1n los ca\u00f1os, las tapas de cloacas, en cambio el chofer que viene de afuera no conoce y ah\u00ed ocurren las roturas\u201d.<\/p>\n<p><strong>Plan archivado<\/strong><\/p>\n<p>Gennuso dijo que por ahora el acuerdo con\u00a0OPS\u00a0se va a mantener, porque el municipio ten\u00eda previsto iniciar en este mandato un plan de reequipamiento de m\u00e1quinas y camiones pero debieron postergarlo por la pandemia.<\/p>\n<p>La ca\u00edda de recaudaci\u00f3n y el cambio de prioridades le puso freno a la idea de incorporar al menos una motoniveladora y renovar camiones recolectores de basura con compras por leasing, seg\u00fan ten\u00eda proyectado el intendente, con el visto bueno de Hacienda.<\/p>\n<p>La operatoria se iba a canalizar mediante una l\u00ednea de financiamiento del banco BICE, pero por ahora qued\u00f3 postergada.<\/p>\n<h6>Fuente: R\u00edo Negro<\/h6>\n","protected":false},"excerpt":{"rendered":"<p>La municipalidad contin\u00faa utilizando la maquinaria de la firma cipole\u00f1a. La empresa se\u00f1ala que est\u00e1 pr\u00f3xima a levantar la quiebra y estima el pasivo de la ciudad andina en unos 250 millones de pesos.<\/p>\n","protected":false},"author":2,"featured_media":106592,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5],"tags":[11],"class_list":["post-106591","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-informe-economico","tag-rio-negro"],"_links":{"self":[{"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/posts\/106591","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/comments?post=106591"}],"version-history":[{"count":0,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/posts\/106591\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/media\/106592"}],"wp:attachment":[{"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/media?parent=106591"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/categories?post=106591"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/tags?post=106591"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}