{"id":108595,"date":"2020-10-28T14:07:05","date_gmt":"2020-10-28T17:07:05","guid":{"rendered":"http:\/\/argentinamunicipal.com.ar\/argentina\/?p=108595"},"modified":"2020-10-28T14:07:05","modified_gmt":"2020-10-28T17:07:05","slug":"el-intendente-de-guaymallen-aseguro-que-la-incertidumbre-economica-esta-frenando-el-50-de-la-obra-publica","status":"publish","type":"post","link":"http:\/\/argentinamunicipal.com.ar\/argentina\/el-intendente-de-guaymallen-aseguro-que-la-incertidumbre-economica-esta-frenando-el-50-de-la-obra-publica\/","title":{"rendered":"El intendente de Guaymall\u00e9n asegur\u00f3 que la incertidumbre econ\u00f3mica est\u00e1 frenando el 50% de la obra p\u00fablica"},"content":{"rendered":"<p>El intendente de Guaymall\u00e9n, Marcelino Iglesias, asegur\u00f3 que el precio del material de construcci\u00f3n frena la obra p\u00fablica de Mendoza<\/p>\n<p>La incertidumbre econ\u00f3mica y la consecuente especulaci\u00f3n nos est\u00e1n frenando la obra p\u00fablica de la comuna, que es el 50% de la obra p\u00fablica de la provincia. Yo no pido subsidios, pido que normalicen la econom\u00eda para que los que trabajamos podamos seguir trabajando. La actividad de la obra p\u00fablica genera mucho trabajo y eso hay que cuidarlo, si realmente le interesa al Gobierno nacional hay que apuntalar ese sector\u00bb, remarc\u00f3, enf\u00e1tico, el intendente de Guaymall\u00e9n, Marcelino Iglesias.<br \/>\nEn esa comuna, que fue\u00a0la primera en retomar la obra p\u00fablica en abril pasado cuando finaliz\u00f3 la primera etapa de la cuarentena. Hoy en Guaymall\u00e9n\u00a0hay 26 frentes de trabajo de distintas obras, ya sea de cord\u00f3n, cuneta y banquina, de remodelaci\u00f3n de una plaza o ampliaci\u00f3n de una repavimentaci\u00f3n, y se esperaba avanzar con la licitaci\u00f3n de 10 obras m\u00e1s, pero la falta de precios por la incertidumbre econ\u00f3mica hace que todo se ralentice o directamente se frene.<\/p>\n<p>\u00abLas empresas vienen a plantearme que no pueden hacer una alcantarilla si no tienen hierro, y pasa que hoy el hierro no tiene precio, nadie en un corral\u00f3n quiere arriesgarse a vender a un precio tal porque no sabe a qu\u00e9 precio deber\u00e1 reponer la mercader\u00eda. Eso est\u00e1 tentando contra las empresas de construcci\u00f3n que son generadoras de mano de obra\u00bb, sincer\u00f3 el jefe comunal.<\/p>\n<p>El hecho de que una obra se frene tiene consecuencias directas en la cantidad de personas que se emplean para esa tarea y los despidos o desvinculaciones son las primeras decisiones que se toman ante la falta de rentabilidad.<\/p>\n<p>\u00abUna empresa que trabajando a un ritmo sostenido empleaba a 8 cuadrillas de personal, a fin de mes trabajar\u00e1 s\u00f3lo con 5 cuadrillas porque no se justifica aquella cantidad de empleados y porque las empresas est\u00e1n crujiendo financieramente\u00bb, ejemplifican desde la comuna.<\/p>\n<p>\u00abHoy todas estas obras son un gran interrogante, entre ellas el tramo 3 y 4 del carril Godoy Cruz, por ejemplo, y lo peor es que nadie sabe a ciencia cierta cuando se normalizar\u00e1 esto. Que no lo sepa yo que soy el intendente de una comuna se entiende, pero que no lo sepa el presidente ni el ministro de Econom\u00eda, eso es grave y desconcertante\u00bb, dispar\u00f3 Iglesias.<\/p>\n<h6>Fuente: Uno<\/h6>\n","protected":false},"excerpt":{"rendered":"<p>El intendente de Guaymall\u00e9n, Marcelino Iglesias, asegur\u00f3 que el precio del material de construcci\u00f3n frena la obra p\u00fablica de Mendoza<\/p>\n","protected":false},"author":2,"featured_media":108596,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"tags":[31],"class_list":["post-108595","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-informe-politico","tag-mendoza"],"_links":{"self":[{"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/posts\/108595","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/comments?post=108595"}],"version-history":[{"count":0,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/posts\/108595\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/media\/108596"}],"wp:attachment":[{"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/media?parent=108595"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/categories?post=108595"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/tags?post=108595"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}