{"id":108700,"date":"2020-11-02T05:40:19","date_gmt":"2020-11-02T08:40:19","guid":{"rendered":"http:\/\/argentinamunicipal.com.ar\/argentina\/?p=108700"},"modified":"2020-10-30T10:21:25","modified_gmt":"2020-10-30T13:21:25","slug":"santa-rosa-abrio-paritarias-y-dio-un-aumento-del-15-y-un-bono-extra","status":"publish","type":"post","link":"http:\/\/argentinamunicipal.com.ar\/argentina\/santa-rosa-abrio-paritarias-y-dio-un-aumento-del-15-y-un-bono-extra\/","title":{"rendered":"Santa Rosa abri\u00f3 paritarias y dio un aumento del 15% y un bono extra"},"content":{"rendered":"<p>La intendenta de Santa Rosa, Flor Dest\u00e9fanis, decidi\u00f3 abrir paritarias para los empleados municipales. Dio un aumento del 15% m\u00e1s una suma fija hasta diciembre<\/p>\n<p>La intendenta de Santa Rosa, Flor Dest\u00e9fanis, fue la primera en abrir paritarias para los empleados municipales. Les dio un aumento del 15% y un bono extra hasta diciembre.<\/p>\n<p>En un a\u00f1o marcado por la pandemia y el derrumbe de la econom\u00eda, y con ella de la recaudaciones estatales, la comuna de Santa Rosa se convirti\u00f3 en la primera en abrir paritarias para los empleados municipales y elevar el alica\u00eddo sueldo de esos empleados.<br \/>\nEl acuerdo al que lleg\u00f3\u00a0la intendenta Flor Dest\u00e9fanis con el sindicato que los representa supone un aumento del 15% en una cuota a pagarse con el mes de octubre y que se cobrar\u00e1 el s\u00e1bado 1 de noviembre\u00a0y\u00a0dos sumas fijas, como bonos extra hasta diciembre cuando volver\u00e1 a discutirse otro incremento. Tambi\u00e9n se acord\u00f3 el pase a planta temporaria de 25 agentes de tr\u00e1nsito de esa comuna.<\/p>\n<p>El 2020 ha sido el a\u00f1o en el que nadie en el Estado ha osado hablar de apertura de paritarias, y a cada consulta period\u00edstica la respuesta es que \u00abse hace un esfuerzo por pagar los sueldos a tiempo\u00bb y se recuerda que se debi\u00f3 armar un cronograma diferido para pagar el medio aguinaldo a los empleados p\u00fablicos. Tanto es as\u00ed que la intergremial que nuclea a todos los empleados p\u00fablicos ya convoc\u00f3 a un paro para el pr\u00f3ximo 4 de Noviembre, en reclamo de que se inicie esa discusi\u00f3n salarial y se otorgue alg\u00fan aumento.<\/p>\n<p>En ese marco no es menor que una comuna haya decidido otorgar un\u00a0aumento para empleados municipales, cuyos magros sueldos pasar\u00e1n ahora a tener un b\u00e1sico de $9.245.<\/p>\n<p>\u00abNosotros ven\u00edamos pagando un bono de $2.000 que no era remunerativo pero sab\u00edamos que lo necesario era dar un aumento que fuera al b\u00e1sico e impactara en los \u00edtems que dependen de \u00e9l, por eso hicimos un gran esfuerzo para dar este aumento del 15% y otorgaremos dos bonos extras de entre $1.000 y $1.500 dependiendo de las categor\u00edas para los meses de octubre y noviembre porque volveremos a reunirnos con los gremios para analizar la situaci\u00f3n\u00bb, explic\u00f3 Dest\u00e9fanis.<\/p>\n<p>En esa comuna el aumento llegar\u00e1 a unos 762 empleados, que son quienes hoy est\u00e1n en planta permanente o temporaria, lo que le supone a las arcas comunales una inversi\u00f3n total de $2.319.970.<\/p>\n<p>Tambi\u00e9n se acord\u00f3 dar indumentaria de trabajo, priorizando a quienes se desempe\u00f1en en Obras y Servicios P\u00fablicos y conformar una comisi\u00f3n multisectorial para definir y controlar a qu\u00e9 empleados les corresponde cobrar el \u00edtem de riesgo por la actividad que desempe\u00f1en.<\/p>\n<h6>Fuente: Uno<\/h6>\n","protected":false},"excerpt":{"rendered":"<p>La intendenta de Santa Rosa, Flor Dest\u00e9fanis, decidi\u00f3 abrir paritarias para los empleados municipales. Dio un aumento del 15% m\u00e1s una suma fija hasta diciembre<\/p>\n","protected":false},"author":2,"featured_media":108702,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[31],"class_list":["post-108700","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-informe-sindical","tag-mendoza"],"_links":{"self":[{"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/posts\/108700","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/comments?post=108700"}],"version-history":[{"count":0,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/posts\/108700\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/media\/108702"}],"wp:attachment":[{"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/media?parent=108700"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/categories?post=108700"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/tags?post=108700"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}