{"id":115887,"date":"2021-06-25T05:00:31","date_gmt":"2021-06-25T08:00:31","guid":{"rendered":"http:\/\/argentinamunicipal.com.ar\/argentina\/?p=115887"},"modified":"2021-06-24T14:36:05","modified_gmt":"2021-06-24T17:36:05","slug":"fernandez-presento-un-plan-de-viviendas-para-adultos-mayores-estamos-dando-un-paso-etico","status":"publish","type":"post","link":"http:\/\/argentinamunicipal.com.ar\/argentina\/fernandez-presento-un-plan-de-viviendas-para-adultos-mayores-estamos-dando-un-paso-etico\/","title":{"rendered":"Fern\u00e1ndez present\u00f3 un plan de viviendas para adultos mayores: \u00abEstamos dando un paso \u00e9tico\u00bb"},"content":{"rendered":"<p>El Presidente encabez\u00f3 el lanzamiento de un plan destinado a la construcci\u00f3n y entrega de viviendas para mayores de 60 a\u00f1os sin acceso a una soluci\u00f3n habitacional o que no califiquen por la edad para ning\u00fan cr\u00e9dito hipotecario.<\/p>\n<p>El presidente Alberto Fern\u00e1ndez afirm\u00f3 que el Gobierno est\u00e1 \u00abdando un paso \u00e9tico que a la pol\u00edtica le hace bien, que es ocuparse de resolver el problema de d\u00f3nde viven los que llegan a la madurez y no tienen d\u00f3nde\u00bb, al encabezar el lanzamiento de un plan destinado a la construcci\u00f3n y entrega de viviendas para mayores de 60 a\u00f1os sin acceso a una soluci\u00f3n habitacional o que no califiquen por la edad para ning\u00fan cr\u00e9dito hipotecario.<\/p>\n<p>Adem\u00e1s,Fern\u00e1ndez asever\u00f3 que los argentinos \u00able vamos a ganar\u00bb al coronavirus, sostuvo que el plan de vacunaci\u00f3n \u00abes el ma\u00f1ana, el camino\u00bb y dijo que el gobierno nacional \u00abno va a parar hasta que el \u00faltimo argentino est\u00e9 vacunado\u00bb.<\/p>\n<p>\u00abVacunamos a casi todos los adultos mayores y ahora vamos a poner el m\u00e1ximo empe\u00f1o en vacunar a todos los argentinos, Esa es la puerta de salida y no est\u00e1 lejos. M\u00e1s all\u00e1 de las cr\u00edticas, mal intencionadas en muchos casos, seguimos buscando vacunas, seguimos trayendo vacunas y no vamos a parar hasta que el \u00faltimo argentino est\u00e9 vacunado\u00bb, dijo.<\/p>\n<h6>Fuente: Telam<\/h6>\n","protected":false},"excerpt":{"rendered":"<p>El Presidente encabez\u00f3 el lanzamiento de un plan destinado a la construcci\u00f3n y entrega de viviendas para mayores de 60 a\u00f1os sin acceso a una soluci\u00f3n habitacional o que no califiquen por la edad para ning\u00fan cr\u00e9dito hipotecario.<\/p>\n","protected":false},"author":2,"featured_media":115888,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[8],"tags":[21],"class_list":["post-115887","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-informe-nacional","tag-argentina"],"_links":{"self":[{"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/posts\/115887","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/comments?post=115887"}],"version-history":[{"count":0,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/posts\/115887\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/media\/115888"}],"wp:attachment":[{"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/media?parent=115887"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/categories?post=115887"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/tags?post=115887"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}