{"id":116003,"date":"2021-06-29T05:15:39","date_gmt":"2021-06-29T08:15:39","guid":{"rendered":"http:\/\/argentinamunicipal.com.ar\/argentina\/?p=116003"},"modified":"2021-06-28T20:17:19","modified_gmt":"2021-06-28T23:17:19","slug":"la-rioja-brindara-un-seguro-colectivo-para-trabajadores-de-la-salud","status":"publish","type":"post","link":"http:\/\/argentinamunicipal.com.ar\/argentina\/la-rioja-brindara-un-seguro-colectivo-para-trabajadores-de-la-salud\/","title":{"rendered":"La Rioja brindar\u00e1 un seguro colectivo para trabajadores de la salud"},"content":{"rendered":"<p>Ricardo Quintela, el gobernador de La Rioja, firm\u00f3 un convenio con autoridades del Banco Naci\u00f3n y de Naci\u00f3n Seguros de Retiro S.A para brindar una cobertura de Seguro Colectivo a todos los trabajadores de la salud. Estar\u00e1 disponible para los agentes p\u00fablicos de la provincia y de los municipios. Es decir que, adem\u00e1s del seguro obligatorio con el que cuentan, podr\u00e1n acceder a un seguro extra.<\/p>\n<p>C\u00f3mo ser\u00e1 financiado y para qui\u00e9nes<\/p>\n<p>La herramienta desarrollada &#8211; bajo el formato de un seguro de retiro colectivo &#8211; representa un instrumento de ahorro durante la vida activa de los trabajadores p\u00fablicos provinciales y\/o municipales y permitir\u00e1 construir una renta adicional a la jubilaci\u00f3n futura de los trabajadores.<\/p>\n<p>Se establece con el fin de otorgar un beneficio suplementario en el momento de acceder al retiro para aquellos trabajadores de la salud y adem\u00e1s a los agentes p\u00fablicos provinciales o municipales que adhieran voluntariamente al seguro. Se materializar\u00e1 mediante la emisi\u00f3n de una p\u00f3liza.<\/p>\n<p>El Seguro de Retiro colectivo ser\u00e1 financiado por el agente p\u00fablico con un peque\u00f1o aporte (del 1 por ciento) en su car\u00e1cter de activo. Por su parte, la provincia har\u00e1 un aporte mayor (del 2 por ciento), durante un tiempo y despu\u00e9s se invertir\u00e1n los aportes.<\/p>\n<p>En el sector salud,\u00a0pueden acceder adem\u00e1s de los profesionales; personal administrativo, de servicios generales y quienes se desempe\u00f1an en centros de salud, hospitales distritales y zonales. La intenci\u00f3n es incluir a todos aquellos que le hicieron frente a esta pandemia de la\u00a0covid-19.<\/p>\n<p>En busca de una pol\u00edtica federal<br \/>\nLa r\u00fabrica estuvo a cargo tambi\u00e9n de M\u00e1ximo Augusto Rodr\u00edguez, en representaci\u00f3n de Naci\u00f3n Seguros de Retiro S.A. y refrendada por el presidente del Banco de la Naci\u00f3n Argentina, Eduardo Hecker.<\/p>\n<p>Rodr\u00edguez expres\u00f3 que el convenio es una herramienta que se pone en marcha en el marco de las instrucciones del presidente Fern\u00e1ndez de federalizar cada pol\u00edtica de Estado que se ejecute. La presencia de la\u00a0pandemia de la covid-19\u00a0constituye una\u00a0\u00aboportunidad hist\u00f3rica para recomponer algo\u00bb de todo lo que hacen los trabajadores del sistema de salud.<\/p>\n<p>El jefe de Gabinete de Ministros de la provincia, Juan Luna, remarc\u00f3 en que el convenio\u00a0\u201cestar\u00e1 a disposici\u00f3n de los empleados p\u00fablicos, en especial del sector de la salud\u00bb y que \u201cser\u00e1 un beneficio que cobrar\u00e1n de car\u00e1cter optativo,\u00a0que podr\u00e1 funcionar como una prima o renta vitalicia\u201d.\u00a0Destac\u00f3, adem\u00e1s, la voluntad pol\u00edtica no solo de la Provincia, sino tambi\u00e9n de Naci\u00f3n Seguros de Retiro S.A. para llegar a este convenio.<\/p>\n<p>El gobernador remarc\u00f3 que durante el gobierno nacional anterior se perdieron muchas fuentes de trabajo. Durante su gesti\u00f3n, por el contrario, \u00abse recuperaron cientos de fuentes de trabajo, como el caso de la industria textil, tanto en Capital como en el interior\u00bb.<\/p>\n<h6>FUente: P\u00e1gina 12<\/h6>\n","protected":false},"excerpt":{"rendered":"<p>Ricardo Quintela, el gobernador de La Rioja, firm\u00f3 un convenio con autoridades del Banco Naci\u00f3n y de Naci\u00f3n Seguros de Retiro S.A para brindar una cobertura de Seguro Colectivo a todos los trabajadores de la salud.<\/p>\n","protected":false},"author":2,"featured_media":116004,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[65],"tags":[26],"class_list":["post-116003","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-provincias","tag-la-rioja"],"_links":{"self":[{"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/posts\/116003","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/comments?post=116003"}],"version-history":[{"count":0,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/posts\/116003\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/media\/116004"}],"wp:attachment":[{"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/media?parent=116003"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/categories?post=116003"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/tags?post=116003"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}