{"id":116813,"date":"2021-07-22T05:00:10","date_gmt":"2021-07-22T08:00:10","guid":{"rendered":"http:\/\/argentinamunicipal.com.ar\/argentina\/?p=116813"},"modified":"2021-07-22T06:27:30","modified_gmt":"2021-07-22T09:27:30","slug":"mendoza-activa-cinco-nuevos-pozos-de-petroleo-en-malargue","status":"publish","type":"post","link":"http:\/\/argentinamunicipal.com.ar\/argentina\/mendoza-activa-cinco-nuevos-pozos-de-petroleo-en-malargue\/","title":{"rendered":"Mendoza Activa: cinco nuevos pozos de petr\u00f3leo en Malarg\u00fce"},"content":{"rendered":"<p>Con el plan de reactivaci\u00f3n econ\u00f3mica provincial Mendoza Activa Hidrocarburos la empresa Pluspetrol abri\u00f3 cinco nuevos pozos de petr\u00f3leo en Malarg\u00fce<\/p>\n<p>Desde el gobierno provincial anunciaron que con la iniciativa Mendoza Activa, destinada a la reactivaci\u00f3n econ\u00f3mica incentivando la inversi\u00f3n privada -devuelve el 40% sobre el total invertido-, se ha reactivado la producci\u00f3n con cinco nuevos pozos de petr\u00f3leo en el Sur. Se trata de la empresa Pluspetrol, que produce el 24% del crudo de la provincial. El programa lanzado a mediados del 2020, en plena pandemia ayud\u00f3 a mantener a las empresas activas, conservando as\u00ed fuentes de trabajo, y en medio de los vaivenes del precio del crudo, el sector hidrocarbur\u00edfero en Mendoza sigue creciendo a paso firme: a los $2.200 millones en inversiones logrados en la primera etapa del programa Mendoza Activa Hidrocarburos se suman cinco nuevas perforaciones.<\/p>\n<p><strong>Cinco nuevos pozos en Malarg\u00fce<\/strong><br \/>\nPluspetrol, que produce el 24% del crudo que se extrae en la provincia, iniciar\u00e1 obras en cinco pozos: tres en sus concesiones de Jag\u00fcel Casa de Piedra, y dos en Gobernador Ayala, ambos en Malarg\u00fce.\u00a0Estas obras se suman a las presentadas por la empresa en el marco de Mendoza Activa, con $343 millones que se invierten en la perforaci\u00f3n de otros siete pozos nuevos\u00a0y un trabajo de abandono de pozo, con un incremento estimado de producci\u00f3n de 55 metros c\u00fabicos por d\u00eda.<\/p>\n<p>Las obras de estos cinco pozos nuevos comenzar\u00e1n este mes (julio) y seguir\u00e1n durante agosto. Los trabajos de perforaci\u00f3n son los que mueven m\u00e1s empleos y servicios en el sector.<\/p>\n<p>\u201cEs muy importante ver esta recuperaci\u00f3n. Hist\u00f3ricamente, en Mendoza, la mayor\u00eda del empleo y el trabajo a pymes se da en trabajos de perforaci\u00f3n de pozos\u201d, explic\u00f3 el director de Hidrocarburos de la provincia, Estanislao Schilardi, quien agreg\u00f3: \u00abTener cinco perforaciones nuevas en menos de un mes nos da da la pauta de la reactivaci\u00f3n del sector\u00bb.<\/p>\n<p><strong>Acciones proactivas para la industria y el trabajo<\/strong><br \/>\nCuando comenz\u00f3 la pandemia y se desat\u00f3 la crisis del precio del crudo, en 2020,\u00a0el gobierno de Rodolfo Su\u00e1rez implement\u00f3 una serie de acciones para la industria hidrocarbur\u00edfera que hoy est\u00e1n dando sus frutos.<\/p>\n<p>Adem\u00e1s de\u00a0lograr que YPF volviera a comprar petr\u00f3leo a productores locales, ya que durante el aislamiento hab\u00eda suspendido la compra, y que se estableciera un precio local del barril, se comenz\u00f3 a instrumentar el plan Mendoza Activa para el sector.<\/p>\n<p>El plan, aprobado por\u00a0la Legislatura a fines de 2020, logr\u00f3, en tres convocatorias lanzadas desde febrero, inversiones por $2.200 millones de pesos, superando las expectativas de lo previsto por ley.<\/p>\n<p>Por eso, el Ministerio de Econom\u00eda y Energ\u00eda envi\u00f3 la segunda etapa a la Legislatura, que se convirti\u00f3 en ley, esta vez con una previsi\u00f3n de inversiones de $7.000 millones.<\/p>\n<p>Una de las condiciones de la ley es el \u201ccompre mendocino\u201d, es decir que se contraten trabajadores, pymes y suministros locales.<\/p>\n<p>Con un funcionamiento similar al de Mendoza Activa, el Estado mendocino reintegra hasta el 40% de las inversiones que se presentan. Estos reintegros se utilizan para liquidar Ingresos Brutos y Regal\u00edas. Con devoluciones y todo, el plan logra que se aumente la recaudaci\u00f3n y que se creen trabajos directos e indirectos para los mendocinos.<\/p>\n<p><strong>Otras explotaciones activadas<\/strong><br \/>\nEn el marco de este programa comenzaron nuevamente las perforaciones en Mendoza. Ya est\u00e1n en marcha dos proyectos presentados en la tercera convocatoria del programa.<\/p>\n<p>Uno es de\u00a0Hattrick Energy, en Lindero de Piedra (Malarg\u00fce), donde se inyectar\u00e1n $187 millones para perforaci\u00f3n de un pozo, un\u00a0pulling\u00a0y estimulaciones de crudo extra pesado.<\/p>\n<p>\u201cLa perforaci\u00f3n en Lindero de Piedra implica una inversi\u00f3n de $150 millones y se estima una tasa de producci\u00f3n de 15 metros c\u00fabicos por d\u00eda (m3\/d\u00eda)\u201d, explic\u00f3 Schilardi.<\/p>\n<p>Las otras dos nuevas perforaciones son las siete de Pluspetrol, a las que se agregan las cinco nuevas en Malarg\u00fce.<\/p>\n<p>Estas inversiones\u00a0se suman a las ya presentadas en la primera y la segunda convocatoria por YPF SA, la UTE Emesa-Hattrick y Aconcagua Energ\u00eda.<\/p>\n<h6>Fuente: Uno<\/h6>\n","protected":false},"excerpt":{"rendered":"<p>Con el plan de reactivaci\u00f3n econ\u00f3mica provincial Mendoza Activa Hidrocarburos la empresa Pluspetrol abri\u00f3 cinco nuevos pozos de petr\u00f3leo en Malarg\u00fce<\/p>\n","protected":false},"author":2,"featured_media":116814,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[31],"class_list":["post-116813","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-informe-municipal","tag-mendoza"],"_links":{"self":[{"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/posts\/116813","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/comments?post=116813"}],"version-history":[{"count":0,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/posts\/116813\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/media\/116814"}],"wp:attachment":[{"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/media?parent=116813"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/categories?post=116813"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/tags?post=116813"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}