{"id":136608,"date":"2023-06-01T05:40:39","date_gmt":"2023-06-01T08:40:39","guid":{"rendered":"http:\/\/argentinamunicipal.com.ar\/argentina\/?p=136608"},"modified":"2023-05-31T17:42:37","modified_gmt":"2023-05-31T20:42:37","slug":"manana-se-anunciaria-la-recomposicion-salarial-para-los-trabajadores-municipales-de-caleta-olivia","status":"publish","type":"post","link":"http:\/\/argentinamunicipal.com.ar\/argentina\/manana-se-anunciaria-la-recomposicion-salarial-para-los-trabajadores-municipales-de-caleta-olivia\/","title":{"rendered":"Ma\u00f1ana se anunciar\u00eda la recomposici\u00f3n salarial para los trabajadores municipales de Caleta Olivia"},"content":{"rendered":"<p>Julian Carrizo se reuni\u00f3 con el intendente Fernando Cotillo. Por las redes del gremio se adelant\u00f3 que \u00abConfiamos en que en el d\u00eda de ma\u00f1ana, mi\u00e9rcoles, se lograr\u00e1 un acuerdo definitivo que refleje nuestros intereses y necesidades\u00bb.<\/p>\n<p>En el posteo destinado a los compa\u00f1eros afiliados y afiliadas del Sindicato de Obreros y Empleados Municipales de Caleta Olivia expresa que \u00abNuestro Secretario General, compa\u00f1ero\u00a0Juli\u00e1n Carrizo, ha estado trabajando arduamente junto a la Comisi\u00f3n Directiva y todo el equipo\u00a0de trabajo para lograr mejoras en nuestras condiciones laborales y salariales\u00bb.<\/p>\n<p>Agrega que \u00abEn los \u00faltimos d\u00edas, el secretario general\u00a0Juli\u00e1n Carrizo ha mantenido un di\u00e1logo constructivo con el Se\u00f1or Intendente Municipal Fernando Cotillo y su gabinete del Ejecutivo comunal, con el objetivo de llegar a un acuerdo que beneficie a todos los compa\u00f1eros municipales\u00bb.<\/p>\n<p>\u00abLas negociaciones han avanzado significativamente y se est\u00e1n analizando detalladamente el contenido del Acta Acuerdo\u00bb.<\/p>\n<p>Adelanta que \u00abel\u00a0d\u00eda de ma\u00f1ana, mi\u00e9rcoles, se lograr\u00e1 un acuerdo definitivo que refleje nuestros intereses y necesidades.\u00a0Agradecemos el apoyo y la paciencia durante todo este proceso.\u00a0Sabemos que muchos de ustedes han estado expectantes por los avances en este tema y queremos asegurarles que estamos trabajando diligentemente para garantizar mejoras significativas\u00bb.<\/p>\n<p>\u00abContinuaremos inform\u00e1ndoles sobre los avances de las negociaciones y los resultados obtenidos. Nuestra prioridad es velar por el bienestar de cada uno de ustedes\u00bb.<\/p>\n<h6>Fuente: lavanguardianoticias.com.ar<\/h6>\n","protected":false},"excerpt":{"rendered":"<p>Julian Carrizo se reuni\u00f3 con el intendente Fernando Cotillo. Por las redes del gremio se adelant\u00f3 que \u00abConfiamos en que en el d\u00eda de ma\u00f1ana, mi\u00e9rcoles, se lograr\u00e1 un acuerdo definitivo que refleje nuestros intereses y necesidades\u00bb.<\/p>\n","protected":false},"author":2,"featured_media":136609,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[29],"class_list":["post-136608","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-informe-sindical","tag-santa-cruz"],"_links":{"self":[{"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/posts\/136608","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/comments?post=136608"}],"version-history":[{"count":0,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/posts\/136608\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/media\/136609"}],"wp:attachment":[{"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/media?parent=136608"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/categories?post=136608"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/tags?post=136608"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}