{"id":136903,"date":"2023-06-08T05:26:23","date_gmt":"2023-06-08T08:26:23","guid":{"rendered":"http:\/\/argentinamunicipal.com.ar\/argentina\/?p=136903"},"modified":"2023-06-07T19:29:53","modified_gmt":"2023-06-07T22:29:53","slug":"vuoto-y-cabandie-avanzan-en-la-creacion-del-centro-ambiental-ushuaia","status":"publish","type":"post","link":"http:\/\/argentinamunicipal.com.ar\/argentina\/vuoto-y-cabandie-avanzan-en-la-creacion-del-centro-ambiental-ushuaia\/","title":{"rendered":"Vuoto y Cabandi\u00e9 avanzan en la creaci\u00f3n del Centro Ambiental Ushuaia"},"content":{"rendered":"<p>El Intendente de Ushuaia y el Ministro de Medio Ambiente de la Naci\u00f3n destacaron la importancia del proyecto que contempla una planta de compactaci\u00f3n y enfardado de residuos provenientes del rechazo de la separaci\u00f3n y recuperaci\u00f3n; una estaci\u00f3n de carga y transferencia de fardos; un \u00e1rea para compostaje; una planta de tratamiento de neum\u00e1ticos fuera de uso; una planta de tratamiento de restos de poda y origen forestal, entre otros espacios.<\/p>\n<p>El intendente de Ushuaia, Walter Vuoto, mantuvo un encuentro con el ministro de Medio Ambiente de la Naci\u00f3n, Juan Cabandi\u00e9, con el objetivo de \u201cavanzar en nuestra visi\u00f3n de una Ushuaia sostenible y m\u00e1s verde\u201d, explic\u00f3 el Jefe comunal.<\/p>\n<p>Durante la reuni\u00f3n dialogaron, entre otros temas, sobre el proyecto de desarrollo del Centro Ambiental Ushuaia, con financiamiento del Banco Interamericano de Desarrollo (BID). \u201cFue una reuni\u00f3n productiva en la que renovamos el compromiso de nuestra gesti\u00f3n con el desarrollo sostenible de la ciudad\u201d, destac\u00f3 Vuoto; y agreg\u00f3 que \u201cavanzamos sobre el trabajo en conjunto para seguir progresando en el proyecto de instalaci\u00f3n de una planta procesadora de residuos en la ciudad\u201d.<\/p>\n<p>El futuro Centro Ambiental Ushuaia contempla distintos espacios como una planta de compactaci\u00f3n y enfardado de residuos provenientes del rechazo de la separaci\u00f3n y recuperaci\u00f3n; una estaci\u00f3n de carga y transferencia de fardos para disposici\u00f3n final; un \u00e1rea para el desarrollo a futuro de compostaje a nivel municipal; una planta de tratamiento de neum\u00e1ticos fuera de uso; una planta de tratamiento de restos de poda y origen forestal; y un sal\u00f3n de usos m\u00faltiples para la capacitaci\u00f3n de operarios y el desarrollo de actividades de extensi\u00f3n y relaciones con la comunidad.<\/p>\n<p>En la ocasi\u00f3n, el Intendente de Ushuaia y el ministro de Ambiente de la Naci\u00f3n tambi\u00e9n hablaron sobre la luminaria LED que se instalar\u00e1 en la bicisenda lindera al bulevar de acceso al aeropuerto internacional Malvinas Argentinas; tecnolog\u00eda de bajo consumo que permitir\u00e1 reducir la emisi\u00f3n de gases de efecto invernadero y adem\u00e1s, garantizar\u00e1 una buena visibilidad a los ciclistas sin generar molestias a peatones, fauna y conductores de veh\u00edculos.<\/p>\n<h6>Fuente: El Diario del Fin del Mundo<\/h6>\n","protected":false},"excerpt":{"rendered":"<p>El futuro Centro Ambiental Ushuaia contempla distintos espacios como una planta de compactaci\u00f3n y enfardado de residuos provenientes del rechazo de la separaci\u00f3n y recuperaci\u00f3n; una estaci\u00f3n de carga y transferencia de fardos para disposici\u00f3n final<\/p>\n","protected":false},"author":2,"featured_media":136904,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[34],"class_list":["post-136903","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-informe-municipal","tag-tierra-del-fuego"],"_links":{"self":[{"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/posts\/136903","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/comments?post=136903"}],"version-history":[{"count":0,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/posts\/136903\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/media\/136904"}],"wp:attachment":[{"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/media?parent=136903"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/categories?post=136903"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/tags?post=136903"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}