{"id":20314,"date":"2014-12-01T10:24:05","date_gmt":"2014-12-01T13:24:05","guid":{"rendered":"http:\/\/argentinamunicipal.com.ar\/argentina\/?p=20314"},"modified":"2014-12-01T11:03:12","modified_gmt":"2014-12-01T14:03:12","slug":"presupuesto-participativo-en-la-plata-votaron-casi-34ooo-vecinos","status":"publish","type":"post","link":"http:\/\/argentinamunicipal.com.ar\/argentina\/presupuesto-participativo-en-la-plata-votaron-casi-34ooo-vecinos\/","title":{"rendered":"Presupuesto Participativo en La Plata: votaron casi 34000 vecinos"},"content":{"rendered":"<p><a href=\"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-content\/uploads\/2014\/12\/19563.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-full wp-image-20315\" src=\"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-content\/uploads\/2014\/12\/19563.jpg\" alt=\"19563\" width=\"356\" height=\"238\" srcset=\"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-content\/uploads\/2014\/12\/19563.jpg 356w, http:\/\/argentinamunicipal.com.ar\/argentina\/wp-content\/uploads\/2014\/12\/19563-300x200.jpg 300w\" sizes=\"auto, (max-width: 356px) 100vw, 356px\" \/><\/a>Cerca de 34.000 vecinos fueron a las urnas este fin de semana<\/p>\n<p>Con un marcado predominio de las obras de pavimentaci\u00f3n, alumbrado y alivio hidr\u00e1ulico, casi 34 mil platenses eligieron cu\u00e1les proyectos consideran de ejecuci\u00f3n prioritaria en sus barrios y localidades en el marco de la edici\u00f3n 2015 del Presupuesto Participativo municipal.<\/p>\n<p>Despu\u00e9s de un s\u00e1bado que convoc\u00f3 a poco m\u00e1s de 15 mil votantes, el temporal aquiet\u00f3 a los vecinos de la Ciudad con viento, fr\u00edo y la amenaza permanente de nuevas lluvias, dejando vac\u00edas las calles. Sin embargo, de acuerdo con la Comuna, sufragaron ayer otras 18 mil personas, entre las 8 y las 19 en los treinta centros habilitados entre el casco hist\u00f3rico y su periferia.<\/p>\n<h3>150 PROPUESTAS<\/h3>\n<p>Fueron 150 las propuestas sobre la mesa, impresas en papeletas blancas y verdes, a raz\u00f3n de cinco por zona. Quien se acercaba a emitir su sufragio deb\u00eda marcar con una cruz la elegida y depositarla en una urna previa exhibici\u00f3n del documento.<\/p>\n<p>En este contexto, los c\u00f3mputos oficiales determinaron que los proyectos que se concreten a lo largo de 2015 ser\u00e1n los siguientes: en Abasto, el n\u00famero 102 (repavimentaci\u00f3n, luminarias, asfalto y mejorado en calles de la localidad); en Arturo Segu\u00ed, el 153 (asfalto); en Casco \u201cI\u201d, el 174 (luminarias, mobiliario urbano y cestos en avenida 38, sem\u00e1foro en diagonal 74 y 116 y luminarias en 120 de 32 a 44); y en Casco \u201cII\u201d, el 204 (recuperaci\u00f3n del espacio p\u00fablico en 120 de 66 a 72, luminarias en 66 entre 1 y 122 y sem\u00e1foro en 120 y 66).<\/p>\n<p>En City Bell \u201cI\u201d se impuso el proyecto 225 (luminarias y c\u00e1maras de seguridad en establecimientos educativos); en City Bell \u201cII\u201d, el 253 (obras hidr\u00e1ulicas); en Angel Etcheverry, el 300 (asfalto, luminarias y mejorado); en Gonnet \u201cI\u201d, el 332 (asfalto y mejorado); en Gonnet \u201cII\u201d, el 353 (asfalto, mejorado y obra hidr\u00e1ulica); y en Jos\u00e9 Hern\u00e1ndez, el 404 (asfalto y mejorado).<\/p>\n<p>En Los Hornos \u201cI\u201d, el 426 (repavimentaci\u00f3n, mejorado, luminarias, y puesta en valor de parque \u201cJorge Julio L\u00f3pez\u201d). En Los Hornos \u201cII\u201d, el 450 (asfalto, mejorado, luminarias puente en 145 entre 54 y 55); en Lisandro Olmos \u201cI\u201d, el 478 (Construcci\u00f3n de Casa del Ni\u00f1o y Jard\u00edn Maternal, juegos, luminarias, asfalto y puesta en valor de plaza de 33 y 184); en Lisandro Olmos \u201cII\u201d, el 500 (ensanche de 161 entre 44 y 45 con rambla, veredas, luminarias y refugios, asfalto, mejorado, bacheo y cartel de bienvenida a la localidad en 161 y 44).<\/p>\n<p>En Ringuelet, el 528 (luminarias, c\u00e1maras de seguridad, remodelaci\u00f3n y ampliaci\u00f3n del comedor comunitario municipal \u201cHugo Stunz\u201d); en Melchor Romero \u201cI\u201d, el 552 (asfalto y c\u00e1maras de seguridad); en Melchor Romero \u201cII\u201d, el 576 (asfalto); en San Carlos \u201cI\u201d, el 604 (asfalto, mejorado, puente en148 y 50 y c\u00e1maras de seguridad); en San Carlos \u201cII\u201d, el 626 (asfalto, luminarias, refugios, c\u00e1maras de seguridad y puente en 140 y arroyo El Gato); en San Lorenzo \u201cI\u201d, el 651 (puesta en valor de rotonda de 72 y 31 y espacios verdes, rambla de avenida 31 entre 72 y 76, forestaci\u00f3n, mobiliario urbana, luminarias, sendas peatonales, restauraci\u00f3n de monumentos, veredas en rotonda, y c\u00e1maras de seguridad); y en San Lorenzo \u201cII\u201d, el 677 (asfalto y mejorado).<\/p>\n<p>En Tolosa \u201cI\u201d, el 701 (c\u00e1maras de seguridad, luminarias, sem\u00e1foros, cord\u00f3n cuneta y construcci\u00f3n de ermita en 17 y 524; en Tolosa \u201cII\u201d el 730 (obra hidr\u00e1ulica, luminarias, veredas comunitarias y apertura de calle 10 entre avenida Ant\u00e1rtida y 8). En Villa Elisa \u201cI\u201d, el 753 (asfalto, mejorado y luminarias); en Villa Elisa \u201cII\u201d, el 775 (asfalto, mejorado, fresado, obra hidr\u00e1ulica, luminarias, circuito aer\u00f3bico en calle 2, paso a nivel en 422 bis, puesta en valor de plaza Los Zorzales, veredas, separador vial en diagonal 424 y Centenario, y red de agua potable).<\/p>\n<p>Por \u00faltimo, en Villa Elvira \u201cI\u201d gan\u00f3 el proyecto 802 (sem\u00e1foro con giro en 7 y 89, refugios, se\u00f1alizaci\u00f3n de carriles en 1, 7 y 120, asfalto en acceso a barrio 19 de Febrero, puesta en valor de avenida 80, luminarias, circuito aer\u00f3bico en calle 10, plaza de 3 y 86); y en Villa Elvira \u201cII\u201d, el 826 (asfalto, mejorado, puesta en valor de plaza de ruta 11 y 604, y arreglo de puente en 92 y 118).<\/p>\n<p><strong>INCIDENTE EN VILLA ELVIRA <\/strong><\/p>\n<p>El desarrollo de la jornada no estuvo exento de algunas pol\u00e9micas e incidentes, como los que se desarrollaron en la Escuela T\u00e9cnica N\u00ba5, de 76 entre 7 y 8, y obligaron a la polic\u00eda a intervenir para calmar los \u00e1nimos. Seg\u00fan relataron vecinos del lugar, el arribo de un colectivo con \u201cgente de otros barrios\u201d, presuntamente para emitir su voto en esa zona de Villa Elvira, gener\u00f3 fuertes discusiones entre los impulsores de sendas iniciativas y hubo escenas de pugilato hasta que personal de la comisar\u00eda 8va restaur\u00f3 el orden.<\/p>\n<h3>33.890<\/h3>\n<p>Fueron, de acuerdo con los c\u00f3mputos oficiales, los platenses que se acercaron a emitir sus votos entre el s\u00e1bado y ayer en el marco de las elecciones del Presupuesto Participativo 2015. A fines de 2013, la convocatoria del municipio hab\u00eda movilizado alrededor de 32 mil voluntades de vecinos<\/p>\n<h6>Fuente: El D\u00eda<\/h6>\n","protected":false},"excerpt":{"rendered":"<p>Cerca de 34.000 vecinos fueron a las urnas este fin de semana Con un marcado predominio de las obras de pavimentaci\u00f3n, alumbrado y alivio hidr\u00e1ulico, casi 34 mil platenses eligieron cu\u00e1les proyectos consideran de ejecuci\u00f3n prioritaria en sus barrios y localidades en el marco de la edici\u00f3n 2015 del Presupuesto Participativo municipal. Despu\u00e9s de un<\/p>\n","protected":false},"author":2,"featured_media":20315,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2,4],"tags":[12],"class_list":["post-20314","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-informe-municipal","category-informe-politico","tag-buenos-aires"],"_links":{"self":[{"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/posts\/20314","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/comments?post=20314"}],"version-history":[{"count":0,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/posts\/20314\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/media\/20315"}],"wp:attachment":[{"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/media?parent=20314"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/categories?post=20314"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/tags?post=20314"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}