{"id":31001,"date":"2015-06-08T08:48:49","date_gmt":"2015-06-08T11:48:49","guid":{"rendered":"http:\/\/argentinamunicipal.com.ar\/argentina\/?p=31001"},"modified":"2015-06-08T09:00:09","modified_gmt":"2015-06-08T12:00:09","slug":"en-medio-de-un-boicot-y-actos-de-violencia-votaron-en-mexico","status":"publish","type":"post","link":"http:\/\/argentinamunicipal.com.ar\/argentina\/en-medio-de-un-boicot-y-actos-de-violencia-votaron-en-mexico\/","title":{"rendered":"En medio de un boicot y actos de violencia votaron en M\u00e9xico"},"content":{"rendered":"<p><a href=\"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-content\/uploads\/2015\/06\/672892_gd.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-31013\" src=\"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-content\/uploads\/2015\/06\/672892_gd.jpg\" alt=\"672892_gd\" width=\"592\" height=\"395\" srcset=\"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-content\/uploads\/2015\/06\/672892_gd.jpg 592w, http:\/\/argentinamunicipal.com.ar\/argentina\/wp-content\/uploads\/2015\/06\/672892_gd-300x200.jpg 300w\" sizes=\"auto, (max-width: 592px) 100vw, 592px\" \/><\/a><br \/>\nLos padres de los 43 estudiantes desaparecidos participaron de un movimiento para suspender los comicios en Tixtla. Miles de agentes de seguridad y militares movilizados.<\/p>\n<p>La quema de material electoral y las protestas marcaron las elecciones intermedias en diversos puntos de M\u00e9xico aunque en el resto de pa\u00eds las votaciones transcurrieron con relativa normalidad ayer pese al llamamiento al boicot convocado por diversos grupos sociales, el temor a otros actos violentos y el descontento generalizado de la poblaci\u00f3n que se podr\u00eda traducir en una alta abstenci\u00f3n.<\/p>\n<p>El gobierno federal realiz\u00f3 un gran despliegue del ej\u00e9rcito, la marina y la polic\u00eda federal sobre todo en los estados de Chiapas, Oaxaca, Guerrero y Michoac\u00e1n, y realiz\u00f3 patrullajes tanto a\u00e9reos como terrestres en las zonas m\u00e1s conflictivas pero el presidente Enrique Pe\u00f1a Nieto subray\u00f3 que los incidentes fueron \u201caislados\u201d.<\/p>\n<p>M\u00e1s de 83 millones de mexicanos elegieron a los 500 miembros de la C\u00e1mara de Diputados, los gobiernos en nueve de 31 estados, adem\u00e1s de cientos de alcaldes y legisladores locales en unas votaciones que se consideran una especie de refer\u00e9ndum sobre la gesti\u00f3n del presidente Enrique Pe\u00f1a Nieto, en el poder desde diciembre de 2012.<\/p>\n<p>En Chiapas, Oaxaca, Guerrero hubo quema de boletas, urnas de votaci\u00f3n y diferente material electoral, y se registraron protestas de quienes llamaban al boicot y hubo enfrentamientos espor\u00e1dicos que concluyeron con la detenci\u00f3n de 88 personas en Oaxaca y 11 en Chiapas, informaron sus respectivas fiscal\u00edas<\/p>\n<p>El secretario de Gobernaci\u00f3n, Miguel Angel Osorio Chong, apunt\u00f3 como el incidente m\u00e1s \u201ccomplicado\u201d ocurri\u00f3 en el municipio de Tixtla, en el sure\u00f1o estado de Guerrero, donde estudiantes, maestros y padres de los 43 alumnos de magisterio desaparecidos en septiembre en ese estado -cuya escuela est\u00e1 en este municipio- se acercaron a las mesas de votaci\u00f3n e intentaron convencer a los funcionarios para que les entregaran las boletas, que despu\u00e9s quemaron como forma de protesta.<\/p>\n<p>\u201cNosotros queremos que primero aparezcan los j\u00f3venes y despu\u00e9s que haya elecciones\u201d, dijo Martina de la Cruz, madre de uno de los desaparecidos.<\/p>\n<p><a href=\"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-content\/uploads\/2015\/06\/mexico1_655x438.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter  wp-image-31002\" src=\"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-content\/uploads\/2015\/06\/mexico1_655x438.jpg\" alt=\"mexico1_655x438\" width=\"567\" height=\"379\" srcset=\"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-content\/uploads\/2015\/06\/mexico1_655x438.jpg 655w, http:\/\/argentinamunicipal.com.ar\/argentina\/wp-content\/uploads\/2015\/06\/mexico1_655x438-300x201.jpg 300w\" sizes=\"auto, (max-width: 567px) 100vw, 567px\" \/><\/a><\/p>\n<p>Poco despu\u00e9s se registr\u00f3 un enfrentamiento con palos y piedras entre los manifestantes que llamaban al boicot, muchos con la cara cubierta con pasamonta\u00f1as, y alrededor de un millar de personas que dijeron se opon\u00edan al boicot y deseaban defender su derecho al voto.<\/p>\n<p>\u201cTixtla ya est\u00e1 cansada de esta gente\u201d, dijo una enfermera que no quiso revelar su nombre.<\/p>\n<p>En los actos de boicot m\u00e1s violentos participaron tambi\u00e9n miembros de la Coordinadora Nacional de Trabajadores de la Educaci\u00f3n (CNTE), un sindicato de maestros que se opone a la reforma educativa del gobierno y presente sobre todo en los estados del suroeste.<\/p>\n<p>En Oaxaca, miembros de este grupo, todos con la cara cubierta o con m\u00e1scaras de Anonimus, vaciaron un cami\u00f3n con papeler\u00eda electoral, boletas, urnas y mesas de votaciones en pleno z\u00f3calo y lo prendieron fuego a todo al grito de \u00ab\u00a1Vivos se los llevaron, vivos los queremos!\u00bb, en alusi\u00f3n a los 43 estudiantes desaparecidos en Guerrero.<\/p>\n<p>Mientras, en las afueras de esta ciudad colonial, esperaban unos 50 veh\u00edculos militares pesados listos para intervenir ante cualquier incidencia y un helic\u00f3ptero de la marina sobrevolaba la zona.<\/p>\n<h6>Fuente: Los Andes<\/h6>\n","protected":false},"excerpt":{"rendered":"<p>Los padres de los 43 estudiantes desaparecidos participaron de un movimiento para suspender los comicios en Tixtla. Miles de agentes de seguridad y militares movilizados. La quema de material electoral y las protestas marcaron las elecciones intermedias en diversos puntos de M\u00e9xico aunque en el resto de pa\u00eds las votaciones transcurrieron con relativa normalidad ayer<\/p>\n","protected":false},"author":2,"featured_media":31013,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[22],"tags":[57],"class_list":["post-31001","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-el-mundo","tag-el-mundo"],"_links":{"self":[{"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/posts\/31001","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/comments?post=31001"}],"version-history":[{"count":0,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/posts\/31001\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/media\/31013"}],"wp:attachment":[{"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/media?parent=31001"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/categories?post=31001"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/tags?post=31001"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}