{"id":31242,"date":"2015-06-11T08:37:31","date_gmt":"2015-06-11T11:37:31","guid":{"rendered":"http:\/\/argentinamunicipal.com.ar\/argentina\/?p=31242"},"modified":"2015-06-11T08:37:31","modified_gmt":"2015-06-11T11:37:31","slug":"premian-programa-ambiental-de-guaymallen","status":"publish","type":"post","link":"http:\/\/argentinamunicipal.com.ar\/argentina\/premian-programa-ambiental-de-guaymallen\/","title":{"rendered":"Premian programa ambiental de Guaymall\u00e9n"},"content":{"rendered":"<p><a href=\"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-content\/uploads\/2015\/06\/1-Men-Guaymallenportada.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-31243\" src=\"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-content\/uploads\/2015\/06\/1-Men-Guaymallenportada.jpg\" alt=\"1-Men-Guaymallenportada\" width=\"641\" height=\"330\" srcset=\"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-content\/uploads\/2015\/06\/1-Men-Guaymallenportada.jpg 641w, http:\/\/argentinamunicipal.com.ar\/argentina\/wp-content\/uploads\/2015\/06\/1-Men-Guaymallenportada-300x154.jpg 300w\" sizes=\"auto, (max-width: 641px) 100vw, 641px\" \/><\/a><br \/>\nLa Universidad de Congreso distingui\u00f3 al programa municipal Guaymall\u00e9n Ecol\u00f3gico con la Menci\u00f3n al Compromiso Ambiental, en el marco del D\u00eda Mundial del Ambiente, celebrado cada 5 de junio en todo el planeta. Desde su puesta en marcha, en diciembre de 2014, Guaymall\u00e9n<\/p>\n<p>Ecol\u00f3gico logr\u00f3 erradicar 30 carretelas del radio urbano, con el objetivo de eliminar la tracci\u00f3n a sangre. Adem\u00e1s, el programa apunta a concientizar a la poblaci\u00f3n acerca de los beneficios de la recolecci\u00f3n diferenciada e incluir socialmente a los recuperadores urbanos, a trav\u00e9s de la mejora de las condiciones de trabajo y la formalizaci\u00f3n de su tarea.<\/p>\n<p>La Menci\u00f3n al Compromiso Ambiental que otorga la Universidad de Congreso, reconoce a miembros de la comunidad que contribuyan a la preservaci\u00f3n del ambiente.<\/p>\n<p>\u00abEl fin del premio es destacar las acciones para que sean un ejemplo a seguir, fomentando la conciencia hacia el medio ambiente\u00bb, se\u00f1alaron sus autoridades.<\/p>\n<h6>Fuente: Los Andes<\/h6>\n","protected":false},"excerpt":{"rendered":"<p>La Universidad de Congreso distingui\u00f3 al programa municipal Guaymall\u00e9n Ecol\u00f3gico con la Menci\u00f3n al Compromiso Ambiental, en el marco del D\u00eda Mundial del Ambiente, celebrado cada 5 de junio en todo el planeta. Desde su puesta en marcha, en diciembre de 2014, Guaymall\u00e9n Ecol\u00f3gico logr\u00f3 erradicar 30 carretelas del radio urbano, con el objetivo de<\/p>\n","protected":false},"author":2,"featured_media":31243,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[31],"class_list":["post-31242","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-informe-municipal","tag-mendoza"],"_links":{"self":[{"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/posts\/31242","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/comments?post=31242"}],"version-history":[{"count":0,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/posts\/31242\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/media\/31243"}],"wp:attachment":[{"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/media?parent=31242"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/categories?post=31242"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/tags?post=31242"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}