{"id":32860,"date":"2015-07-11T09:16:34","date_gmt":"2015-07-11T12:16:34","guid":{"rendered":"http:\/\/argentinamunicipal.com.ar\/argentina\/?p=32860"},"modified":"2015-07-11T09:16:34","modified_gmt":"2015-07-11T12:16:34","slug":"la-nacion-declaro-la-emergencia-agropecuaria-por-granizo-y-heladas-en-mendoza","status":"publish","type":"post","link":"http:\/\/argentinamunicipal.com.ar\/argentina\/la-nacion-declaro-la-emergencia-agropecuaria-por-granizo-y-heladas-en-mendoza\/","title":{"rendered":"La Naci\u00f3n declar\u00f3 la Emergencia Agropecuaria por granizo y heladas en Mendoza"},"content":{"rendered":"<p><a href=\"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-content\/uploads\/2015\/07\/i11095-olivos-helada-631.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-32861\" src=\"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-content\/uploads\/2015\/07\/i11095-olivos-helada-631.jpg\" alt=\"i11095-olivos-helada-631\" width=\"631\" height=\"280\" srcset=\"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-content\/uploads\/2015\/07\/i11095-olivos-helada-631.jpg 631w, http:\/\/argentinamunicipal.com.ar\/argentina\/wp-content\/uploads\/2015\/07\/i11095-olivos-helada-631-300x133.jpg 300w\" sizes=\"auto, (max-width: 631px) 100vw, 631px\" \/><\/a><br \/>\nSe reasignar\u00e1n recursos para garantizar la continuidad de las explotaciones familiares o empresariales que sufrieron da\u00f1os en la \u00faltima temporada.<\/p>\n<p>El Ministerio de Agricultura, Ganader\u00eda y Pesca de la Naci\u00f3n declar\u00f3 la Emergencia Agropecuaria para la provincia de Mendoza. Esta disposici\u00f3n que se detalla en las resoluciones 420 y 421 se conoci\u00f3 a trav\u00e9s del Bolet\u00edn Oficial.<\/p>\n<p>La declaraci\u00f3n de Emergencia comprende a las provincias de Entre R\u00edos y Mendoza. En el caso de nuestra provincia, comprende a las explotaciones agropecuarias ubicadas en zonas bajo riego de distintos departamentos y distritos afectadas por heladas y granizadas ocurridas durante el per\u00edodo agr\u00edcola 2014\/2015 para el per\u00edodo 26 de septiembre de 2014-31 de marzo de 2016.<\/p>\n<p>La ley 25. 506, que prev\u00e9 la creaci\u00f3n de Sistema Nacional para la Prevenci\u00f3n y Mitigaci\u00f3n de Emergencias y Desastres Agropecuarios de la Secretar\u00eda de Agricultura, Ganader\u00eda, Pesca y Alimentos y establece en el art\u00edculo 6 Los estados de emergencia agropecuaria o zona de desastre deber\u00e1n ser declarados previamente por la provincia afectada, que deber\u00e1 solicitar ante la Comisi\u00f3n Nacional de Emergencias y Desastres Agropecuarios.<\/p>\n<p>En ese sentido la provincia de Mendoza, a trav\u00e9s del Ministerio de Agroindustria y Tecnolog\u00eda declar\u00f3 las zonas afectadas por granizo y heladas a trav\u00e9s del Decreto N\u00b0 372 publicado en el Bolet\u00edn Oficial el 18 de marzo de 2015 y a trav\u00e9s del Decreto N\u00b0914 publicado el 30 de junio en el Bolet\u00edn oficial http:\/\/www.gobernac.mendoza.gov.ar\/boletin\/pdf\/20150630-29902-normas.pdf .<\/p>\n<p>Mediante estas declaraciones, se establece que el productor damnificado que cuente con el certificado de da\u00f1os, otorgado oportunamente por la Direcci\u00f3n de Agricultura y Contingencias Clim\u00e1ticas, gozar\u00e1 de los beneficios que otorgan el Estado de Emergencia Agropecuaria o el Estado de Desastre Agropecuario. Estos son aportes no reembolsables para gastos de inversi\u00f3n; l\u00edneas de cr\u00e9dito especiales, o garantizar por s\u00ed o trav\u00e9s de sociedades de garant\u00edas rec\u00edprocas tales cr\u00e9ditos destinados a financiar gastos de inversi\u00f3n y capital de trabajo; suspensi\u00f3n de hasta noventa (90) d\u00edas y\/o ciclo productivo despu\u00e9s de finalizado el per\u00edodo de emergencia agropecuaria o zona de desastre de la iniciaci\u00f3n de juicios y procedimientos administrativos por cobros de acreencias vencidas con anterioridad a la emergencia o desastre agropecuario, entre otros aspectos.<\/p>\n<h6>Fuente: Uno, Mendoza<\/h6>\n","protected":false},"excerpt":{"rendered":"<p>Se reasignar\u00e1n recursos para garantizar la continuidad de las explotaciones familiares o empresariales que sufrieron da\u00f1os en la \u00faltima temporada. El Ministerio de Agricultura, Ganader\u00eda y Pesca de la Naci\u00f3n declar\u00f3 la Emergencia Agropecuaria para la provincia de Mendoza. Esta disposici\u00f3n que se detalla en las resoluciones 420 y 421 se conoci\u00f3 a trav\u00e9s del<\/p>\n","protected":false},"author":2,"featured_media":32861,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5],"tags":[31],"class_list":["post-32860","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-informe-economico","tag-mendoza"],"_links":{"self":[{"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/posts\/32860","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/comments?post=32860"}],"version-history":[{"count":0,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/posts\/32860\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/media\/32861"}],"wp:attachment":[{"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/media?parent=32860"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/categories?post=32860"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/tags?post=32860"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}