{"id":35079,"date":"2015-08-19T08:45:04","date_gmt":"2015-08-19T11:45:04","guid":{"rendered":"http:\/\/argentinamunicipal.com.ar\/argentina\/?p=35079"},"modified":"2015-08-19T09:59:54","modified_gmt":"2015-08-19T12:59:54","slug":"persisten-los-problemas-con-el-pago-de-haberes-municipales-en-santa-rosa-y-lujan","status":"publish","type":"post","link":"http:\/\/argentinamunicipal.com.ar\/argentina\/persisten-los-problemas-con-el-pago-de-haberes-municipales-en-santa-rosa-y-lujan\/","title":{"rendered":"Persisten los problemas con el pago de haberes municipales en Santa Rosa y Luj\u00e1n"},"content":{"rendered":"<p><a href=\"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-content\/uploads\/2015\/08\/50f4847f9c10e_684_x1.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-35080\" src=\"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-content\/uploads\/2015\/08\/50f4847f9c10e_684_x1.jpg\" alt=\"50f4847f9c10e_684_x\" width=\"684\" height=\"456\" srcset=\"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-content\/uploads\/2015\/08\/50f4847f9c10e_684_x1.jpg 684w, http:\/\/argentinamunicipal.com.ar\/argentina\/wp-content\/uploads\/2015\/08\/50f4847f9c10e_684_x1-300x200.jpg 300w\" sizes=\"auto, (max-width: 684px) 100vw, 684px\" \/><\/a><br \/>\nSanta Rosa y Luj\u00e1n encabezan el r\u00e1nking de atrasos. La Federaci\u00f3n que nuclea a los sindicatos denuncia -adem\u00e1s- una rebaja en los adicionales.<\/p>\n<p>La complicada situaci\u00f3n financiera de la Provincia se va sintiendo con distinta intensidad en los municipios. En los que m\u00e1s repercute es en aquellos que a\u00fan lo liquidan, en su totalidad, el mes de julio a la n\u00f3mina de los empleados estatales, de funcionarios y concejales. A la cabeza de estos, el caso que ya muchos se\u00f1alan como el especial, Santa Rosa.<\/p>\n<p>En el departamento del Este provincial, s\u00f3lo han cobrado hasta la clase 4 y algunos de la 5, mientas que de la 6 a la 10 a\u00fan esperan. Pero en Luj\u00e1n, despu\u00e9s de haberse normalizado la situaci\u00f3n \u201cdesde hace algunos meses\u201d, los n\u00fameros volvieron a desordenarse y los funcionarios y ediles todav\u00eda no tienen depositados en sus cuentas el mes pasado, con el agravante de la pol\u00e9mica que envuelve la transici\u00f3n entre Carlos L\u00f3pez Puelles (PJ) y Omar De Marchi (PD). En otros departamentos, los sindicatos denuncian quitas en los \u00edtems de mayor dedicaci\u00f3n, conceptos que abultan el salario de los municipales.<\/p>\n<p>Mientras tanto, los municipios esperan con ansias la coparticipaci\u00f3n. El gobernador, Francisco P\u00e9rez, sin dar m\u00e1s detalles, el viernes pasado hizo anuncios en materia cuentas y dijo que, en lo que corresponde al pago quincenal a los departamentos, se continuar\u00eda con los pagos esta semana.<\/p>\n<p>S\u00f3lo mencion\u00f3 a Rivadavia y a San Carlos como las \u00fanicas comunas a las que se les deb\u00eda dinero.<\/p>\n<p>La coparticipaci\u00f3n es un ingreso que reciben las comunas dos veces al mes y que no tiene un destino espec\u00edfico para gasto. Por lo tanto, es usada por la mayor\u00eda de los municipios para el pago de salarios, sobre todo, por aquellos que no cuentan con una recaudaci\u00f3n considerable en tasas municipales.<\/p>\n<p>En sus explicaciones, P\u00e9rez hizo menci\u00f3n a que el dep\u00f3sito implica para la Provincia, alrededor de $400 millones mensuales y que el cronograma de pago se encuentra afectado por \u201cuna situaci\u00f3n estructural\u201d, en la que la Provincia recibe \u201cs\u00f3lo el 4%de la coparticipaci\u00f3n federal\u201d.<\/p>\n<p>Lo cierto es que en la cadena de pagos, los empleados municipales son los \u00faltimos eslabones y los primeros afectados. \u201cNosotros pasamos el D\u00eda del Ni\u00f1o sin plata, a su vez tenemos gastos fijos con vencimientos. Esta situaci\u00f3n nos tiene muy mal a toda la familia\u201d, se\u00f1al\u00f3 Norma P\u00e9rez, esposa de un trabajador de Santa Rosa y quien se consider\u00f3 a s\u00ed misma como una de los tantos \u201cafectados indirectamente\u201d.<\/p>\n<p>Por otro lado, la concejal de la UCR, D\u00e9bora Quiroga, dijo que s\u00f3lo entr\u00f3 de la coparticipaci\u00f3n $2 millones, cuando en realidad deber\u00eda haber ingresado entre 3,5 y 4 millones.<\/p>\n<p>\u201cNosotros queremos un sinceramiento. No sabemos si han cobrado los adelantos de fondos que se pidieron en otras oportunidades y por eso ahora descontaron, pero lo cierto es que ac\u00e1 cobr\u00f3 el personal hasta la clase 5, mientras que los funcionarios en general y a los concejales nos deben desde el mes de mayo y el aguinaldo\u201d, se\u00f1al\u00f3 Quiroga, quien compiti\u00f3 en las \u00faltimas elecciones en contra del actual Sergio Salgado (PJ). Este \u00faltimo renov\u00f3 su cargo.<\/p>\n<p>Por esta situaci\u00f3n, Quiroga \u00a0adelant\u00f3 que podr\u00edan estar presentando en estos d\u00edas una denuncia por \u201cretenci\u00f3n indebida de haberes\u201d. \u201cNo se cobra en tiempo y forma, se adeuda dinero que corresponde a los haberes, \u00edtems de zona. C\u00f3mo ser\u00e1 la situaci\u00f3n, que hay concejales que se fueron en el 2013 y a\u00fan les deben plata\u201d.<\/p>\n<p>En el caso de Luj\u00e1n, el presidente del Concejo Deliberante, Eduardo P\u00e9rez (PJ), se\u00f1al\u00f3 que tanto ellos como los funcionarios del Ejecutivo a\u00fan no cobran el mes de julio, y que cerca del fin de semana tendr\u00edan novedades, siempre y cuando entre la segunda remesa de la coparticipaci\u00f3n.<\/p>\n<p>A su vez, el edil, cont\u00f3 que este desfasaje si bien lo hab\u00edan tenido hace tiempo, se hab\u00eda solucionado hace unos meses cuando qued\u00f3, como \u00fanico agente financiero, el banco Supervielle. Es por eso que, este mes, es el primero en el que tienen problemas luego de haberse regularizado la situaci\u00f3n.<\/p>\n<p>Este diario, en su edici\u00f3n del domingo, dio cuenta a trav\u00e9s de un informe elaborado por el intendente electo De Marchi, que la deuda que tiene el departamento asciende a los $400 millones.<\/p>\n<p>Fabi\u00e1n Barahona, del secretario general de la Federaci\u00f3n de Sindicatos Municipales, dijo que no s\u00f3lo Luj\u00e1n y Santa Rosa presentaron problemas. El caso de Guaymall\u00e9n, que este mes descont\u00f3 \u00edtems de mayor dedicaci\u00f3n y luego regulariz\u00f3 la situaci\u00f3n, tras el paro que hicieron algunos sectores, se repiti\u00f3 en otros lugares.<\/p>\n<p>\u201cEn Jun\u00edn se bajaron 50% los adicionales, mientras que en Malarg\u00fce pas\u00f3 lo mismo que en Luj\u00e1n. En Maip\u00fa y San Mart\u00edn tambi\u00e9n se han descontado los adicionales. Nosotros hicimos por todo esto, una presentaci\u00f3n en el Ministerio de Trabajo. Estamos en un estado de asamblea permanente y alerta, porque esto puede ser un detonante para todos los departamentos\u201d, advirti\u00f3 Barahona.<\/p>\n<h6>Fuente: Los Andes<\/h6>\n","protected":false},"excerpt":{"rendered":"<p>Santa Rosa y Luj\u00e1n encabezan el r\u00e1nking de atrasos. La Federaci\u00f3n que nuclea a los sindicatos denuncia -adem\u00e1s- una rebaja en los adicionales. La complicada situaci\u00f3n financiera de la Provincia se va sintiendo con distinta intensidad en los municipios. En los que m\u00e1s repercute es en aquellos que a\u00fan lo liquidan, en su totalidad, el<\/p>\n","protected":false},"author":2,"featured_media":35080,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5,7],"tags":[31],"class_list":["post-35079","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-informe-economico","category-informe-sindical","tag-mendoza"],"_links":{"self":[{"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/posts\/35079","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/comments?post=35079"}],"version-history":[{"count":0,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/posts\/35079\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/media\/35080"}],"wp:attachment":[{"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/media?parent=35079"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/categories?post=35079"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/tags?post=35079"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}