{"id":37328,"date":"2015-09-30T08:00:35","date_gmt":"2015-09-30T11:00:35","guid":{"rendered":"http:\/\/argentinamunicipal.com.ar\/argentina\/?p=37328"},"modified":"2015-09-30T09:53:05","modified_gmt":"2015-09-30T12:53:05","slug":"santa-rosa-sigue-acumulando-atrasos-salariales","status":"publish","type":"post","link":"http:\/\/argentinamunicipal.com.ar\/argentina\/santa-rosa-sigue-acumulando-atrasos-salariales\/","title":{"rendered":"Santa Rosa sigue acumulando atrasos salariales"},"content":{"rendered":"<p><a href=\"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-content\/uploads\/2015\/09\/o_1352529290.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-37329\" src=\"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-content\/uploads\/2015\/09\/o_1352529290.jpg\" alt=\"o_1352529290\" width=\"640\" height=\"360\" srcset=\"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-content\/uploads\/2015\/09\/o_1352529290.jpg 640w, http:\/\/argentinamunicipal.com.ar\/argentina\/wp-content\/uploads\/2015\/09\/o_1352529290-300x169.jpg 300w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/><\/a><br \/>\nTermina setiembre y al menos un 30% de los empleados municipales de Santa Rosa, no ha cobrado a\u00fan el sueldo de agosto y hasta anoche, no hab\u00eda indicios de que hoy la comuna fuese a pagar. En los \u00faltimos d\u00edas, parte de los municipales se pleg\u00f3 a un quite de colaboraci\u00f3n laboral, tanto en la comuna como en las delegaciones de Las Catitas y La Dormida y ayer, el Concejo Deliberante no sesion\u00f3 por un paro de sus empleados.<\/p>\n<p>La consecuencia m\u00e1s visible de la crisis financiera es la falta de plata suficiente para pagar los sueldos al mismo tiempo, situaci\u00f3n que se repite desde mayo. Hasta ayer, solo los empleados de las clases inferiores a la 6 hab\u00edan cobrado agosto. El resto segu\u00eda esperando y tambi\u00e9n los contratados, funcionarios y concejales.<\/p>\n<p>Mientras que la oposici\u00f3n responsabiliza del problema a \u201cla mala administraci\u00f3n municipal\u201d, el Ejecutivo asegura que la llegada intermitente de dinero que baja desde la Provincia, obliga a pagar de manera escalonada. \u201cNo hay plata y pagamos seg\u00fan nos llega. Hoy (por ayer) deb\u00edan llegar 1,9 mill\u00f3n de pesos pero me avisan que se va a retrasar\u201d, explic\u00f3 el intendente Sergio Salgado (PJ) y agreg\u00f3: \u201cSanta Rosa no tiene ingresos propios suficientes para paliar la crisis, como pueden ser los casos de Luj\u00e1n, San Mart\u00edn o Godoy Cruz; ac\u00e1 dependemos del dinero que nos llega de la provincia\u201d.<\/p>\n<p>Ayer no hubo sesi\u00f3n en el Concejo Deliberante debido a un paro de los empleados; de todos modos, el recinto se llen\u00f3 de municipales y gremialistas, que fueron a debatir con los ediles la crisis santarrosina, en un ambiente caldeado en el que no faltaron amenazas de desalojo y acusaciones cruzadas.<\/p>\n<h6>Fuente: Los Andes<\/h6>\n","protected":false},"excerpt":{"rendered":"<p>Termina setiembre y al menos un 30% de los empleados municipales de Santa Rosa, no ha cobrado a\u00fan el sueldo de agosto y hasta anoche, no hab\u00eda indicios de que hoy la comuna fuese a pagar. En los \u00faltimos d\u00edas, parte de los municipales se pleg\u00f3 a un quite de colaboraci\u00f3n laboral, tanto en la<\/p>\n","protected":false},"author":2,"featured_media":37329,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[31],"class_list":["post-37328","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-informe-sindical","tag-mendoza"],"_links":{"self":[{"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/posts\/37328","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/comments?post=37328"}],"version-history":[{"count":0,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/posts\/37328\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/media\/37329"}],"wp:attachment":[{"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/media?parent=37328"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/categories?post=37328"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/tags?post=37328"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}