{"id":40495,"date":"2015-12-15T08:07:16","date_gmt":"2015-12-15T11:07:16","guid":{"rendered":"http:\/\/argentinamunicipal.com.ar\/argentina\/?p=40495"},"modified":"2015-12-15T08:07:16","modified_gmt":"2015-12-15T11:07:16","slug":"junin-arranca-ano-nuevo-edificio-municipal","status":"publish","type":"post","link":"http:\/\/argentinamunicipal.com.ar\/argentina\/junin-arranca-ano-nuevo-edificio-municipal\/","title":{"rendered":"Jun\u00edn arranca el a\u00f1o con nuevo edificio municipal"},"content":{"rendered":"<p><a href=\"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-content\/uploads\/2015\/12\/image566f6a6aa96666.46443786.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter  wp-image-40496\" src=\"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-content\/uploads\/2015\/12\/image566f6a6aa96666.46443786.jpg\" alt=\"image566f6a6aa96666.46443786\" width=\"675\" height=\"431\" srcset=\"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-content\/uploads\/2015\/12\/image566f6a6aa96666.46443786.jpg 1220w, http:\/\/argentinamunicipal.com.ar\/argentina\/wp-content\/uploads\/2015\/12\/image566f6a6aa96666.46443786-300x192.jpg 300w, http:\/\/argentinamunicipal.com.ar\/argentina\/wp-content\/uploads\/2015\/12\/image566f6a6aa96666.46443786-768x490.jpg 768w, http:\/\/argentinamunicipal.com.ar\/argentina\/wp-content\/uploads\/2015\/12\/image566f6a6aa96666.46443786-1024x654.jpg 1024w\" sizes=\"auto, (max-width: 675px) 100vw, 675px\" \/><\/a><br \/>\nEl 18 de enero se inaugurar\u00e1 la estructura de 800 m2 y tres niveles. En la vieja Municipalidad funcionar\u00e1 el Concejo Deliberante.<\/p>\n<p>En enero, Jun\u00edn abrir\u00e1 las puertas de su nuevo edificio municipal, una estructura con m\u00e1s de 800 metros cuadrados repartidos en tres niveles y donde se concentrar\u00e1 la mayor parte de la actividad de la comuna. Anoche, el intendente Mario Abed utiliz\u00f3 la explanada de esa nueva casa municipal para asumir su cuarto per\u00edodo consecutivo al frente del Ejecutivo.<\/p>\n<p>\u201cEste edificio se construy\u00f3 con un doble prop\u00f3sito: por un lado, mejorar la atenci\u00f3n a los vecinos, que contar\u00e1n con un local moderno donde se concentrar\u00e1 la mayor parte de la actividad municipal: pero tambi\u00e9n esto nos permitir\u00e1 liberar al kil\u00f3metro cero de la mayor parte de los veh\u00edculos\u201d, explic\u00f3 el intendente ayer por la ma\u00f1ana.<\/p>\n<p>Efectivamente, hoy el grueso de los veh\u00edculos que estaciona en los alrededores del municipio y la plaza Juan Bautista Alberdi pertenece a empleados y funcionarios de la comuna o a vecinos que concurren por alg\u00fan tr\u00e1mite.<\/p>\n<p>El proyecto para construir una nueva Municipalidad en Jun\u00edn comenz\u00f3 a tomar forma en 2006, cuando la comuna expropi\u00f3 algunos terrenos para abrir la calle Sarmiento hacia el norte de la avenida Mitre, una iniciativa que buscaba prolongar la ciudad en esa direcci\u00f3n, hasta entonces dominada por los vi\u00f1edos.<\/p>\n<p>La idea de la comuna era abrir una calle frente a la iglesia Nuestra Se\u00f1ora del Rosario que, en direcci\u00f3n al norte, conectara el centro de Jun\u00edn con la calle 18 de Enero y con los barrios de esa zona.<\/p>\n<p>As\u00ed, la nueva arteria -llamada Rom\u00e1n Cano- permiti\u00f3 planificar un crecimiento comercial y residencial hacia el norte de la ciudad, que poco a poco est\u00e1 tomando forma; en esos mismos terrenos ganados a las fincas y ya urbanizados, la comuna construy\u00f3 su nuevo edificio municipal sobre un lote de 7.600 metros cuadrados, que ser\u00e1 inaugurado el 18 de enero, como parte de los festejos por el aniversario del departamento.<\/p>\n<p>La obra est\u00e1 terminada y solo quedan por conectar los equipos de aire acondicionado y poner en marcha el ascensor que une los distintos pisos.<\/p>\n<p>En la planta baja funcionar\u00e1n las \u00e1reas de Servicios y Rentas, en el primer piso ir\u00e1n Contadur\u00eda y Asesor\u00eda, mientras que en el segundo piso se ubicar\u00e1n la Secretar\u00eda de Gobierno y la Intendencia.<\/p>\n<p>La obra fue proyectada en 2012, tras un acuerdo entre la comuna y el Ministerio de Infraestructura de la provincia; tuvo un costo inicial de 4,4 millones de pesos, una cifra que el municipio logr\u00f3 congelar a pesar del paso del tiempo y la inflaci\u00f3n, gracias a que hizo acopio de materiales.<\/p>\n<p>\u201cA la licitaci\u00f3n la gan\u00f3 la empresa Flores Constructora y nosotros compramos los materiales necesarios, si el trabajo se ha demorado m\u00e1s de dos a\u00f1os en estar listo ha sido por problemas de la empresa para cumplir con lo pautado, pero esa demora en realidad al municipio no le ha significado un mayor costo, porque todo el gasto lo hicimos al comienzo\u201d, subray\u00f3 Abed.<\/p>\n<p>La Municipalidad actual es un vistoso edificio de estilo neocl\u00e1sico que fue inaugurado en 1912. Est\u00e1 ubicado frente a la plaza Alberdi (a poco m\u00e1s de 300 metros del nuevo palacio municipal), en la esquina de San Mart\u00edn y Sarmiento, y aunque se mantiene en buenas condiciones a lo largo de los a\u00f1os experiment\u00f3 reformas interiores y refacciones que permitieron albergar a las principales dependencias del Ejecutivo.<\/p>\n<p>\u201cUna vez que nos mudemos, este edificio quedar\u00e1 para Obras P\u00fablicas y para el Concejo Deliberante\u201d, agreg\u00f3 Abed.<\/p>\n<p>Hay que tener en cuenta que el Concejo de Jun\u00edn funciona desde 1983 en un espacio improvisado en el primer piso del polideportivo municipal; por ello, tras la mudanza de enero, los diez ediles y el personal del HCD pasar\u00e1n a ocupar el actual edificio municipal y as\u00ed, la intendencia quedar\u00e1 para el presidente del Concejo, los ediles se repartir\u00e1n las oficinas y la sala de sesi\u00f3n se ubicar\u00e1 en el actual hall municipal.<\/p>\n<p>Para completar los cambios, el espacio que ocupa el Concejo en el polideportivo ser\u00e1 utilizado por la gente de Vivienda y de Compras, que hoy trabajan en un sal\u00f3n alquilado por la comuna.<\/p>\n<h6>Fuente: Los Andes<\/h6>\n","protected":false},"excerpt":{"rendered":"<p>El 18 de enero se inaugurar\u00e1 la estructura de 800 m2 y tres niveles. En la vieja Municipalidad funcionar\u00e1 el Concejo Deliberante. En enero, Jun\u00edn abrir\u00e1 las puertas de su nuevo edificio municipal, una estructura con m\u00e1s de 800 metros cuadrados repartidos en tres niveles y donde se concentrar\u00e1 la mayor parte de la actividad<\/p>\n","protected":false},"author":2,"featured_media":40496,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[31],"class_list":["post-40495","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-informe-municipal","tag-mendoza"],"_links":{"self":[{"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/posts\/40495","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/comments?post=40495"}],"version-history":[{"count":0,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/posts\/40495\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/media\/40496"}],"wp:attachment":[{"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/media?parent=40495"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/categories?post=40495"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/tags?post=40495"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}