{"id":45980,"date":"2016-04-08T06:02:43","date_gmt":"2016-04-08T09:02:43","guid":{"rendered":"http:\/\/argentinamunicipal.com.ar\/argentina\/?p=45980"},"modified":"2016-04-08T07:05:40","modified_gmt":"2016-04-08T10:05:40","slug":"planificacion-municipal-parana-endureceran-las-medidas-los-trabajadores-despedidos","status":"publish","type":"post","link":"http:\/\/argentinamunicipal.com.ar\/argentina\/planificacion-municipal-parana-endureceran-las-medidas-los-trabajadores-despedidos\/","title":{"rendered":"En Planificaci\u00f3n municipal de Paran\u00e1 endurecer\u00e1n las medidas los trabajadores despedidos"},"content":{"rendered":"<p>Hay tres contratados, con dos a\u00f1os de antig\u00fcedad, que siguen cumpliendo con sus tareas pero no cobran los sueldos desde diciembre. En las oficinas del edificio 5 Esquinas hace dos semanas que realizan \u00abretenciones de servicios\u00bb.<\/p>\n<p>Tres trabajadores de la subsecretaria de Planificaci\u00f3n, que depende en forma directa del intendente Sergio Varisco, est\u00e1n esperando por la firma de la renovaci\u00f3n de sus contratos desde diciembre. El 26 de enero se presentaron a trabajar, con el aval (y la promesa) de la actual gesti\u00f3n pero hace meses que no cobran sus sueldos y por lo que observan los trabajadores de carrera \u00abno hay decisi\u00f3n pol\u00edtica de firmar los expedientes relacionados con el \u00e1rea\u00bb.<\/p>\n<p>En solidaridad con los tres j\u00f3venes que esperan por la renovaci\u00f3n, sus compa\u00f1eros, realizan retenciones de servicios desde hace dos semanas. \u00abAc\u00e1 no entra ni sale ning\u00fan expediente\u00bb, agreg\u00f3 una fuente consultada por UNO.<\/p>\n<p>Las situaci\u00f3n es preocupante porque, adem\u00e1s, algunas empresas constructoras de la ciudad est\u00e1n inquietas porque sus certificados tambi\u00e9n est\u00e1n frenados y siguen sin cobrar obras que ya realizaron. Ponen como ejemplo las \u00faltimas mejoras de infraestructura que se realizaron en el Parque Varisco.<\/p>\n<p>Las constructoras a su vez tienen sueldos que pagar y la cadena se hace cada vez m\u00e1s extensa.<\/p>\n<p>UNO\u00a0pudo saber que para las 18 hay una reuni\u00f3n agendada en el Palacio Municipal para tratar algunos temas relacionados con Planificaci\u00f3n y los trabajadores esperan por novedades \u00abpositivas\u00bb.<\/p>\n<p>El malestar dentro del edificio de 5 Esquinas se potencia porque tienen el n\u00famero de decreto con que se contrataron a tres profesionales que ganar\u00e1n en promedio unos 20.000 pesos cada uno por mes y a los tres contratados, que adem\u00e1s cobran como monotributistas, hace tres meses que van a trabajar poniendo plata de su bolsillo.<\/p>\n<h6>Fuente: Uno, Entre R\u00edos<\/h6>\n","protected":false},"excerpt":{"rendered":"<p>Hay tres contratados, con dos a\u00f1os de antig\u00fcedad, que siguen cumpliendo con sus tareas pero no cobran los sueldos desde diciembre. En las oficinas del edificio 5 Esquinas hace dos semanas que realizan \u00abretenciones de servicios\u00bb.<\/p>\n","protected":false},"author":2,"featured_media":45981,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[17],"class_list":["post-45980","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-informe-sindical","tag-entre-rios"],"_links":{"self":[{"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/posts\/45980","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/comments?post=45980"}],"version-history":[{"count":0,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/posts\/45980\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/media\/45981"}],"wp:attachment":[{"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/media?parent=45980"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/categories?post=45980"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/tags?post=45980"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}