{"id":45986,"date":"2016-04-08T06:14:00","date_gmt":"2016-04-08T09:14:00","guid":{"rendered":"http:\/\/argentinamunicipal.com.ar\/argentina\/?p=45986"},"modified":"2016-04-08T08:46:49","modified_gmt":"2016-04-08T11:46:49","slug":"trelew-adhirio-al-programa-municipios-comunidades-saludables","status":"publish","type":"post","link":"http:\/\/argentinamunicipal.com.ar\/argentina\/trelew-adhirio-al-programa-municipios-comunidades-saludables\/","title":{"rendered":"Trelew adhiri\u00f3 al Programa Municipios y Comunidades Saludables"},"content":{"rendered":"<p>El subsecretario de Programas de Salud del Chubut, Mariano Cabrera, destac\u00f3 la importancia de que los Gobiernos Nacional y Provincial y los Municipios trabajen en conjunto en el desarrollo de las pol\u00edticas sanitarias, poniendo el acento en la promoci\u00f3n y prevenci\u00f3n de la salud, para brindar una mejor atenci\u00f3n a la poblaci\u00f3n. Lo hizo al participar ayer jueves en Trelew del acto en el cual el intendente de esa ciudad, Adri\u00e1n Maderna, firm\u00f3 la adhesi\u00f3n al Programa Nacional Municipios y Comunidades Saludables.<\/p>\n<p>El evento tuvo lugar en las instalaciones de la C\u00e1mara de Industria y Comercio del Este del Chubut en ocasi\u00f3n de conmemorarse el D\u00eda Mundial de la Salud, que se celebra el 7 de abril de cada a\u00f1o. Junto a Maderna y Cabrera estuvieron la presidente del Concejo Deliberante de Trelew, Leila Lloyd Jones; el director municipal de Salud, Ra\u00fal Ber\u00f3n; y el asesor de esa \u00e1rea, Julio L\u00f3pez Ruiz D\u00edaz. Tambi\u00e9n asistieron, por parte del Ministerio de Salud que conduce Leandro Gonz\u00e1lez: la directora provincial de Promoci\u00f3n y Prevenci\u00f3n de la Salud, Jimena Marcos; la jefa del Departamento Provincial de Nutrici\u00f3n, Karen Bender; y la referente provincial del Programa Municipios y Comunidades Saludables, Susana Capart.<\/p>\n<p><strong>Lineamientos<\/strong><\/p>\n<p>En la oportunidad, el intendente de Trelew, Adri\u00e1n Madera, se refiri\u00f3 a la adhesi\u00f3n al Programa Municipios Saludables y expres\u00f3: \u201cEstamos muy contentos de poder trabajar con este lineamiento en conjunto, tanto con el Gobierno Nacional como Provincial\u201d, destacando la importancia de \u201csumar esfuerzos\u201d y \u201cunificar recursos\u201d para mejorar los servicios de salud en la ciudad, contando tambi\u00e9n con \u201cel aporte del \u00e1mbito privado de la salud\u201d.<\/p>\n<p>Y sobre la adhesi\u00f3n a este programa, lo mismo que a otras iniciativas sanitarias nacionales y provinciales, dijo que \u201ces muy importante porque significa contar con recursos, los cuales son volcados a diferentes vecinos de la ciudad de Trelew\u201d.<\/p>\n<p>Asimismo y en referencia al accionar del gobernador Mario Das Neves, Maderna resalt\u00f3 que \u201ctenemos un gobernador que piensa en la ciudad de Trelew, al igual que en todos los pueblos de la provincia\u201d, momento en el que tambi\u00e9n dijo que \u201ctambi\u00e9n hay una Municipalidad que trata de hacer el esfuerzo y que con errores y virtudes trabaja para todos los vecinos\u201d.<\/p>\n<p><strong>Salud integral<\/strong><\/p>\n<p>El subsecretario de Programas de Salud del Chubut, Mariano Cabrera, destac\u00f3 que \u201cnosotros tenemos una mirada de salud integral, en donde son importantes todos los actores, no solamente el Ministerio de Salud en su rol de organizador sino los efectores, que son los municipios y es la gente que participa activamente\u201d.<\/p>\n<p>En este sentido, el funcionario provincial resalt\u00f3 que el Programa Municipios Saludables es fundamental para contar con una \u201cmisma l\u00ednea de trabajo, con un lineamiento nacional, provincial y municipal. La salud \u2013dijo- no solamente se relaciona con enfermedades sino que implica distintos determinantes, principalmente lo que son estilos de vida saludables, lo que es tener servicios: agua, luz, gas, y tener trabajo. Eso tambi\u00e9n impacta directamente en la salud y ah\u00ed el rol de los municipios es clave\u201d, indic\u00f3 Cabrera. Adem\u00e1s felicit\u00f3 \u201cel trabajo que se viene haciendo a nivel municipal en Trelew con respecto a temas de salud\u201d.<\/p>\n<p>A su vez, explic\u00f3 que el Programa Municipios Saludables \u201cest\u00e1 apuntado a fortalecer el rol protag\u00f3nico que tienen hoy los municipios y las comunidades, en hacer un diagn\u00f3stico propio de cu\u00e1l es la situaci\u00f3n particular de cada comunidad y tomar acciones concretas para mejorar la calidad de vida\u201d.<\/p>\n<p><strong>Empoderar a municipios<\/strong><\/p>\n<p>Por su parte, el asesor de la Direcci\u00f3n Municipal de Salud de Trelew, Julio L\u00f3pez Ruiz D\u00edaz, precis\u00f3 que el Programa Municipios Saludables \u201cse basa en 4 lineamientos estrat\u00e9gicos: primero, el n\u00facleo de las acciones est\u00e1n dirigidas a la promoci\u00f3n y prevenci\u00f3n de la salud; segundo, se trabaja en el territorio y desde el territorio; y tercero, se busca empoderar al municipio, para que actu\u00e9 como un actor principal\u201d junto a los Estados Nacional y Provincial y otros actores sociales. En cuarto lugar, se tienen en cuenta \u201clos determinantes y condicionantes de la salud: los modos de vida, los factores socioecon\u00f3micos, la salud ambiental y los servicios y sistemas de salud\u201d, a\u00f1adi\u00f3.<\/p>\n<h6>Fuente: El Diario de Madryn<\/h6>\n","protected":false},"excerpt":{"rendered":"<p>El intendente de Trelew, Adri\u00e1n Maderna, firm\u00f3 la adhesi\u00f3n al Programa Nacional Municipios y Comunidades Saludables.<\/p>\n","protected":false},"author":2,"featured_media":45987,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[14],"class_list":["post-45986","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-informe-municipal","tag-chubut"],"_links":{"self":[{"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/posts\/45986","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/comments?post=45986"}],"version-history":[{"count":0,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/posts\/45986\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/media\/45987"}],"wp:attachment":[{"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/media?parent=45986"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/categories?post=45986"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/tags?post=45986"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}