{"id":45998,"date":"2016-04-08T06:00:07","date_gmt":"2016-04-08T09:00:07","guid":{"rendered":"http:\/\/argentinamunicipal.com.ar\/argentina\/?p=45998"},"modified":"2016-04-08T07:44:44","modified_gmt":"2016-04-08T10:44:44","slug":"diputados-saltenos-dialogaron-la-nueva-ley-organica-municipios","status":"publish","type":"post","link":"http:\/\/argentinamunicipal.com.ar\/argentina\/diputados-saltenos-dialogaron-la-nueva-ley-organica-municipios\/","title":{"rendered":"Diputados salte\u00f1os dialogaron acerca de la nueva ley org\u00e1nica de municipios"},"content":{"rendered":"<p>En una reuni\u00f3n realizada en la C\u00e1mara Baja, diputados, concejales y funcionarios del Ejecutivo provincial intercambiaron opiniones acerca de los proyectos de Ley que se encuentran en an\u00e1lisis para reemplazar la actual Ley Org\u00e1nica de Municipalidades N\u00b0 1349.<\/p>\n<p>Al respecto, todos los presentes coincidieron que la actual normativa, cuya fecha de sanci\u00f3n data de 1933, est\u00e1 desactualizada y no brinda respuestas a situaciones que se plantean actualmente en los municipios, dejando\u00a0vac\u00edos\u00a0legales que dificultan la vida institucional de los mismos.<\/p>\n<p>El presidente de la comisi\u00f3n de Asuntos Municipales de la C\u00e1mara de Diputados, Mario Vilca, expuso los diferentes proyectos en an\u00e1lisis, que surgieron desde el Senado, el Ejecutivo y Diputados, con el objetivo de poder plasmarlos en un \u00fanico proyecto consensuado por funcionarios y legisladores, tanto provinciales como municipales.<\/p>\n<p>Por ese motivo el Secretario Legislativo de la C\u00e1mara Baja, Pedro Mellado, adelant\u00f3 que en sucesivas reuniones se invitar\u00e1n a participar a senadores, para que el an\u00e1lisis y la redacci\u00f3n de dicho proyecto sea de car\u00e1cter bicameral.<\/p>\n<p>Los concejales Carlos Cruz (Campo Quijano) y Juan D\u00e1valos (San Lorenzo), se mostraron interesados en que la nueva ley contemple mecanismos para un mayor control a los Ejecutivos Municipales y que se garantice la independencia de los cuerpos legislativos, en especial en lo que respecta a los econ\u00f3mico.<\/p>\n<p>En tanto el Subsecretario de Asuntos Legislativos de la Provincia, Mart\u00edn Avila, se\u00f1al\u00f3 que debe incluirse la obligatoriedad de dictar una Carta Org\u00e1nica a los municipios que cumplan con los requisitos exigidos por la Constituci\u00f3n Provincial, debido a que en la actualidad existen varias localidades que ya podr\u00edan acceder a dicha reglamentaci\u00f3n, pero por diversos motivos no lo hacen.<\/p>\n<p>Finalmente los presentes acordaron seguir con las reuniones, a las cuales se incorporar\u00e1n tambi\u00e9n a intendentes municipales, y remarcaron que existe la voluntad tanto desde el Ejecutivo como desde la Legislatura de avanzar firmemente en la sanci\u00f3n de esta nueva Ley.<\/p>\n<p>En este encuentro adem\u00e1s participaron el diputado Alberto Abad\u00eda, el prosecretario legislativo de Diputados, Alberto Barrios y asesores de los legisladores.<\/p>\n<h6>Fuente: La Hora de Salta<\/h6>\n","protected":false},"excerpt":{"rendered":"<p>En una reuni\u00f3n realizada en la C\u00e1mara Baja, diputados, concejales y funcionarios del Ejecutivo provincial intercambiaron opiniones acerca de los proyectos de Ley que se encuentran en an\u00e1lisis para reemplazar la actual Ley Org\u00e1nica de Municipalidades N\u00b0 1349.<\/p>\n","protected":false},"author":2,"featured_media":45999,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[9],"class_list":["post-45998","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-informe-municipal","tag-salta"],"_links":{"self":[{"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/posts\/45998","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/comments?post=45998"}],"version-history":[{"count":0,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/posts\/45998\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/media\/45999"}],"wp:attachment":[{"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/media?parent=45998"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/categories?post=45998"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/tags?post=45998"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}