{"id":46034,"date":"2016-04-08T07:30:08","date_gmt":"2016-04-08T10:30:08","guid":{"rendered":"http:\/\/argentinamunicipal.com.ar\/argentina\/?p=46034"},"modified":"2016-04-08T08:43:41","modified_gmt":"2016-04-08T11:43:41","slug":"lanzaran-una-nueva-modalidad-ahorro-comprar-viviendas","status":"publish","type":"post","link":"http:\/\/argentinamunicipal.com.ar\/argentina\/lanzaran-una-nueva-modalidad-ahorro-comprar-viviendas\/","title":{"rendered":"Lanzar\u00e1n una nueva modalidad para ahorro para comprar viviendas"},"content":{"rendered":"<p>En una primera etapa, se han comprometido al lanzamiento de estos pr\u00e9stamos los bancos: Ciudad, Macro, Provincia de Buenos Aires, Hipotecario, Galicia y Santander R\u00edo.<\/p>\n<p>Con el prop\u00f3sito de reanimar el alica\u00eddo mercado inmobiliario, el Banco Central puso en marcha un sistema de ahorro indexado para la compra de viviendas, cuyos instrumentos se denominar\u00e1n UVIs, y se ajustar\u00e1n por CER. El Central pronostic\u00f3 que bajo esta nueva modalidad se pagar\u00e1n cuotas m\u00e1s bajas que las habituales para un pr\u00e9stamo hipotecario y que se necesitar\u00e1n menores requisitos.<\/p>\n<p>En una primera etapa, indic\u00f3 que se han comprometido al lanzamiento de estos pr\u00e9stamos los bancos: Ciudad, Macro, Provincia de Buenos Aires, Hipotecario, Galicia y Santander R\u00edo.<\/p>\n<p>La autoridad monetaria dijo que el sistema apunta a \u00abfomentar el desarrollo con equidad social\u00bb, uno de los mandatos de su Carta Org\u00e1nica. Los instrumentos bajo esta nueva modalidad estar\u00e1n denominados en Unidades de Vivienda (UVIs).<\/p>\n<p>El valor inicial de una UVI al 31 de marzo de 2016 equivaldr\u00e1 a la mil\u00e9sima parte del costo promedio de construcci\u00f3n de un metro cuadrado testigo, basado en las cifras conocidas para inmuebles de diverso tipo en las ciudades de Buenos Aires, C\u00f3rdoba, Rosario, Salta y zona del Litoral (Santa Fe de la Vera Cruz-Paran\u00e1), ponderados por poblaci\u00f3n.<\/p>\n<p>Ya que este metro cuadrado testigo se ubica en $14.053, el valor inicial de la UVI ser\u00e1 de 14,053 pesos y se actualizar\u00e1 diariamente por el Coeficiente de Estabilizaci\u00f3n de Referencia (CER), basado en el \u00edndice de precios al consumidor.<\/p>\n<p>El cepo cambiario implementado en octubre de 2011 afect\u00f3 sensiblemente la compraventa de inmuebles, mientras que la paralizaci\u00f3n del programa Procrear que dispuso el Gobierno de Mauricio Macri cuando asumi\u00f3, fren\u00f3 la construcci\u00f3n de viviendas.<\/p>\n<p>En un comunicado, la entidad que conduce Federico Sturzenegger explic\u00f3 que \u00abel \u00edndice de precios al consumidor tiene una alt\u00edsima correlaci\u00f3n con el costo de la construcci\u00f3n, pero sufre menor volatilidad\u00bb.<\/p>\n<p>\u00abDe este modo, 1000 UVIs alcanzar\u00e1n aproximadamente para construir 1 metro cuadrado testigo en cualquier momento futuro. El valor diario de la UVI se publicar\u00e1 en la p\u00e1gina web del Banco Central\u00bb, agreg\u00f3.<\/p>\n<p>Seg\u00fan la entidad, \u00abla habilitaci\u00f3n del ahorro en UVIs pondr\u00e1 al alcance de las familias argentinas un instrumento de ahorro protegido de la inflaci\u00f3n, similar al ahorro en ladrillos pero que ser\u00e1 accesible a todas las familias independientemente de su poder adquisitivo\u00bb.<\/p>\n<p>La nueva modalidad de ahorro consistir\u00e1 en dep\u00f3sitos por plazos m\u00ednimos de 180 d\u00edas, indic\u00f3 el directorio del BCRA.<\/p>\n<p>\u00abPodr\u00e1 haber dep\u00f3sitos precancelables de plazos m\u00e1s largos, una vez transcurridos 180 d\u00edas\u00bb, agreg\u00f3. La habilitaci\u00f3n del mercado de cr\u00e9dito en UVIs tiene el potencial de multiplicar el acceso a cr\u00e9ditos hipotecarios, hoy reducidos a alrededor de una cent\u00e9sima del PIB.<\/p>\n<p>Al estar denominados en UVIs, la tasa de inter\u00e9s de estos cr\u00e9ditos pasa a ser una tasa real, que el Central anticipa oscilar\u00e1 en torno a 5%.<\/p>\n<p>As\u00ed, las cuotas de un cr\u00e9dito hipotecario bajo esta nueva modalidad son asimilables a un alquiler tradicional, el cual t\u00edpicamente se ubica en aproximadamente un porcentaje fijo del valor de la propiedad y se va adecuando con el nivel de precios de la econom\u00eda. Una gran ventaja de esta modalidad es que hace posible cuotas sensiblemente m\u00e1s accesibles que las de un cr\u00e9dito tradicional, especialmente al principio.<\/p>\n<p>\u00abEn un cr\u00e9dito tradicional de cuotas fijas, las cuotas iniciales tienen que ser muy elevadas para compensar el hecho de que la inflaci\u00f3n puede licuar el valor de las cuotas posteriores\u00bb, remarc\u00f3. Por ejemplo, asumiendo una relaci\u00f3n cuota ingreso del 30%, en el cr\u00e9dito est\u00e1ndar para un monto de 1 mill\u00f3n de pesos se necesita un ingreso mensual de 68.609 pesos. En el pr\u00e9stamo con UVIs, el ingreso mensual requerido es de 26.855 pesos.<\/p>\n<h6>Fuente: Uno, Mendoza<\/h6>\n","protected":false},"excerpt":{"rendered":"<p>En una primera etapa, se han comprometido al lanzamiento de estos pr\u00e9stamos los bancos: Ciudad, Macro, Provincia de Buenos Aires, Hipotecario, Galicia y Santander R\u00edo.<\/p>\n","protected":false},"author":2,"featured_media":46035,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[8],"tags":[21],"class_list":["post-46034","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-informe-nacional","tag-argentina"],"_links":{"self":[{"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/posts\/46034","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/comments?post=46034"}],"version-history":[{"count":0,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/posts\/46034\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/media\/46035"}],"wp:attachment":[{"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/media?parent=46034"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/categories?post=46034"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/tags?post=46034"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}