{"id":46053,"date":"2016-04-09T09:27:42","date_gmt":"2016-04-09T12:27:42","guid":{"rendered":"http:\/\/argentinamunicipal.com.ar\/argentina\/?p=46053"},"modified":"2016-04-09T09:27:42","modified_gmt":"2016-04-09T12:27:42","slug":"reclaman-los-estados-municipales-boanerenses-adhieran-la-ley-acceso-justo-al-habitat","status":"publish","type":"post","link":"http:\/\/argentinamunicipal.com.ar\/argentina\/reclaman-los-estados-municipales-boanerenses-adhieran-la-ley-acceso-justo-al-habitat\/","title":{"rendered":"Reclaman a los estados municipales boanerenses que adhieran a la ley de Acceso Justo al Habitat"},"content":{"rendered":"<p>La diputada provincial Alicia S\u00e1nchez inst\u00f3 a las comunas bonaerense a que adhieran a la ley de Acceso Justo al Habitat para poder combatir la crisis habitacional \u2013que seg\u00fan confirm\u00f3- atraviesa la Provincia.<\/p>\n<p>En el marco del XV Encuentro de la Secretar\u00eda Latinoamericana de la Vivienda y el H\u00e1bitat Popular, la legisladora sostuvo: \u201cHay un importante d\u00e9ficit de viviendas adecuadas. La Ley 14.449 de Acceso Justo al H\u00e1bitat, vino para ser utilizada y para cambiar esta situaci\u00f3n. Es muy importante que los estados municipales adhieran a la ley, ya que cuando el propietario de una tierra quiere construir un mega emprendimiento -como ser un country o un supermercado- tiene la obligaci\u00f3n de contribuir al fisco, tanto para la compra de tierras como para la construcci\u00f3n de viviendas populares\u201d.<\/p>\n<p>En ese sentido ampli\u00f3 el concepto de la legislaci\u00f3n bonaerense al sostener que \u201ceste impuesto debe ir al municipio a trav\u00e9s de la creaci\u00f3n de una cuenta especial\u201d, lo cual implica que \u201cel intendente tiene que comprometerse con la causa sino es imposible llevar adelante la ley\u201d.<\/p>\n<p>Del evento participaron los Diputados Provinciales: Walter Abarca; Valeria Amendolara; Gabriel Barrientos; la Presidenta de la Comisi\u00f3n de Tierras y Organizaci\u00f3n Territorial, Alicia S\u00e1nchez (Co-autora de la ley 14.449) y el Responsable de la Federaci\u00f3n de Cooperativas Autogestionadas MOI- Argentina, N\u00e9stor Jeifetz.<\/p>\n<p>Por \u00faltimo, adelant\u00f3 que presentaron un proyecto de reforma a la ley que plantea \u201cen aumentar el impuesto al bald\u00edo -que va al fondo fiduciario- en un 30%. Este fondo es para pagar las expropiaciones y la compra de tierras para la producci\u00f3n de suelo urbano\u201d.<\/p>\n<h6>Fuente: INFOCIELO<\/h6>\n","protected":false},"excerpt":{"rendered":"<p>Diputados bonaerense se refirieron al estado de situaci\u00f3n provincial durante el XV Encuentro de la Secretar\u00eda Latinoamericana de la Vivienda y el H\u00e1bitat Popular. <\/p>\n","protected":false},"author":1,"featured_media":46054,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[12],"class_list":["post-46053","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-informe-municipal","tag-buenos-aires"],"_links":{"self":[{"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/posts\/46053","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/comments?post=46053"}],"version-history":[{"count":0,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/posts\/46053\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/media\/46054"}],"wp:attachment":[{"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/media?parent=46053"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/categories?post=46053"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/tags?post=46053"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}