{"id":46113,"date":"2016-04-09T11:44:16","date_gmt":"2016-04-09T14:44:16","guid":{"rendered":"http:\/\/argentinamunicipal.com.ar\/argentina\/?p=46113"},"modified":"2016-04-09T11:44:16","modified_gmt":"2016-04-09T14:44:16","slug":"fin-mes-concordia-sera-sede-del-encuentro-nacional-intendentes-peronistas","status":"publish","type":"post","link":"http:\/\/argentinamunicipal.com.ar\/argentina\/fin-mes-concordia-sera-sede-del-encuentro-nacional-intendentes-peronistas\/","title":{"rendered":"A fin de mes Concordia ser\u00e1 sede del encuentro nacional de intendentes peronistas"},"content":{"rendered":"<p><span style=\"line-height: 1.5\">El pr\u00f3ximo 28 y 29 de abril se reunir\u00e1n en Concordia intendentes justicialistas de todo el pa\u00eds. En el Centro de Convenciones se realizar\u00e1 la tercera reuni\u00f3n del a\u00f1o, luego de que se conformara en Chaco el Bloque Federal de Intendentes Peronistas de la Federaci\u00f3n Argentina de Municipios (FAM) y de que se ratificara a sus autoridades en la reuni\u00f3n realizada en Formosa, donde Enrique Cresto fue designado por sus pares presidente del bloque<\/span><\/p>\n<p>En este encuentro en Concordia se debatir\u00e1 sobre \u00abLos nuevos desaf\u00edos de la gesti\u00f3n municipal: Pasado, Presente y Futuro del Municipalismo Argentino\u00bb, expondr\u00e1n funcionarios de destacada trayectoria nacional, y se avanzar\u00e1 en la articulaci\u00f3n y gesti\u00f3n del espacio que integra la Federaci\u00f3n Argentina de Municipios (FAM). Econom\u00eda, desarrollo, producci\u00f3n y turismo, ser\u00e1n los ejes de las disertaciones, se indic\u00f3 en un comunicado enviado a esta Agencia.<\/p>\n<h3><span style=\"line-height: 1.5\">3\u00b0 Reuni\u00f3n de Viceintendentes de la Costa del Uruguay<\/span><\/h3>\n<p>A su vez, el jueves 28 en paralelo se realizar\u00e1 en Concordia la 3\u00b0 reuni\u00f3n de los viceintendentes del PJ de la Costa del R\u00edo Uruguay, luego de los encuentros mantenidos en Gualeguaych\u00fa y en Concepci\u00f3n del Uruguay. Adem\u00e1s de los viceintendentes, participar\u00e1n del encuentro los concejales del justicialismo, en un encuentro que servir\u00e1 para profundizar el intercambio de experiencias, de iniciativas parlamentarias y de puesta en com\u00fan de proyectos presentados, que se viene realizando en las ciudades de este margen de la provincia.<\/p>\n<h6>Fuente: APFDigital<\/h6>\n","protected":false},"excerpt":{"rendered":"<p>El pr\u00f3ximo 28 y 29 de abril se reunir\u00e1n en Concordia intendentes justicialistas de todo el pa\u00eds.<\/p>\n","protected":false},"author":1,"featured_media":46114,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"tags":[21,17],"class_list":["post-46113","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-informe-politico","tag-argentina","tag-entre-rios"],"_links":{"self":[{"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/posts\/46113","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/comments?post=46113"}],"version-history":[{"count":0,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/posts\/46113\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/media\/46114"}],"wp:attachment":[{"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/media?parent=46113"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/categories?post=46113"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/tags?post=46113"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}