{"id":46161,"date":"2016-04-11T06:47:18","date_gmt":"2016-04-11T09:47:18","guid":{"rendered":"http:\/\/argentinamunicipal.com.ar\/argentina\/?p=46161"},"modified":"2016-04-11T06:47:18","modified_gmt":"2016-04-11T09:47:18","slug":"mar-del-plata-ya-esta-lista-recibir-radar-meteorologico","status":"publish","type":"post","link":"http:\/\/argentinamunicipal.com.ar\/argentina\/mar-del-plata-ya-esta-lista-recibir-radar-meteorologico\/","title":{"rendered":"Mar del Plata ya est\u00e1 lista para recibir el radar meteorol\u00f3gico"},"content":{"rendered":"<p>As\u00ed lo confirm\u00f3 Sergio Andueza, director del COM. \u00abFinalizamos la construcci\u00f3n de la base y todo lo relacionado a la obra civil\u00bb, asegur\u00f3. Comienza ahora la etapa final.<\/p>\n<p><span style=\"line-height: 1.5\">Las obras del radar del Sinarame (Sistema Nacional de Radares Meteorol\u00f3gicos) que se instalar\u00e1 en Mar del Plata avanzan a buen ritmo. En los \u00faltimos d\u00edas, culmin\u00f3 la primera etapa, que const\u00f3 en la construcci\u00f3n de la base y todo lo relacionado a la obra civil. As\u00ed lo confirm\u00f3 el director del Centro de Operaciones y Monitoreo, Sergio Andueza.<\/span><\/p>\n<p>\u201cFinalizamos la primera etapa, que es la construcci\u00f3n de la base y todo lo relacionado a la obra civil y en este momento nos encontramos realizando gestiones para tener energ\u00eda y la fibra \u00f3ptica, que es por donde se conectar\u00e1 con el Servicio Meteorol\u00f3gico Nacional. Luego, ser\u00e1 el turno del montaje y las pruebas t\u00e9cnicas para recibir la correspondiente informaci\u00f3n\u201d, inform\u00f3 el funcionario municipal luego de recorrer las obras junto a representantes del Invap, con sede en Bariloche que se dedica a la investigaci\u00f3n aplicada y est\u00e1 llevando adelante la instalaci\u00f3n de la<\/p>\n<p>El radar estar\u00e1 ubicado en el predio donde se erige la Planta de Efluentes Cloacales, frente al Emisario Submarino, al norte de la ciudad. Tendr\u00e1 un radio de alcance aproximado de 480 kil\u00f3metros y permitir\u00e1 tener una previsi\u00f3n de las contingencias meteorol\u00f3gicas tanto para la ciudad de Mar del Plata, sur de la provincia de Buenos Aires y el Litoral Atl\u00e1ntico.<\/p>\n<p>\u201cEl de Mar del Plata ser\u00e1 uno de los diez radares que se instalar\u00e1n en todo el pa\u00eds. El nuestro es el cuarto. Pr\u00f3ximamente estar\u00e1 finalizado y tendr\u00e1 una terminal en el Centro de Operaciones y Monitoreo de Mar del Plata (COM), que servir\u00e1 para tener una informaci\u00f3n m\u00e1s exacta, que les servir\u00e1 a los meteor\u00f3logos poder determinar si se aproximan tormentas o no\u201d, detall\u00f3 Andueza.<\/p>\n<p><strong>Destacan rol del COM<\/strong><\/p>\n<p>Andueza tambi\u00e9n remarc\u00f3 que \u201cel COM -inaugurado en febrero de 2015, hace poco m\u00e1s de un a\u00f1o- es un modelo a seguir, no solo en biovigilancia sino tambi\u00e9n en operaciones y emergencias\u201d, por eso fue visitado por representantes de Invap que \u201clo han tomado como referencia ante la construcci\u00f3n de un Centro de Operaciones en la ciudad de C\u00f3rdoba, puntualmente en t\u00e9rminos de emergencias meteorol\u00f3gicas. Est\u00e1n viendo c\u00f3mo se instal\u00f3 en Mar del Plata y toda su infraestructura\u201d, a\u00f1adi\u00f3.<\/p>\n<p>En este sentido, el director del COM manifest\u00f3 que \u201ctenemos un centro de operaciones con una sala de crisis, con toda la tecnolog\u00eda e infraestructura armada como para poder hacer un centro de operaciones integral, no s\u00f3lo con biovigilancia\u201d y resalt\u00f3 que \u201chemos estado analizando distintos proyectos que el Invap est\u00e1 desarrollando con el Ministerio de Seguridad de Naci\u00f3n, en cuanto al procesamiento de las im\u00e1genes. C\u00f3mo se pueden implementar distintas estrategias y la tecnolog\u00eda avanzada en informaci\u00f3n que tenemos almacenada, que es mucha, y que se podr\u00eda optimizar incorporando, por ejemplo, sensores para mejorar el espacio p\u00fablico en toda la ciudad como un control de tr\u00e1fico o sem\u00e1foros\u201d.<\/p>\n<p>El funcionario remarc\u00f3 que \u201cel Centro de Operaciones de Mar del Plata es el m\u00e1s grande del pa\u00eds\u201d y que por eso \u201cnos est\u00e1n visitando de distintos lugares\u201d. \u201cNo estamos hablando solamente de un centro de biovigilancia aplicado a la seguridad, sino de un centro integral desde donde podemos tener el control no solo de la seguridad de las c\u00e1maras, sino de Defensa Civil y de cualquier otra tecnolog\u00eda aplicada a la ciudad que se quiera imponer\u201d, concluy\u00f3.<\/p>\n<h6>Fuente: La capital, Mar del Plata<\/h6>\n","protected":false},"excerpt":{"rendered":"<p>As\u00ed lo confirm\u00f3 Sergio Andueza, director del COM. \u00abFinalizamos la construcci\u00f3n de la base y todo lo relacionado a la obra civil\u00bb, asegur\u00f3. Comienza ahora la etapa final.<\/p>\n","protected":false},"author":2,"featured_media":46162,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[12],"class_list":["post-46161","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-informe-municipal","tag-buenos-aires"],"_links":{"self":[{"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/posts\/46161","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/comments?post=46161"}],"version-history":[{"count":0,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/posts\/46161\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/media\/46162"}],"wp:attachment":[{"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/media?parent=46161"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/categories?post=46161"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/tags?post=46161"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}