{"id":46209,"date":"2016-04-11T08:13:43","date_gmt":"2016-04-11T11:13:43","guid":{"rendered":"http:\/\/argentinamunicipal.com.ar\/argentina\/?p=46209"},"modified":"2016-04-11T08:13:43","modified_gmt":"2016-04-11T11:13:43","slug":"46209-2","status":"publish","type":"post","link":"http:\/\/argentinamunicipal.com.ar\/argentina\/46209-2\/","title":{"rendered":"La Justicia intentar\u00e1 mediar en el conflicto de Barranqueras"},"content":{"rendered":"<p>El procurador general del Poder Judicial, Jorge Canteros, intervino en el conflicto que mantienen desde hace m\u00e1s de un mes empleados municipales y la intendente de Barranqueras, Alicia Azula, por el pase a planta de un grupo de trabajadores precarizados y propuso a las partes que el martes inicien una instancia de mediaci\u00f3n.<\/p>\n<p>Azula dijo que este \u201ces un conflicto pol\u00edtico\u201d impulsado por uno de los dos gremios municipales que tiene el acompa\u00f1amiento de la mayor\u00eda los ediles, los cuatro de la oposici\u00f3n y uno del oficialismo, que empez\u00f3 pocos d\u00edas despu\u00e9s de asumir en diciembre su cuarto mandato.<\/p>\n<p>La jefa comunal no confirm\u00f3 la asistencia de un representante de la comuna a la mediaci\u00f3n judicial \u201cporque la Polic\u00eda constat\u00f3 que hubo destrozos de bienes municipales en la jornada del jueves por la tarde, la justicia no actu\u00f3 de oficio ni tuvo en cuenta nuestra denuncia p\u00fablica de las consecuencias de la toma\u201d parcial del edificio.<\/p>\n<p>Poco m\u00e1s de un tercio de los 900 empleados municipales est\u00e1n registrados en la planta permanente y la mayor\u00eda lo hace con distintos tipos de contratos laborales precarios, sin aportes jubilatorios ni acceso a la obra social y otros derechos.<\/p>\n<p>En tanto que la Asociaci\u00f3n Sindical de Trabajadores Municipales de Barranqueras sostiene que la intendente Azula \u201cdebe cumplir con requisitos m\u00ednimos de institucionalidad y pasar a planta en forma progresiva a los empleados contratados\u201d.<\/p>\n<p>\u201cAzula est\u00e1 desde hace muchos a\u00f1os en el municipio y solo benefici\u00f3 a un reducido grupo de allegados. Nosotros estamos planteando que cumpla con las leyes laborales vigentes y pase a planta a trabajadores precarizados con un plan cre\u00edble\u201d, dijo Ricardo Uferer, uno de los referentes de este conflicto sindical.<\/p>\n<p>El dirigente gremial dijo que \u201cen el pueblo de Barranqueras y entre los trabajadores hay un marcado hartazgo gremial por la inacci\u00f3n de la intendenta, que tuvo aspiraciones pol\u00edticas y descuid\u00f3 su tarea anteponiendo sus ambiciones personales y cuando volvi\u00f3 se encontr\u00f3 con un conflicto que es consecuen- cia de su propia gesti\u00f3n\u201d.<\/p>\n<h6>Fuente: Diario Norte<\/h6>\n","protected":false},"excerpt":{"rendered":"<p>El procurador general del Poder Judicial, Jorge Canteros, intervino en el conflicto que mantienen desde hace m\u00e1s de un mes empleados municipales y la intendente de Barranqueras, Alicia Azula, por el pase a planta de un grupo de trabajadores precarizados <\/p>\n","protected":false},"author":2,"featured_media":46210,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[30],"class_list":["post-46209","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-informe-sindical","tag-chaco"],"_links":{"self":[{"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/posts\/46209","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/comments?post=46209"}],"version-history":[{"count":0,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/posts\/46209\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/media\/46210"}],"wp:attachment":[{"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/media?parent=46209"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/categories?post=46209"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/tags?post=46209"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}