{"id":46281,"date":"2016-04-12T06:15:43","date_gmt":"2016-04-12T09:15:43","guid":{"rendered":"http:\/\/argentinamunicipal.com.ar\/argentina\/?p=46281"},"modified":"2016-04-12T07:18:27","modified_gmt":"2016-04-12T10:18:27","slug":"mendoza-respaldo-comunal-pese-no-hubo-consulta","status":"publish","type":"post","link":"http:\/\/argentinamunicipal.com.ar\/argentina\/mendoza-respaldo-comunal-pese-no-hubo-consulta\/","title":{"rendered":"Mendoza: Respaldo comunal pese a que no hubo consulta"},"content":{"rendered":"<p><span style=\"line-height: 1.5\">La propuesta que impulsar\u00e1 hoy el gobernador Alfredo Cornejo al presidente Mauricio Macri de dar prioridad a la inversi\u00f3n en obra p\u00fablica en infraestructura social b\u00e1sica, no ha sido conversada previamente entre el mandatario provincial y los intendentes mendocinos.\u00a0<\/span><\/p>\n<p>As\u00ed lo confirman desde municipios de todos los colores pol\u00edticos que -no obstante- ven con buenos ojos la posibilidad de avanzar en la realizaci\u00f3n de obras cercanas a los vecinos como las de agua potable, cloacas, gas, pavimento, cunetas y banquinas. Aunque intendentes propios y ajenos se quejan porque \u201cla Provincia nos debe entre tres y cuatro quincenas de coparticipaci\u00f3n\u201d.<\/p>\n<p>Cornejo ha mantenido dos encuentros con los intendentes el 28 de febrero y el 31 de marzo. En ambos predominaron los informes sobre las escu\u00e1lidas finanzas p\u00fablicas y \u201cla necesidad\u201d de acordar paritarias municipales con un techo del 22 % desdoblado. Ni en una ni en la otra apareci\u00f3 la obra p\u00fablica aunque en Aysam crecen los pedidos comunales de mantenimiento y ampliaci\u00f3n de las redes de agua potable y cloacas.<\/p>\n<p>\u201cTodo lo que pueda conseguir el Gobernador viene bien\u201d, afirm\u00f3 el jefe comunal capitalino Rodolfo Su\u00e1rez (UCR), ayer tambi\u00e9n en Buenos Aires.<\/p>\n<p>Hizo gestiones por su cuenta ante la Naci\u00f3n para destrabar la intrincada apertura de Avenida Godoy Cruz e impulsar la de Moldes, sobre terrenos ferroviarios. Su\u00e1rez y el presidente de Aysam, el dem\u00f3crata Richard Battagi\u00f3n, han avanzado en un acuerdo de instalaci\u00f3n de agua y cloacas en el Barrio Olivares con una inversi\u00f3n que la comuna reconocer\u00e1 condonando la deuda por 14 millones de pesos que mantiene Aguas Mendocinas por roturas de asfalto en Capital.<\/p>\n<p>\u201cEs necesario reactivar la obra p\u00fablica y generar empleo\u201d, destaca el intendente de San Carlos, Jorge Difonso afiliado al PD pero militante del Frente Renovador. \u201c<\/p>\n<p>A Aysam le hemos presentado proyectos concretos de desarrollo de agua potable y cloacas y a Infraestructura (a cargo de Sergio Marinelli) de gas natural\u201d, remarc\u00f3. E hizo notar que a fines de abril comenzar\u00e1 a colocarse producci\u00f3n agraria de seis departamentos del Valle de Uco y el Sur mendocino en el \u201cPuerto de Frutas de Tigre\u201d, por acuerdos con esa comuna.<\/p>\n<p>En tanto, el intendente de San Mart\u00edn, Jorge Omar Gim\u00e9nez (FpV) se mostr\u00f3 sumamente cr\u00edtico: \u201cEs bueno que el Presidente y el Gobernador se junten a trabajar y a hablar de obra p\u00fablica. Es bueno que se enteren que est\u00e1n gobernando. Porque hasta ahora, todo parece una gran mentira\u201d, dispar\u00f3.<\/p>\n<h6>Fuente: Los Andes<\/h6>\n","protected":false},"excerpt":{"rendered":"<p>La propuesta que impulsar\u00e1 hoy el gobernador Cornejo al presidente Macri de dar prioridad a la inversi\u00f3n en obra p\u00fablica en infraestructura social b\u00e1sica, no ha sido conversada previamente entre el mandatario provincial y los intendentes<\/p>\n","protected":false},"author":2,"featured_media":46282,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"tags":[31],"class_list":["post-46281","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-informe-politico","tag-mendoza"],"_links":{"self":[{"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/posts\/46281","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/comments?post=46281"}],"version-history":[{"count":0,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/posts\/46281\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/media\/46282"}],"wp:attachment":[{"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/media?parent=46281"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/categories?post=46281"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/tags?post=46281"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}