{"id":46307,"date":"2016-04-12T06:01:08","date_gmt":"2016-04-12T09:01:08","guid":{"rendered":"http:\/\/argentinamunicipal.com.ar\/argentina\/?p=46307"},"modified":"2016-04-12T08:04:10","modified_gmt":"2016-04-12T11:04:10","slug":"destacaron-33-promedio-los-empleados-municipales-san-juan-tendran-aumento","status":"publish","type":"post","link":"http:\/\/argentinamunicipal.com.ar\/argentina\/destacaron-33-promedio-los-empleados-municipales-san-juan-tendran-aumento\/","title":{"rendered":"33% en promedio de aumento para los empleados municipales\u00a0de San Juan"},"content":{"rendered":"<p>El secretario gremial Enrique Funes expres\u00f3 que s\u00f3lo resta definir un porcentaje en el departamento San Mart\u00edn y que se espera arribar a un acuerdo esta semana.<\/p>\n<p>Los empleados municipales sanjuaninos, a excepci\u00f3n de quienes se desempe\u00f1an en San Mart\u00edn, ya lograron su aumento salarial con un promedio del 33%.<\/p>\n<p>De acuerdo a lo que destac\u00f3 el secretario gremial de UPCN, Enrique Funes a radio Sarmiento: \u00abhubo porcentajes variables que van del 30 al 38% y hacemos un promedio del 33%. Es un n\u00famero favorable para los trabajadores y lo bueno es que hubo celeridad en el proceso\u00bb. Y agreg\u00f3 que \u00abnos queda cerrar la negociaci\u00f3n en San Mart\u00edn en el que la situaci\u00f3n no es f\u00e1cil porque el intendente est\u00e1 jugando con los tiempos\u00bb.<\/p>\n<p>Adem\u00e1s, Funes hizo un comentario cr\u00edtico: \u00ablos municipios tienen que destinar dinero propio para los empleados. Sino es f\u00e1cil pedir del Ejecutivo\u00bb, en referencia al subsidio de casi 300 millones de pesos que el gobierno de San Juan distribuir\u00e1 entre los distritos para apoyar el aumento.<\/p>\n<h6>fuente: La Provincia<\/h6>\n","protected":false},"excerpt":{"rendered":"<p>El secretario gremial Enrique Funes expres\u00f3 que s\u00f3lo resta definir un porcentaje en el departamento San Mart\u00edn y que se espera arribar a un acuerdo esta semana.<\/p>\n","protected":false},"author":2,"featured_media":46308,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[32],"class_list":["post-46307","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-informe-sindical","tag-san-juan"],"_links":{"self":[{"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/posts\/46307","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/comments?post=46307"}],"version-history":[{"count":0,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/posts\/46307\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/media\/46308"}],"wp:attachment":[{"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/media?parent=46307"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/categories?post=46307"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/tags?post=46307"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}