{"id":46336,"date":"2016-04-13T06:16:39","date_gmt":"2016-04-13T09:16:39","guid":{"rendered":"http:\/\/argentinamunicipal.com.ar\/argentina\/?p=46336"},"modified":"2016-04-13T06:16:39","modified_gmt":"2016-04-13T09:16:39","slug":"echeverria-nueva-protesta-municipales-despidos","status":"publish","type":"post","link":"http:\/\/argentinamunicipal.com.ar\/argentina\/echeverria-nueva-protesta-municipales-despidos\/","title":{"rendered":"Echeverr\u00eda: Nueva protesta de Municipales por despidos"},"content":{"rendered":"<p><span style=\"line-height: 1.5\">Desde el Sindicato de Trabajadores Municipales de Esteban Echeverr\u00eda (STMEE)denunciaron que un delegado fue \u201cdespedido injustamente\u201d.<\/span><\/p>\n<p>El lunes, los empleados del galp\u00f3n de Log\u00edstica de la Secretar\u00eda de Desarrollo Social de Esteban Echeverr\u00eda instalaron una carpa para reclamar la reincorporaci\u00f3n de Jorge Tula, un delegado del gremio que fue \u201cdespedido injustamente\u201d seg\u00fan denunciaron.<\/p>\n<p>Por la tarde, levantaron la protesta porque fueron convocados por el Ejecutivo para dialogar pero ayer no hubo avances y cuando volvieron al galp\u00f3n, el lugar estaba cerrado y nos les permitieron el ingreso.<\/p>\n<p>\u201cReclamamos que reincorporen a un compa\u00f1ero al que echaron hace una semana sin justificaci\u00f3n, lo \u00fanico que le dijeron es que era contratado\u201d, asever\u00f3 el secretario General Adjunto del Sindicato, Ricardo Ju\u00e1rez, a Info Regi\u00f3n.<\/p>\n<p>\u201cEl lunes instalamos las carpas pero el subsecretario de Gobierno, N\u00e9stor Bianchini, nos llam\u00f3 y nos pidi\u00f3 que levantemos la medida de fuerza porque el intendente Fernando Gray dio la orden para ir a un dialogo pero cuando nos presentamos fue in\u00fatil porque primero tienen que reincorporar al compa\u00f1ero que mal echaron\u201d, reclam\u00f3 Ju\u00e1rez.<\/p>\n<p>Indic\u00f3 que tras la reuni\u00f3n volvieron al galp\u00f3n pero \u201clas puertas estaban cerradas\u201d. \u201cNo nos dejaron ingresar a trabajar, por eso hicimos un acta para que firmen todos los trabajadores que se hicieron presentes y aunque los de personal no nos quisieron recibir el acta, se lo llevamos directamente a Bianchini y se lo presentamos a Desarrollo Social para que conste que los trabajadores estamos ac\u00e1 y cumplimos horario\u201d, remarc\u00f3.<\/p>\n<p>Ju\u00e1rez, por \u00faltimo, asegur\u00f3 que seguir\u00e1n las medidas de fuerza porque \u201cse niegan a reincorporarlo sabiendo que es delegado del gremio y que dejan a una familia en la calle\u201d.<\/p>\n<h6>Fuente: InfoRegi\u00f3n<\/h6>\n","protected":false},"excerpt":{"rendered":"<p>Desde el Sindicato de Trabajadores Municipales de Esteban Echeverr\u00eda (STMEE)denunciaron que un delegado fue \u201cdespedido injustamente\u201d.<\/p>\n","protected":false},"author":2,"featured_media":46337,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[12],"class_list":["post-46336","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-informe-sindical","tag-buenos-aires"],"_links":{"self":[{"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/posts\/46336","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/comments?post=46336"}],"version-history":[{"count":0,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/posts\/46336\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/media\/46337"}],"wp:attachment":[{"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/media?parent=46336"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/categories?post=46336"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/tags?post=46336"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}