{"id":46431,"date":"2016-04-14T06:48:14","date_gmt":"2016-04-14T09:48:14","guid":{"rendered":"http:\/\/argentinamunicipal.com.ar\/argentina\/?p=46431"},"modified":"2016-04-14T06:48:14","modified_gmt":"2016-04-14T09:48:14","slug":"mas-400-intendentes-avalaron-ayer-presencia-acuerdo-federal-schiaretti","status":"publish","type":"post","link":"http:\/\/argentinamunicipal.com.ar\/argentina\/mas-400-intendentes-avalaron-ayer-presencia-acuerdo-federal-schiaretti\/","title":{"rendered":"M\u00e1s de 400 intendentes avalaron ayer con su presencia el Acuerdo Federal de Schiaretti"},"content":{"rendered":"<p>La gran mayor\u00eda de los municipios adherir\u00e1 a los fondos para obras viales, de cloacas, agua y desag\u00fces. Tambi\u00e9n recibir\u00e1n los recursos para la Polic\u00eda. En cambio, subsiste la resistencia al traspaso del Paicor.<\/p>\n<p>En el marco de un acto desarrollado en el Centro C\u00edvico de C\u00f3rdoba, el gobernador Juan Schiaretti present\u00f3 ayer el nuevo Acuerdo Federal ante m\u00e1s de 350 intendentes de toda la provincia y en forma simb\u00f3lica suscribi\u00f3 el contenido del mismo con los jefes municipales de C\u00f3rdoba (el radical Ram\u00f3n Mestre), de Villa Carlos Paz (el vecinalista Esteban Avil\u00e9s), de Jes\u00fas Mar\u00eda (el macrista Gabriel Frizza) y de La Carlota (el justicialista Fabio Guaschino).<\/p>\n<p>Ante la atenta mirada de sus ministros y de quienes ostentan el poder territorial en los diferentes pueblos y ciudades de C\u00f3rdoba, el mandatario provincial destac\u00f3 que este acuerdo \u201cactualiza el federalismo en la provincia para que el Gobierno y el poder se hagan m\u00e1s territorial y lleguen de manera directa a la gente\u201d. Tambi\u00e9n anticip\u00f3 que el mismo ser\u00e1 ratificado a trav\u00e9s de una ley por la Legislatura Unicameral de C\u00f3rdoba.<\/p>\n<p>Adem\u00e1s de explicar los lineamientos generales de los nuevos fondos de obras que se crear\u00e1n con sendos aportes de la Provincia, Schiaretti defendi\u00f3 la propuesta de transferir a los municipios y comunas el mantenimiento de edificios y m\u00f3viles policiales, la limpieza de escuelas y el servicio del Paicor, con recursos que su administraci\u00f3n girar\u00e1 todos los meses junto a la coparticipaci\u00f3n.<\/p>\n<p>Las c\u00e1pitas para alimentar a cada ni\u00f1o se ir\u00e1n actualizando en funci\u00f3n de la inflaci\u00f3n. Adem\u00e1s, se tendr\u00e1 en cuenta el padr\u00f3n actualizado por la Provincia que determin\u00f3 que el 30% de los alumnos de escuelas p\u00fablicas necesita esta prestaci\u00f3n porque sus familias est\u00e1n bajo la l\u00ednea de la pobreza.<\/p>\n<p>En el acto Schiaretti confirm\u00f3 las primicias de LA MA\u00d1ANA sobre la creaci\u00f3n de estos nuevos fondos de obras y la transferencia de servicios provinciales como el Paicor. Tambi\u00e9n ratific\u00f3 lo anticipado por este medio en el sentido de que se modificar\u00e1n los \u00edndices vigentes para el reparto de coparticipaci\u00f3n provincial en funci\u00f3n del Censo Nacional 2010 y se actualizar\u00e1n las cifras que se entregan por Fofindes, para que los intendentes financien de una manera m\u00e1s justa y eficiente la atenci\u00f3n primaria de la salud que brindan en sus pueblos.<\/p>\n<p>\u201cTengo plena confianza en la capacidad de gesti\u00f3n de los intendentes, tal como se ha demostrado en los \u00faltimos a\u00f1os con la transferencia de recursos para el mantenimiento de escuelas. Ahora pretendemos hacer lo mismo con el servicio de alimentaci\u00f3n del Paicor, el sost\u00e9n de las comisar\u00edas y los m\u00f3viles policiales\u201d, enfatiz\u00f3 Schiaretti. Una vez que los jefes municipales suscriban los convenios particulares, la Provincia pondr\u00e1 a disposici\u00f3n de cada uno de ellos seg\u00fan un \u00edndice similar al de coparticipaci\u00f3n, una suma total de 690 millones de pesos correspondientes a dos grandes fondos de obras p\u00fablicas (uno para cord\u00f3n cuneta y pavimento y la colocaci\u00f3n de c\u00e1maras de seguridad por 390 millones y el restante de 300 millones de pesos para redes de cloacas, gas y desag\u00fces y gastos administrativos de las comunas).<\/p>\n<p>Estos recursos deber\u00e1n ser devueltos por los intendentes con 30 pagos mensuales sin inter\u00e9s, con cuatro meses de gracia y una quita en car\u00e1cter de subsidio del 25% en relaci\u00f3n al monto original que servir\u00e1 para compensar parte de las deudas que tiene la Provincia con los municipios y comunas.<\/p>\n<p>El Gobierno aportar\u00e1 anualmente hasta 2019 un monto similar de su propio presupuesto para los dos fondos de obras mencionados (ser\u00e1n 2760 millones de pesos en cuatro a\u00f1os). Estas partidas se fortalecer\u00e1n todos los meses con el dinero que vayan devolviendo los intendentes de los pr\u00e9stamos recibidos.<\/p>\n<p>En otras palabras, los jefes municipales de C\u00f3rdoba tendr\u00e1n tres fondos disponibles para obras ya que se mantiene el creado hace ya varios a\u00f1os por Jos\u00e9 Manuel de la Sota. Todos ellos ser\u00e1n administrados por la Mesa de Trabajo Provincia-Municipios, seg\u00fan admiti\u00f3 el propio gobernador Juan Schiaretti en el marco del acto de ayer.<\/p>\n<p>Habr\u00e1 adem\u00e1s otro fondo complementario para obras de municipios y comunas por 217 millones que administrar\u00e1 discrecionalmente la Provincia.<\/p>\n<h6>Fuente: La Ma\u00f1ana de C\u00f3rdoba<\/h6>\n","protected":false},"excerpt":{"rendered":"<p>La gran mayor\u00eda de los municipios adherir\u00e1 a los fondos para obras viales, de cloacas, agua y desag\u00fces. Tambi\u00e9n recibir\u00e1n los recursos para la Polic\u00eda. En cambio, subsiste la resistencia al traspaso del Paicor.<\/p>\n","protected":false},"author":2,"featured_media":46432,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"tags":[3],"class_list":["post-46431","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-informe-politico","tag-cordoba"],"_links":{"self":[{"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/posts\/46431","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/comments?post=46431"}],"version-history":[{"count":0,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/posts\/46431\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/media\/46432"}],"wp:attachment":[{"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/media?parent=46431"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/categories?post=46431"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/tags?post=46431"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}