{"id":46479,"date":"2016-04-14T06:26:15","date_gmt":"2016-04-14T09:26:15","guid":{"rendered":"http:\/\/argentinamunicipal.com.ar\/argentina\/?p=46479"},"modified":"2016-04-14T08:28:52","modified_gmt":"2016-04-14T11:28:52","slug":"detienen-alcalde-caso-corrupcion-espana","status":"publish","type":"post","link":"http:\/\/argentinamunicipal.com.ar\/argentina\/detienen-alcalde-caso-corrupcion-espana\/","title":{"rendered":"Detienen a otro alcalde por caso de corrupci\u00f3n en Espa\u00f1a"},"content":{"rendered":"<p>La polic\u00eda espa\u00f1ola arrest\u00f3 ayer al alcalde de Granada, Jos\u00e9 Torres Hurtado, del Partido Popular (PP), por su presunta implicaci\u00f3n en una trama de corrupci\u00f3n urban\u00edstica en esa ciudad, una de las m\u00e1s tur\u00edsticas del sur de Espa\u00f1a. \u00abAqu\u00ed no hay corrupci\u00f3n; ni antes, ni despu\u00e9s, ni ahora tampoco\u00bb, dijo Torres Hurtado tras quedar en libertad con cargos luego de declarar ante la jefatura Superior de Polic\u00eda de Andaluc\u00eda Oriental.<\/p>\n<p>El alcalde de Granada, considerado un dirigente cercano al presidente en funciones y l\u00edder de los conservadores espa\u00f1oles, Mariano Rajoy, remarc\u00f3 que no piensa dimitir de su cargo: \u00abSeguir\u00e9 trabajando por la ciudad el tiempo que me dejen o me corresponda o Dios me d\u00e9 salud\u00bb, sostuvo.<\/p>\n<p>Sin embargo, el Comit\u00e9 de Derechos y Garant\u00edas del PP decidi\u00f3 suspenderlo de militancia de forma cautelar tanto a \u00e9l como a su concejal de Urbanismo.<\/p>\n<p>En el marco del operativo fueron detenidas 17 personas, entre ellas la concejal de Urbanismo, Isabel Nieto, e importantes empresarios de la construcci\u00f3n, seg\u00fan inform\u00f3 la prensa espa\u00f1ola.<\/p>\n<p>Las actuaciones judiciales parten de dos querellas de la Fiscal\u00eda de Urbanismo y Medio Ambiente de Granada para investigar la existencia de una trama corrupta en el \u00e1rea de Urbanismo del ayuntamiento.<\/p>\n<h6>Fuente: el Liberal<\/h6>\n","protected":false},"excerpt":{"rendered":"<p>La polic\u00eda espa\u00f1ola arrest\u00f3 ayer al alcalde de Granada, Jos\u00e9 Torres Hurtado, del Partido Popular (PP), por su presunta implicaci\u00f3n en una trama de corrupci\u00f3n urban\u00edstica en esa ciudad<\/p>\n","protected":false},"author":2,"featured_media":46480,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[22],"tags":[57],"class_list":["post-46479","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-el-mundo","tag-el-mundo"],"_links":{"self":[{"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/posts\/46479","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/comments?post=46479"}],"version-history":[{"count":0,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/posts\/46479\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/media\/46480"}],"wp:attachment":[{"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/media?parent=46479"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/categories?post=46479"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/tags?post=46479"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}