{"id":46573,"date":"2016-04-15T08:20:08","date_gmt":"2016-04-15T11:20:08","guid":{"rendered":"http:\/\/argentinamunicipal.com.ar\/argentina\/?p=46573"},"modified":"2016-04-15T08:20:08","modified_gmt":"2016-04-15T11:20:08","slug":"subiran-seguro-desempleo-3-000-salario-minimo-7-800","status":"publish","type":"post","link":"http:\/\/argentinamunicipal.com.ar\/argentina\/subiran-seguro-desempleo-3-000-salario-minimo-7-800\/","title":{"rendered":"Subir\u00e1n el seguro por desempleo a $ 3.000 y el salario m\u00ednimo a $ 7.800"},"content":{"rendered":"<p>Sobre el piso de ingresos se prev\u00e9 una suba en torno del 30% en dos etapas. El subsidio para cesantes, que desde hace una d\u00e9cada permanece congelado en $ 400, se elevar\u00e1 a 3.000 pesos y luego se ajustar\u00e1 autom\u00e1ticamente.<br \/>\n<span style=\"line-height: 1.5\"><br \/>\n<\/span><\/p>\n<p><span style=\"line-height: 1.5\">El Gobierno planea aumentar el salario m\u00ednimo y reformular el seguro por desempleo para darles un volumen mayor como pol\u00edticas sociales de contenci\u00f3n. Sobre el piso de ingresos, que ser\u00e1 discutido en mayo, se prev\u00e9 una suba en torno del 30% en dos etapas, para llevarlo de los actuales $ 6.060 a un valor de entre 7.600 y 7.800 pesos. Mientras que al subsidio para cesantes, que desde hace una d\u00e9cada permanece congelado en $ 400, el gabinete econ\u00f3mico tiene resuelto elevarlo a por lo menos 3.000 pesos y engancharlo con el ajuste anual del salario m\u00ednimo.<\/span><\/p>\n<p>Se trata del detalle de los anuncios que Mauricio Macri les adelant\u00f3 a los jefes y principales referentes de las tres versiones de la CGT, y que no incluy\u00f3 respuestas a otras demandas como un freno legal a los despidos y la reforma inmediata del Impuesto a las Ganancias. En cambio, el mandatario s\u00ed se comprometi\u00f3 a distribuir en el corto plazo una remesa adicional de $ 2.700 millones a las obras sociales gremiales, entre otras reivindicaciones de menor impacto p\u00fablico pero estrat\u00e9gicas para el sindicalismo tradicional.<\/p>\n<p>El combo desplegado por Macri en el encuentro con los gremialistas tuvo como eje un pedido de comprensi\u00f3n y paciencia, bajo la premisa de que en la segunda mitad del a\u00f1o el Gobierno da por sentada una desaceleraci\u00f3n de la inflaci\u00f3n. En el gabinete econ\u00f3mico admitieron que qued\u00f3 desactualizada la perspectiva de una suba de precios anual en el rango del 20 al 25%, como hab\u00edan enunciado, sobre todo por el impacto de la suba de tarifas de servicios p\u00fablicos. Pero alegan que una vez absorbidos esos incrementos habr\u00e1 una desaceleraci\u00f3n en el segundo semestre que determinar\u00e1, siempre a juicio de los funcionarios, una inflaci\u00f3n anual del 28 al 29 por ciento.<\/p>\n<p>Aunque el encuentro tuvo momentos de tensi\u00f3n, los colaboradores de Macri creen que imper\u00f3 el pragmatismo de los dirigentes y que le otorgar\u00e1n al Ejecutivo el tiempo necesario para imponer su visi\u00f3n de la pol\u00edtica salarial y social. Para convencerlos -adem\u00e1s de garantizarles financiamiento para las obras sociales-, el Presidente y sus colaboradores les trazaron un sendero de anuncios y medidas con el objetivo de atender las situaciones m\u00e1s cr\u00edticas producto de presumibles crisis en el empleo privado.<\/p>\n<p>La primera escala del plan comenzar\u00e1 en mayo, con la convocatoria anticipada del Consejo del Salario M\u00ednimo, Vital y M\u00f3vil. Si bien esa instituci\u00f3n se define en una negociaci\u00f3n entre empresarios (las principales c\u00e1maras) y sindicalistas (hay representaci\u00f3n mayoritaria de la CGT y minoritaria de CTA) el Ministerio de Trabajo, que encabeza Jorge Triaca, apuntar\u00e1 a guiarlo hacia una suba anual del 30% en dos etapas: la primera, de los actuales $ 6.060 a cerca de 7.000 pesos, y la segunda cuota para llevar el piso a no m\u00e1s de 7.800 pesos.<\/p>\n<p>El salario m\u00ednimo tiene un impacto directo sobre menos de 200 mil trabajadores que no est\u00e1n regidos por Convenios Colectivos de Trabajo y que perciben ese monto, pero el inter\u00e9s central del Gobierno pasa por su incidencia sobre otros grupos: el m\u00e1s numeroso es el de asalariados informales, que alcanzan el 34% del total en el mercado laboral argentino y que seg\u00fan los funcionarios cuentan con ese piso como referencia. Pero tambi\u00e9n influye sobre los trabajadores municipales, muchos de ellos con ingresos inferiores al m\u00ednimo nacional.<\/p>\n<p>Seg\u00fan los planes oficiales, el Consejo cumplir\u00e1 por primera vez en una d\u00e9cada uno de sus prop\u00f3sitos pendientes: el ajuste del subsidio por desempleo, que permanece congelado desde hace a\u00f1os en 400 pesos. Los funcionarios se propusieron en este \u00edtem poner el mayor esfuerzo fiscal y elevarlo a por lo menos $ 3.000, y brindarle al beneficiario, adem\u00e1s, la posibilidad de percibir la Asignaci\u00f3n Universal por Hijo en caso de ser padre de familia.<\/p>\n<p>De ese modo, el subsidio que en la actualidad cobran apenas 60 mil personas -muchos desocupados ni siquiera lo tramitan por lo exiguo del monto- pasar\u00eda, seg\u00fan el Ejecutivo, a constituirse como una pol\u00edtica social de contenci\u00f3n frente a eventuales cierres de empresas en lo que resta del a\u00f1o. Una vez elevado el monto del subsidio se lo dejar\u00e1 atado a la movilidad del salario m\u00ednimo.<\/p>\n<p>En el gabinete econ\u00f3mico dijeron que el primero en dar su aval a la nueva pol\u00edtica en torno del subsidio por desempleo fue Hugo Moyano, el mismo que se hab\u00eda encargado de enhebrar un acuerdo con los bloques opositores del Congreso para impulsar una ley de \u00abemergencia ocupacional\u00bb con la aplicaci\u00f3n de una indemnizaci\u00f3n superior a la legal.<\/p>\n<p>Ayer, de todos modos, el portuario Juan Carlos Schmid, presente en la cumbre de Olivos y aliado estrecho de Moyano, dijo que el encuentro con Macri fue \u00abmuy poco alentador\u00bb y reclam\u00f3 \u00abequilibrar con los intereses de los trabajadores\u00bb. Se trata de la din\u00e1mica habitual de Moyano, de mostrarse componedor y acuerdista en privado y confrontativo -por s\u00ed o a trav\u00e9s de sus colaboradores- en p\u00fablico.<\/p>\n<p>El 29 de abril se terminar\u00e1 de conocer el tono del sindicalismo tradicional hacia los anuncios del Gobierno en el acto que har\u00e1n las CGT junto con las dos CTA frente al Monumento al Trabajo.<\/p>\n<h6>Fuente: El Once<\/h6>\n","protected":false},"excerpt":{"rendered":"<p>Sobre el piso de ingresos se prev\u00e9 una suba en torno del 30% en dos etapas. El subsidio para cesantes, que desde hace una d\u00e9cada permanece congelado en $ 400, se elevar\u00e1 a 3.000 pesos y luego se ajustar\u00e1 autom\u00e1ticamente.<\/p>\n","protected":false},"author":2,"featured_media":46574,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[8],"tags":[21],"class_list":["post-46573","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-informe-nacional","tag-argentina"],"_links":{"self":[{"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/posts\/46573","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/comments?post=46573"}],"version-history":[{"count":0,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/posts\/46573\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/media\/46574"}],"wp:attachment":[{"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/media?parent=46573"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/categories?post=46573"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/tags?post=46573"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}