{"id":46589,"date":"2016-04-15T16:02:00","date_gmt":"2016-04-15T19:02:00","guid":{"rendered":"http:\/\/argentinamunicipal.com.ar\/argentina\/?p=46589"},"modified":"2016-04-15T16:02:00","modified_gmt":"2016-04-15T19:02:00","slug":"alerta-la-uom-despidos-suspensiones-tierra-del-fuego","status":"publish","type":"post","link":"http:\/\/argentinamunicipal.com.ar\/argentina\/alerta-la-uom-despidos-suspensiones-tierra-del-fuego\/","title":{"rendered":"Alerta en la UOM por despidos y suspensiones en Tierra del Fuego"},"content":{"rendered":"<p><span style=\"line-height: 1.5\">La empresa Brightstart, productora de tel\u00e9fonos celulares, anunci\u00f3 en las \u00faltimas horas la decisi\u00f3n de despedir a 120 empleados de planta permanente y dar de baja a la totalidad de contratados y de\u00a0personal denominado \u00abde planta discontinuo\u00bb, con lo que sumaban 258 desafectaciones.<\/span><\/p>\n<p>Por esta situaci\u00f3n, la Uni\u00f3n Obrera Metal\u00fargica (UOM) realizaba asambleas desde anoche.<\/p>\n<p>Encabezados por el secretario general de la seccional local del gremio, el diputado nacional Oscar Mart\u00ednez, los trabajadores elevar\u00e1n una contrapropuesta a la firma, impulsando una reducci\u00f3n horaria y salarial para conservar los puestos laborales.<\/p>\n<p>Fuentes gremiales admitieron que el panorama es \u00abcomplicado\u00bb, y apuntaron a \u00abmedidas del gobierno nacional como la apertura de las importaciones y la devaluaci\u00f3n\u00bb.<\/p>\n<p>En tanto, desde la empresa confirmaron que la decisi\u00f3n se debe a la baja en las ventas en los primeros cuatro meses del a\u00f1o, y a que, seg\u00fan se inform\u00f3 extraoficialmente, los canales de venta se encuentran con seis meses de stock, siendo que el mercado est\u00e1 estancado, aunque todav\u00eda se mantiene la expectativa para el segundo semestre del a\u00f1o.<\/p>\n<p>El anuncio de Brightstart se suma a la baja de 300 contratos que se produjeron d\u00edas atr\u00e1s en la planta IATEC, del Grupo Mirgor, y a la situaci\u00f3n de la empresa Foxman, donde los trabajadores no cobran sus salarios desde el mes de diciembre y fueron abandonados recientemente por la patronal, que se retir\u00f3 de la f\u00e1brica sin dar mayores explicaciones.<\/p>\n<p><span style=\"line-height: 1.5\">Adem\u00e1s, se espera la finalizaci\u00f3n de contratos que, seg\u00fan trascendi\u00f3, no ser\u00edan renovados en la empresa BGH y otras firmas.<\/span><\/p>\n<p>Semana atr\u00e1s, el propio Oscar Mart\u00ednez advert\u00eda durante una jornada de paro y movilizaci\u00f3n que llevaron adelante los metal\u00fargicos, su preocupaci\u00f3n ante \u00abla incertidumbre que existe respecto del futuro de la industria en la provincia\u00bb.<\/p>\n<p>Por el mismo motivo, el Congreso de Delegados de la UOM R\u00edo Grande se declar\u00f3 en estado de sesi\u00f3n permanente desde el comienzo del a\u00f1o, y llev\u00f3 adelante un paro con movilizaci\u00f3n del pasado 29 de marzo.<\/p>\n<p>Mientras tanto, en la provincia crece el temor por la continuidad del R\u00e9gimen de Promoci\u00f3n Industrial que beneficia al sector y vence en 2022.<\/p>\n<p>En su reciente visita a Tierra del Fuego, el ministro del Interior, Rogelio Frigerio, asegur\u00f3 que el Gobierno nacional entiende que \u00abla Promoci\u00f3n Industrial no alcanza para todo lo que necesita la Isla, que es necesario sostenerla porque la Isla no puede vivir sin eso en este momento. Pero que hay que pensar mucho m\u00e1s en grande\u00bb.<\/p>\n<p>FUENTE. EL LITORAL\/DYN<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Movilizaciones en la isla<\/p>\n","protected":false},"author":5,"featured_media":46590,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[65],"tags":[],"class_list":["post-46589","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-provincias"],"_links":{"self":[{"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/posts\/46589","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/comments?post=46589"}],"version-history":[{"count":0,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/posts\/46589\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/media\/46590"}],"wp:attachment":[{"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/media?parent=46589"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/categories?post=46589"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/tags?post=46589"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}