{"id":46761,"date":"2016-04-19T05:30:54","date_gmt":"2016-04-19T08:30:54","guid":{"rendered":"http:\/\/argentinamunicipal.com.ar\/argentina\/?p=46761"},"modified":"2016-04-19T08:33:30","modified_gmt":"2016-04-19T11:33:30","slug":"chalten-afirman-precaria-la-situacion-los-municipales","status":"publish","type":"post","link":"http:\/\/argentinamunicipal.com.ar\/argentina\/chalten-afirman-precaria-la-situacion-los-municipales\/","title":{"rendered":"El Chalt\u00e9n: Afirman que es precaria la situaci\u00f3n de los municipales"},"content":{"rendered":"<p>El delegado de UPCN, Manuel C\u00e1ceres, describi\u00f3 que los sueldos son bajos frente al costo de los precios, y se pagan a mediados de mes.<\/p>\n<p><span style=\"line-height: 1.5\">Dijo que reclamaron tambi\u00e9n la sanci\u00f3n del presupuesto y organigrama. Aclar\u00f3 que a\u00fan no analizan medidas de fuerza.<\/span><\/p>\n<p>\u201cEl empleado municipal est\u00e1 precarizado en todos sus aspectos\u201d, dijo en FM Dimensi\u00f3n el delegado de UPCN de El Chalt\u00e9n.<\/p>\n<p>El nuevo municipio santacruce\u00f1o naci\u00f3 en un momento econ\u00f3mico dif\u00edcil para la provincia, y se ve particularmente afectado, ya que legalmente recibe ingresos como una Comisi\u00f3n de Fomento, y no est\u00e1 contemplado como Municipio en el reparto de la coparticipaci\u00f3n.<\/p>\n<p><strong>Ingresos\u00a0<\/strong><br \/>\nEl referente gremial dijo que los empleados tienen un salario bajo, desde los 6.800 y 7.800 pesos por mes, \u201cteniendo en cuenta que nuestra canasta b\u00e1sica es un 40 por ciento m\u00e1s elevada que El Calafate\u201d.<\/p>\n<p>Adem\u00e1s \u201cestamos cobrando el salario fuera de los t\u00e9rminos legales\u201d aclar\u00f3, y dijo que esto implica tener que pagar intereses en la tarjeta de cr\u00e9dito o los pr\u00e9stamos personales. \u201cEsto acrecienta la crisis econ\u00f3mica de los empleados municipales\u201d, manifest\u00f3 C\u00e1ceres.<\/p>\n<p>Tambi\u00e9n dijo saber \u201cque hay ingresos (incluidos cargos pol\u00edticos) y esto cada vez precariza m\u00e1s a los empleados municipales\u201d.<\/p>\n<p>Hoy la planta municipal ronda los 100 empleados, contando los del Concejo Deliberante.<\/p>\n<p>En El Chalt\u00e9n a\u00fan no se conform\u00f3 el gremio del Sindicato de Obreros y Empleados Municipales (SOEM). El referente de UPCN agreg\u00f3 tambi\u00e9n que \u201cdesde hace m\u00e1s de un a\u00f1o y medio venimos luchando por la reconversi\u00f3n del empleado p\u00fablico, en cuanto a cuestiones laborales, categor\u00edas, etc.\u201d.<\/p>\n<p>En FM Dimensi\u00f3n, C\u00e1ceres manifest\u00f3 que \u201ccomo gremio tenemos di\u00e1logo con el intendente Andrade\u201d.<\/p>\n<p>El jefe comunal fundamenta que la crisis impacta directamente a El Chalt\u00e9n, que es una cuesti\u00f3n de tiempo y que la situaci\u00f3n va a ir mejorando.<\/p>\n<p>El referente gremial describi\u00f3 que sobre esta situaci\u00f3n se han hecho reclamos por escrito y de manera informal.<br \/>\nOtro de los pedidos es que se defina el presupuesto municipal para el presente a\u00f1o, como tambi\u00e9n la realizaci\u00f3n del organigrama, algo que a\u00fan no fue enviado por el Ejecutivo al Concejo Deliberante.<\/p>\n<p><span style=\"line-height: 1.5\">C\u00e1ceres se\u00f1al\u00f3 que hasta el momento \u201cno hemos hecho todav\u00eda ninguna medida de fuerza, entendiendo la situaci\u00f3n y acompa\u00f1ando. Pero la situaci\u00f3n del empleado municipal cada vez se complica m\u00e1s y la realidad marca que en alg\u00fan momento esto no se va a poder sostener\u201d.<\/span><\/p>\n<h6>Fuente: La Opini\u00f3n Austral<\/h6>\n","protected":false},"excerpt":{"rendered":"<p>El delegado de UPCN, Manuel C\u00e1ceres, describi\u00f3 que los sueldos son bajos frente al costo de los precios, y se pagan a mediados de mes. <\/p>\n","protected":false},"author":2,"featured_media":46762,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[29],"class_list":["post-46761","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-informe-sindical","tag-santa-cruz"],"_links":{"self":[{"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/posts\/46761","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/comments?post=46761"}],"version-history":[{"count":0,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/posts\/46761\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/media\/46762"}],"wp:attachment":[{"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/media?parent=46761"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/categories?post=46761"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/tags?post=46761"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}