{"id":46812,"date":"2016-04-20T05:32:31","date_gmt":"2016-04-20T08:32:31","guid":{"rendered":"http:\/\/argentinamunicipal.com.ar\/argentina\/?p=46812"},"modified":"2016-04-20T07:40:53","modified_gmt":"2016-04-20T10:40:53","slug":"cordoba-inquilino-mas-dificil-mas-caro-ciudades-turisticas","status":"publish","type":"post","link":"http:\/\/argentinamunicipal.com.ar\/argentina\/cordoba-inquilino-mas-dificil-mas-caro-ciudades-turisticas\/","title":{"rendered":"C\u00f3rdoba: Ser inquilino es m\u00e1s dif\u00edcil y m\u00e1s caro en ciudades tur\u00edsticas"},"content":{"rendered":"<p>M\u00e1s inmuebles se destinan al turismo y hay menos oferta de casas y departamentos para vivir. Varios ofrecen arrendar de marzo a diciembre.<\/p>\n<p><span style=\"line-height: 1.5\">Carlos Paz, Santa Rosa, La Falda. Alquilar una vivienda resulta complicado en cualquier ciudad. La demanda supera a la oferta y los costos complican a muchos con ingresos medios y bajos. El d\u00e9ficit habitacional que padece el pa\u00eds les cobra factura a los inquilinos. Pero la situaci\u00f3n parece a\u00fan m\u00e1s dif\u00edcil en las ciudades tur\u00edsticas. Entre otras razones, porque se construye m\u00e1s pensando en los turistas que en los que necesitan habitar todo el a\u00f1o.<\/span><\/p>\n<p>En localidades donde parte de la oferta de alojamiento est\u00e1 compuesta por casas y departamentos, el cuadro es m\u00e1s complicado que en aquellas donde se concentra casi exclusivamente en hoteler\u00eda y caba\u00f1as.<\/p>\n<p>Carlos Paz, la mayor ciudad tur\u00edstica cordobesa, da fe de esta situaci\u00f3n. Con costos similares a los de los barrios m\u00e1s caros de C\u00f3rdoba capital, alquilar una vivienda suele ser una misi\u00f3n compleja. Muchos propietarios prefieren \u201cguardar\u201d sus casas y departamentos para la temporada de verano ya que, seg\u00fan sus cuentas, ganan lo mismo en unos meses que por un arrendamiento anual.<\/p>\n<p>El problema surge para los inquilinos que buscan d\u00f3nde vivir. Hay casos en los que los due\u00f1os ponen como condici\u00f3n que quien alquila abandone la propiedad en diciembre, para ofrecerla a otros en verano.<\/p>\n<h6>Fuente: La Voz del interior<\/h6>\n","protected":false},"excerpt":{"rendered":"<p>M\u00e1s inmuebles se destinan al turismo y hay menos oferta de casas y departamentos para vivir. Varios ofrecen arrendar de marzo a diciembre.<\/p>\n","protected":false},"author":2,"featured_media":46813,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[3],"class_list":["post-46812","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-informe-municipal","tag-cordoba"],"_links":{"self":[{"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/posts\/46812","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/comments?post=46812"}],"version-history":[{"count":0,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/posts\/46812\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/media\/46813"}],"wp:attachment":[{"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/media?parent=46812"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/categories?post=46812"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/tags?post=46812"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}