{"id":46851,"date":"2016-04-20T08:31:11","date_gmt":"2016-04-20T11:31:11","guid":{"rendered":"http:\/\/argentinamunicipal.com.ar\/argentina\/?p=46851"},"modified":"2016-04-20T08:31:11","modified_gmt":"2016-04-20T11:31:11","slug":"gobierno-anuncio-la-reanudacion-las-obras-conectaran-cacheuta-potrerillos","status":"publish","type":"post","link":"http:\/\/argentinamunicipal.com.ar\/argentina\/gobierno-anuncio-la-reanudacion-las-obras-conectaran-cacheuta-potrerillos\/","title":{"rendered":"El Gobierno anunci\u00f3 la reanudaci\u00f3n de las obras que conectar\u00e1n Cacheuta con Potrerillos"},"content":{"rendered":"<p>Lo confirm\u00f3 Alfredo Cornejo tras anunciar el comienzo del t\u00fanel que unir\u00e1 ambas localidades, incomunicadas desde hace m\u00e1s de 10 a\u00f1os.<\/p>\n<p>El Gobernador Alfredo Cornejo, junto al ministro de Econom\u00eda, Infraestructura y Energ\u00eda, Enrique Vaqui\u00e9, constat\u00f3 los trabajos que se est\u00e1n ejecutando en la ruta provincial N\u00b082 que permitir\u00e1 la uni\u00f3n de Cacheuta con Potrerillos, una desconexi\u00f3n que, por un error de obra durante el gobierno de Julio Cobos, lleva m\u00e1s de 10 a\u00f1os.<\/p>\n<p>\u00abHemos venido a presentar esta obra civil tan importante para la Provincia, para el turismo, y para la conectividad de la monta\u00f1a\u00bb, se\u00f1al\u00f3 Cornejo durante la conferencia de prensa donde present\u00f3 los detalles, luego de observar los planos junto a los ingenieros inspectores de la obra.<\/p>\n<p>A su vez, Cornejo aclar\u00f3: \u00abMa\u00f1ana comienzan las obras que conectar\u00e1n Cacheuta con el Perilago. Esta es la primera vez que las m\u00e1quinas comenzar\u00e1n a trabajar, de ambos lados, con un plazo de ejecuci\u00f3n que las partes queremos cumplir\u00bb. Si bien el proyecto llevar\u00e1 varios meses el plazo de la obra finaliza en noviembre del 2017.<\/p>\n<p>\u00abHemos tomado la decisi\u00f3n de avanzar con esta obra, que ten\u00eda un buen proyecto. Entre las m\u00faltiples ventajas \u2013que destac\u00f3 el Gobernador- la m\u00e1s importante, en el corto plazo, es que va a generar m\u00e1s de 300 empleos directos\u00bb.<\/p>\n<p>La obra se encuentra en la etapa de construcci\u00f3n de una rampa para llegar a la boca del t\u00fanel y en la fortificaci\u00f3n del cerro para prevenir derrumbes. En las pr\u00f3ximas semanas comenzar\u00e1 con labores m\u00e1s fuertes, con el inicio del t\u00fanel, cuya ejecuci\u00f3n requiere de dos tercios de la inversi\u00f3n. En este sentido el Gobernador estim\u00f3 que \u00abla perforaci\u00f3n para hacer el t\u00fanel representa el 75% del costo total del proyecto. Es una obra muy importante y que vale la pena realizar\u00bb.<\/p>\n<p><strong>El inicio<\/strong><br \/>\nMa\u00f1ana mi\u00e9rcoles, representantes t\u00e9cnicos del Banco Interamericano de Desarrollo (BID) visitar\u00e1n la provincia para observar los avances f\u00edsicos y financieros del proyecto, que se enmarcan en el programa de financiaci\u00f3n Mendoza Tecnol\u00f3gica, dependiente del BID. \u00abEsta obra representa una gran inversi\u00f3n de la provincia, son $386.961.328,58 millones de pesos que estaban adjudicados\u00bb coment\u00f3 Cornejo.<\/p>\n<p>El Gobernador tambi\u00e9n dio algunos detalles del financiamiento al explicar que \u00abtiene una financiaci\u00f3n del BID, a trav\u00e9s de un pr\u00e9stamo de bajo costo. No se hab\u00eda iniciado antes por problemas financieros ya que la Provincia no ten\u00eda los recursos de contraparte, porque si bien financiaba la entidad financiera, el Gobierno deb\u00eda hacerse cargo, con recursos propios, de la contraparte que le correspond\u00eda en esta primera etapa\u00bb.<\/p>\n<p>Por su parte Vaqui\u00e9 detall\u00f3 que \u00abcuando se firm\u00f3 el contrato, el 45% del financiamiento era otorgado por la Provincia y el 55% restante por el BID. Actualmente estamos en una etapa de discusi\u00f3n con el Banco Interamericano de Desarrollo para que la contraparte que pone el Gobierno sea m\u00e1s chica\u00bb. Coment\u00f3 que la semana que viene vendr\u00e1 una misi\u00f3n del organismo internacional para llegar a un acuerdo en el porcentaje.<\/p>\n<p><strong>La obra<\/strong><br \/>\nEl subsecretario de Obras P\u00fablicas, Daniel Chicahuala, cont\u00f3 que adem\u00e1s de las obras \u00abma\u00f1ana tambi\u00e9n comienza el proceso de evaluaci\u00f3n t\u00e9cnica, para encontrar una alternativa de construcci\u00f3n que va a permitir que la Provincia ahorre fondos, abaratando costos y al mismo tiempo logrando reducir los tiempos de ejecuci\u00f3n\u00bb.<\/p>\n<p>En este sentido indic\u00f3: \u00abSe trata de una variante en la construcci\u00f3n que permitir\u00e1 reemplazar el recubrimiento del t\u00fanel de hormig\u00f3n armado por el de hormig\u00f3n proyectado. Son t\u00e9cnicas aprobadas de \u00faltima generaci\u00f3n\u00bb.<\/p>\n<p>La obra total incluir\u00e1 aproximadamente 2.200 metros de conexi\u00f3n vial, incluyendo m\u00e1s de 420 metros lineales de t\u00fanel. Permitir\u00e1 el tr\u00e1nsito fluido entre las localidades de Cacheuta y Potrerillos y habilitar\u00e1 finalmente el circuito tur\u00edstico de la RP N\u00b0 82, desde Sierra de Encalada, en Las Heras, hasta Luj\u00e1n de Cuyo.<\/p>\n<p>El nuevo t\u00fanel se ubicar\u00e1 m\u00e1s al sur que el proyectado en un primer momento, incluir\u00e1 un sector de caracoles en la subida adem\u00e1s de un conjunto de obras complementarias.<\/p>\n<p><strong>Or\u00edgenes del proyecto<\/strong><br \/>\nLa Ruta Provincial N\u00ba82 nace en la localidad de Blanco Encalada en el departamento Luj\u00e1n de Cuyo y vincula, hacia el norte, a trav\u00e9s de la Ruta Provincial N\u00ba 81, la Ciudad de Mendoza, y hacia el sur, las localidades de Cacheuta y Potrerillos.<\/p>\n<p>En Potrerillos se ha desarrollado el proyecto de Aprovechamiento Integral del R\u00edo Mendoza a trav\u00e9s de la construcci\u00f3n del dique que lleva ese nombre, lago artificial con una superficie de 1.300 hect\u00e1reas y una capacidad de 420 hm3. Con esta construcci\u00f3n se interrumpi\u00f3 el trazado de la Ruta Provincial N\u00ba82 y parte de ella qued\u00f3 bajo el agua, lo que provoc\u00f3 la desvinculaci\u00f3n entre Cacheuta y Potrerillos.<\/p>\n<h6>Fuente: Uno, Mendoza<\/h6>\n","protected":false},"excerpt":{"rendered":"<p>Lo confirm\u00f3 Alfredo Cornejo tras anunciar el comienzo del t\u00fanel que unir\u00e1 ambas localidades, incomunicadas desde hace m\u00e1s de 10 a\u00f1os.<\/p>\n","protected":false},"author":2,"featured_media":46852,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[31],"class_list":["post-46851","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-informe-municipal","tag-mendoza"],"_links":{"self":[{"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/posts\/46851","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/comments?post=46851"}],"version-history":[{"count":0,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/posts\/46851\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/media\/46852"}],"wp:attachment":[{"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/media?parent=46851"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/categories?post=46851"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/tags?post=46851"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}