{"id":46911,"date":"2016-04-21T05:06:16","date_gmt":"2016-04-21T08:06:16","guid":{"rendered":"http:\/\/argentinamunicipal.com.ar\/argentina\/?p=46911"},"modified":"2016-04-21T08:09:09","modified_gmt":"2016-04-21T11:09:09","slug":"se-agudizo-la-crisis-municipal-salvador-mazza-cortaron-puente-internacional","status":"publish","type":"post","link":"http:\/\/argentinamunicipal.com.ar\/argentina\/se-agudizo-la-crisis-municipal-salvador-mazza-cortaron-puente-internacional\/","title":{"rendered":"Se agudiz\u00f3 la crisis municipal en Salvador Mazza y cortaron el puente internacional"},"content":{"rendered":"<p>A las protestas de los empleados municipales y los taxistas se sumaron las cooperativas de trabajo, que cortaron el puente que comunica con Pocitos, exigen obras para poder facturar y percibir ingresos.<br \/>\nEl enfrentamiento entre el intendente municipal Rub\u00e9n M\u00e9ndez y los miembros de su gabinete contra quienes llevan adelante la toma de municipio y el bloqueo del ingreso a la fronteriza localidad de Salvador Mazza es total.<br \/>\nAyer, miembros de las conocidas como ONG, en realidad cooperativas de trabajo que facturan por changas que hacen a la comuna, cortaron el puente internacional exigiendo obras para poder percibir algunos ingresos.<br \/>\nLas acusaciones mutuas en los medios de comunicaci\u00f3n local entre los sectores enfrentados han llegado a tal grado de virulencia que hasta el destituido exintendente Carlos Villalba se anim\u00f3 a opinar en contra de la actual gesti\u00f3n.<br \/>\nComo se recordar\u00e1, Villalba fue suspendido por el Gobierno de la Provincia, que le intervino la gesti\u00f3n luego de haber sido encontrado en un prost\u00edbulo en la capital de la provincia y de que se le iniciaran acciones penales por supuesta trata de personas.<br \/>\nEsa fue la \u00faltima actuaci\u00f3n de Villalba durante su gesti\u00f3n al frente de la comuna, que ya ven\u00eda de varios a\u00f1os de total anarqu\u00eda y desmanejo de la administraci\u00f3n a su cargo y de semanas enteras de ollas populares por parte de los empleados municipales exigiendo el pago de haberes. A\u00fan as\u00ed, el exintendente se animo a dar c\u00e1tedra por una radio local sobre la manera de solucionar el problema, que incluye a familias que semanas atr\u00e1s usurparon un predio de propiedad del hijo del intendente.<br \/>\n\u00abDurante mi gesti\u00f3n compramos el predio que se hab\u00eda usurpado en ese momento y le dimos los terrenos a las familias sin que tengan que pagar un peso\u00bb, declar\u00f3 Villalba.<br \/>\nPara los miembros del Ejecutivo, otro de los dirigentes pol\u00edticos de Salvador Mazza que fogonean la protesta es el exintendente Francisco Ib\u00e1\u00f1ez.<br \/>\n\u00abEl hermano es el que les lleva la comida y descaradamente carga la le\u00f1a para que mantengan el fuego de la olla popular\u00bb, aseguraron los seguidores de M\u00e9ndez a las radios locales, a la vez que se mostraron disconformes con la actitud del fiscal penal de Salvador Mazza, Armando Caz\u00f3n, por no ordenar antes el desalojo de la Municipalidad y dejar crecer tanto la protesta sin intervenir.<br \/>\n\u00abNo ordena nada porque es hermano de Cristina Caz\u00f3n, la vicepresidenta segunda del Concejo Deliberante que est\u00e1 enfrentada con M\u00e9ndez y desea llegar a la jefatura comunal\u00bb, interpretaron los vecinos.<\/p>\n<p>\u00abCon hijos argentinos\u00bb<br \/>\nDentro de los manifestantes que permanecen bloqueando el acceso al edificio municipal se encuentran familias que semanas atr\u00e1s usurparon un predio de propiedad de uno de los hijos del intendente Rub\u00e9n M\u00e9ndez.<br \/>\nSoledad Romero, una de las mujeres usurpadoras, record\u00f3: \u00abAntes de tomar esta medida fuimos a Tierra y H\u00e1bitat y ah\u00ed nos enteramos de que la compra del terreno se hizo por $50.000 el mismo d\u00eda 10 de diciembre cuando M\u00e9ndez asum\u00eda su mandato\u00bb.<br \/>\n\u00abA nosotros no nos cierra que un terreno de 90&#215;100 sea tan barato, pero lo que nos conf\u00edan los empleados municipales es que en realidad M\u00e9ndez lo compr\u00f3 a ese precio porque el anterior propietario ten\u00eda una deuda grande con la Municipalidad y el intendente se la hizo desaparecer\u00bb, explic\u00f3 molesta.<br \/>\nSoledad reconoci\u00f3 que el argumento de M\u00e9ndez para no aceptar la usurpaci\u00f3n ni de ese ni de ning\u00fan otro predio obedece a que muchos de los usurpadores ser\u00edan ciudadanos bolivianos que luego lucran con los terrenos adjudicados vendi\u00e9ndolos a quienes realmente los necesitan.<br \/>\n\u00abNo es mi caso. Porque soy ciudadana argentina, nac\u00ed y me cri\u00e9 en Salvador Mazza; hay otras mujeres que son bolivianas pero tienen hijos argentinos, por tanto todas tenemos derecho a tener un lugar donde vivir. Pero el intendente no da la cara, no quiere hablar con nosotros y lo \u00fanico que pide es que la infanter\u00eda nos saque a los golpes. Pero eso no va a pasar, porque nos vamos a quedar en este terreno\u00bb, manifest\u00f3.<br \/>\nLo que dicen los remiseros<br \/>\nJuan Zacur lidera un grupo de remiseros que protestan por el aumento de la unidad tarifaria municipal que pas\u00f3 de $1,20 a $2,20 y que no se actualizaba hac\u00eda a\u00f1os. Pero a esa protesta nunca se pleg\u00f3 el Centro de Taxistas 13 de Abril de Salvador Mazza, el m\u00e1s antiguo de la localidad y que nuclea a m\u00e1s de 150 trabajadores del volante.<br \/>\n\u00abNosotros protestamos no solo porque nos aumentaron los impuestos sino porque ese aumento no se ve en obras. Las calles est\u00e1n hechas un desastre, tenemos hechos de inseguridad todos los d\u00edas y no vamos a pagar m\u00e1s impuestos para que ning\u00fan vivo se lleve nuestra plata\u00bb, argument\u00f3 el remisero.<br \/>\nLuego explic\u00f3 que \u00ablos de 13 de Abril no se plegan a la protesta porque a ellos, por ser los m\u00e1s antiguos, la Municipalidad le hace descuentos y les da otros beneficios\u00bb.<br \/>\nLos remiseros levantaron finalmente su protesta, de forma provisoria, luego de una reuni\u00f3n que mantuvieron con el jefe comunal en dependencias de la comisar\u00eda local, durante la cual M\u00e9ndez les prometi\u00f3 bajarles el impuesto en un 50%.<br \/>\nY aclararon que el acuerdo es provisorio porque deb\u00edan firmar un acta, pero como la comuna est\u00e1 cerrada no se pudo.<\/p>\n<h6>Fuente: El Tribuno, Salta<\/h6>\n","protected":false},"excerpt":{"rendered":"<p>A las protestas de los empleados municipales y los taxistas se sumaron las cooperativas de trabajo, que cortaron el puente que comunica con Pocitos, exigen obras para poder facturar y percibir ingresos.<\/p>\n","protected":false},"author":2,"featured_media":46912,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[9],"class_list":["post-46911","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-informe-sindical","tag-salta"],"_links":{"self":[{"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/posts\/46911","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/comments?post=46911"}],"version-history":[{"count":0,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/posts\/46911\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/media\/46912"}],"wp:attachment":[{"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/media?parent=46911"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/categories?post=46911"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/tags?post=46911"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}