{"id":46958,"date":"2016-04-22T06:55:47","date_gmt":"2016-04-22T09:55:47","guid":{"rendered":"http:\/\/argentinamunicipal.com.ar\/argentina\/?p=46958"},"modified":"2016-04-22T06:55:47","modified_gmt":"2016-04-22T09:55:47","slug":"se-habilitaron-oficinas-rosario-la-direccion-general-empleo","status":"publish","type":"post","link":"http:\/\/argentinamunicipal.com.ar\/argentina\/se-habilitaron-oficinas-rosario-la-direccion-general-empleo\/","title":{"rendered":"Se habilitaron oficinas en Rosario de la Direcci\u00f3n General de Empleo"},"content":{"rendered":"<p>Funcionan de lunes a viernes de 8 a 14, en cada uno de los seis minimunicipios. Ofrecen los servicios de orientaci\u00f3n laboral, capacitaci\u00f3n, programa de empleo independiente y discapacidad.<\/p>\n<p>En la ma\u00f1ana del lunes 18 de abril, el municipio present\u00f3 las nuevas oficinas de empleo que funcionan en los centros municipales de Distrito. El acto se llev\u00f3 a cabo en el minimunicipio Rosa Ziperovich, ubicado en avenida Uriburu 637, y fue encabezado por el secretario General de la Municipalidad, Pablo Javkin, y el titular de la Secretar\u00eda de Producci\u00f3n y Desarrollo Local, Ignacio Del Vecchio, entre otros.<\/p>\n<p>Durante la actividad, Javkin se\u00f1al\u00f3 que se trata de una propuesta conjunta entre la Oficina General de Empleo de la Secretar\u00eda de Producci\u00f3n y Desarrollo Local y los seis centros distritales que dependen de la Secretar\u00eda General. \u00abNuestro objetivo es que la descentralizaci\u00f3n vuelva a cobrar impulso y los Distritos se conviertan en n\u00facleos de vida c\u00edvica, donde el ciudadano no vaya s\u00f3lo a hacer un tr\u00e1mite, sino que tambi\u00e9n encuentren este tipo de herramientas\u00bb, sostuvo el secretario General.<\/p>\n<p>\u00abHoy hay muchas ofertas de cultura, de las \u00e1reas sociales. Ya est\u00e1 funcionando la oficina del consumidor, ahora lo har\u00e1 la oficina de empleo\u00bb, destac\u00f3 el funcionario, quien anunci\u00f3: \u00abVamos a incorporar algo que dijimos: si bien muchos Distritos ya cuentan con centros de Denuncia y Fiscal\u00edas, estamos trabajando con el Ministerio de Seguridad para tener mayor cercan\u00eda entre el Distrito y las fuerzas de seguridad\u00bb.<\/p>\n<p>El funcionario se\u00f1al\u00f3 adem\u00e1s las pol\u00edticas p\u00fablicas que se realizan a diario \u00abpara, a trav\u00e9s de la descentralizaci\u00f3n, estar cerca de los vecinos\u00bb. Y agreg\u00f3: \u00abLo hacemos con los operativos integrales, con el asesoramiento en materia de empleo, derechos del consumidor y por supuesto tambi\u00e9n lo vamos a hacer en materia de seguridad\u00bb.<\/p>\n<p>\u00abQueremos que los distritos cumplan un rol muy importante en la planificaci\u00f3n de la ciudad porque entendemos que esa es la manera de estar m\u00e1s cerca y de cuidar m\u00e1s a los rosarinos, que es la definici\u00f3n de la intendenta\u00bb, sostuvo Javkin.<\/p>\n<p>El \u00e1rea dependiente de la Secretar\u00eda de Producci\u00f3n y Desarrollo Local tiene por funci\u00f3n asesorar, capacitar, acompa\u00f1ar y brindar distintas herramientas a las personas que est\u00e1n en la b\u00fasqueda de un trabajo o que quieren mejorar su situaci\u00f3n laboral, para que a la hora de postularse para un puesto tengan m\u00e1s oportunidades de ser contratadas. En este sentido, el secretario de Producci\u00f3n y Desarrollo Local inform\u00f3 que la Oficina de Empleo atiende de lunes a viernes de 8 a 14.<\/p>\n<p>\u201cEste es el resultado de lo que nos ha solicitado la intendenta, trabajar con cercan\u00eda, apertura y di\u00e1logo que permitan facilitar la capacitaci\u00f3n y la inserci\u00f3n laboral. Por ello, la descentralizaci\u00f3n de la oficina de empleo le permitir\u00e1 a cada vecino dirigirse al Centro Municipal de Distrito m\u00e1s cercano para realizar todas las gestiones y tr\u00e1mites para adquirir nuevas herramientas que den mayores posibilidades de conseguir trabajo\u201d, sostuvo Del Vecchio.<\/p>\n<p>A su turno, Marcial Soraz\u00e1bal, director de Empleo, present\u00f3 los diferentes servicios que brindan las oficinas, que son: orientaci\u00f3n laboral, capacitaci\u00f3n, programa de empleo independiente y discapacidad, opciones que ya ten\u00eda la direcci\u00f3n de Empleo, y que ahora est\u00e1n m\u00e1s cerca del ciudadano ya que las consultas se pueden hacer en forma descentralizada.<\/p>\n<p>\u201cAquellas personas que est\u00e9n buscando empleo podr\u00e1n acercarse al \u00e1rea de orientaci\u00f3n laboral para elaborar su CV y cargarlo en la base de datos para futuras b\u00fasquedas laborales. Adem\u00e1s de anotarse en los diferentes cursos de capacitaci\u00f3n, en todos los distritos habr\u00e1 un \u00e1rea especial para que las personas con discapacidad puedan registrar su perfil, realizar los talleres de orientaci\u00f3n y participar de b\u00fasquedas laborales\u00bb, finaliz\u00f3 diciendo.<\/p>\n<h6>Fuente: Sin Mordaza<\/h6>\n","protected":false},"excerpt":{"rendered":"<p>Funcionan de lunes a viernes de 8 a 14, en cada uno de los seis minimunicipios. Ofrecen los servicios de orientaci\u00f3n laboral, capacitaci\u00f3n, programa de empleo independiente y discapacidad.<\/p>\n","protected":false},"author":2,"featured_media":46959,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[10],"class_list":["post-46958","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-informe-municipal","tag-santa-fe"],"_links":{"self":[{"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/posts\/46958","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/comments?post=46958"}],"version-history":[{"count":0,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/posts\/46958\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/media\/46959"}],"wp:attachment":[{"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/media?parent=46958"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/categories?post=46958"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/tags?post=46958"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}