{"id":46988,"date":"2016-04-22T07:48:52","date_gmt":"2016-04-22T10:48:52","guid":{"rendered":"http:\/\/argentinamunicipal.com.ar\/argentina\/?p=46988"},"modified":"2016-04-22T07:48:52","modified_gmt":"2016-04-22T10:48:52","slug":"revelan-santa-rosa-plazo-fijo-18-millones","status":"publish","type":"post","link":"http:\/\/argentinamunicipal.com.ar\/argentina\/revelan-santa-rosa-plazo-fijo-18-millones\/","title":{"rendered":"Revelan que Santa Rosa tiene un plazo fijo de 18 millones"},"content":{"rendered":"<p><span style=\"line-height: 1.5\">El gobernador Carlos Verna confirm\u00f3 que la Casa de Gobierno ya no asistir\u00e1 financieramente al municipio de Santa Rosa y afirm\u00f3 que \u201cno estamos castigando a nadie ni hay discrecionalidad\u201d. Adem\u00e1s, explic\u00f3 que la comuna capitalina puede usar fondos por 18 millones de pesos que tiene disponibles en plazo fijo y las regal\u00edas petroleras que ser\u00e1n de libre disponibilidad.<\/span><\/p>\n<p>\u201cVen\u00edamos ayudando a los municipios de 25 de Mayo, General Pico y Santa Rosa para pagar sueldos, a todos les pedimos que nos muestren la evoluci\u00f3n de la diferencia entre ingresos y egresos; las dos primeras exhibieron una evoluci\u00f3n pero Santa Rosa no tanto. Quiero desmentir lo que dijeron que antes se le daba plata y ahora no, y doy un ejemplo, en los dos \u00faltimos a\u00f1os, d\u00edganle (al concejal) Cuelle, la Provincia le dio a Santa Rosa 20 millones y yo en cuatro meses le di 46 millones, de los que descont\u00e9 10 del aguinaldo\u201d, dijo Verna.<\/p>\n<p><span style=\"line-height: 1.5\">-\u00bfEsto no profundiza la crisis de Santa Rosa?<\/span><\/p>\n<p>-No creo. Nosotros presentamos una ley de libre disponibilidad de regal\u00edas con las que tendr\u00e1 un ingreso importante y adem\u00e1s, si bien no est\u00e1 en el proyecto que enviamos a la Legislatura, pedimos a los diputados que incorporen un art\u00edculo para que se puedan gastar los fondos retenidos, que no se asignaron y eran para infraestructura, donde Santa Rosa tiene 18 millones en un plazo fijo, no hay castigo.<\/p>\n<p>-\u00bfAltolaguirre dijo que se puede llegar a cortar el agua del Centro C\u00edvico si tiene problema con los empleados?<br \/>\n-Yo no tengo problema con los empleados ni con el municipio, tengo dificultades financieras, o no se enteraron que tuvimos que ir a discutir a Naci\u00f3n por 400 millones y que me anticiparon los fondos del d\u00e9ficit financiero que vamos a tener en las cajas para poder conseguir sueldos. Estuvimos contemplando dejar de pagar los salarios de los funcionarios y abonar solo a los empleados.<\/p>\n<p>-\u00bfLa deuda previsional puede hacer voltear a la Provincia?<br \/>\n-S\u00ed. La Provincia tiene tres cajas financieras importantes, el Banco, la caja provincial y el Instituto de Seguridad Social, el sistema jubilatorio, la p\u00e9rdida o d\u00e9ficit de la caja de este a\u00f1o supera los 900 millones y eso lo tenemos que aportar con impuestos y coparticipaci\u00f3n.<\/p>\n<p><strong>Tierno.<\/strong><br \/>\nEl mandatario, adem\u00e1s, le cerr\u00f3 la puerta a la posibilidad de sentarse a negociar en el corto plazo con los gremios estatales en el marco de la paritaria y remarc\u00f3: \u201cLa paritaria est\u00e1 firmada y se reabre a fines de julio o principios de agosto\u201d.<\/p>\n<p>Sobre las denuncias contra el ministro de Seguridad, Juan Carlos Tierno, Verna indic\u00f3: \u201cLa denuncia que recibi\u00f3 (por cobro indebido de vi\u00e1ticos), fue desmentida en una solicitada. Otra fue archivada por la Justicia y en el caso de Sauze, expliqu\u00e9 varias veces que los que estaban detr\u00e1s de los habitantes de Sauze eran el intendente de Rivadavia y los integrantes de la Sociedad Rural, que defend\u00edan sus campos que iban a quedar inundados. No veo un reclamo popular, lo que veo es intereses concretos de productores, que si ustedes quieren, les doy los nombres, porque yo nac\u00ed en esa zona\u201d.<\/p>\n<h6>Fuente: La Arena<\/h6>\n","protected":false},"excerpt":{"rendered":"<p>El gobernador Carlos Verna confirm\u00f3 que la Casa de Gobierno ya no asistir\u00e1 financieramente al municipio de Santa Rosa y afirm\u00f3 que \u201cno estamos castigando a nadie ni hay discrecionalidad\u201d<\/p>\n","protected":false},"author":2,"featured_media":46989,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5],"tags":[42],"class_list":["post-46988","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-informe-economico","tag-la-pampa"],"_links":{"self":[{"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/posts\/46988","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/comments?post=46988"}],"version-history":[{"count":0,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/posts\/46988\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/media\/46989"}],"wp:attachment":[{"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/media?parent=46988"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/categories?post=46988"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/tags?post=46988"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}